{"id":25922,"date":"2023-02-08T19:28:39","date_gmt":"2023-02-08T22:28:39","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=25922"},"modified":"2023-02-15T08:39:09","modified_gmt":"2023-02-15T11:39:09","slug":"loteria-mineira-edital-jogos","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/loteria-mineira-edital-jogos\/","title":{"rendered":"Loteria Mineira publica edital de licita\u00e7\u00e3o para explora\u00e7\u00e3o dos jogos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nesta ter\u00e7a-feira, a <strong>Loteria Mineira<\/strong> publicou, no Di\u00e1rio Oficial do Estado, o edital de licita\u00e7\u00e3o para concess\u00e3o da explora\u00e7\u00e3o e opera\u00e7\u00e3o de jogos tradicionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Loteria do Estado de Minas Gerais<\/strong> (LEMG), entidade vinculada \u00e0 Secretaria de Finan\u00e7as do Estado (SEF), anunciou o in\u00edcio do processo que busca a assinatura de um contrato que gere ao estado R$ 500 milh\u00f5es e que arrecade ao operador R$ 5 bilh\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A modalidade do concurso \u00e9 a de <strong>Licita\u00e7\u00e3o P\u00fablica Internacional<\/strong> e dar\u00e1 o direito de explorar a ind\u00fastria durante 20 anos no estado, abrangendo os jogos lot\u00e9ricos tradicionais, como loteria convencional e as raspadinhas (loteria instant\u00e2nea). Com a publica\u00e7\u00e3o do edital, iniciou o prazo de 45 dias para a apresenta\u00e7\u00e3o de propostas e abertura dos respectivos envelopes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O vencedor selecionado dever\u00e1 cumprir com um cronograma de implementa\u00e7\u00e3o para lan\u00e7ar o novo esquema de apostas. Ainda, ser\u00e1 respons\u00e1vel pelos servi\u00e7os de planejamento estrat\u00e9gico, pela cria\u00e7\u00e3o de produtos, pela impress\u00e3o de materiais, pela implanta\u00e7\u00e3o e opera\u00e7\u00e3o de produtos de loterias, pelo marketing, pelo armazenamento, pela cria\u00e7\u00e3o e opera\u00e7\u00e3o da rede de distribui\u00e7\u00e3o e pela comercializa\u00e7\u00e3o e pagamento de pr\u00eamios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEst\u00e1vamos muito atentos aos desafios enfrentados por outros estados e nos aprofundamos no assunto. Recebemos contribui\u00e7\u00f5es e realizamos audi\u00eancias. Todas essas a\u00e7\u00f5es tiveram como objetivo compilar todos os documentos para mitigar quaisquer d\u00favidas\u201d, explicou o secret\u00e1rio de Finan\u00e7as do Estado, <strong>Gustavo Barbosa<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEm todas as etapas (as de audi\u00eancia p\u00fablica), os representantes das empresas interessadas no processo tiveram a oportunidade de apresentar contribui\u00e7\u00f5es e sugest\u00f5es, as quais foram avaliadas pelo Comit\u00ea Especial de Licita\u00e7\u00e3o, a fim de aprimorar o editar\u201d, acrescentou o diretor geral da Loteria Mineira, <strong>Ron\u00e1n Moreira<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta ter\u00e7a-feira, a Loteria Mineira publicou, no Di\u00e1rio Oficial do Estado, o edital de licita\u00e7\u00e3o para concess\u00e3o da explora\u00e7\u00e3o e opera\u00e7\u00e3o de jogos tradicionais. A Loteria do Estado de Minas [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":25923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,3668],"tags":[3644,89,3673,3674,1070],"class_list":["post-25922","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-loterias","tag-apostas-esportivas","tag-brasil","tag-edital","tag-licitacao","tag-loteria-mineira"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/25922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=25922"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/25922\/revisions"}],"predecessor-version":[{"id":25925,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/25922\/revisions\/25925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/25923"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=25922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=25922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=25922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}