{"id":27638,"date":"2023-08-11T10:30:00","date_gmt":"2023-08-11T13:30:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=27638"},"modified":"2025-02-12T13:52:54","modified_gmt":"2025-02-12T16:52:54","slug":"fraude-em-apostas-investigacao-bruno-lopes","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/fraude-em-apostas-investigacao-bruno-lopes\/","title":{"rendered":"Fraude em apostas: alvar\u00e1 de soltura de Bruno Lopez, um dos chefes do esquema, \u00e9 emitido pelo TJ-GO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na quarta-feira, 9, o <strong>Tribunal de Justi\u00e7a do Estado de Goi\u00e1s<\/strong> <strong>(TJ-GO)<\/strong> emitiu o alvar\u00e1 de soltura de<strong> Bruno Lopez de Moura<\/strong>, apontado como um dos chefes do esquema de fraude em apostas esportivas em jogos do Campeonato Brasileiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a investiga\u00e7\u00e3o, Lopez dever\u00e1 cumprir as medidas definidas pela Justi\u00e7a para n\u00e3o voltar \u00e0 pris\u00e3o e perder o benef\u00edcio de responder em liberdade.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lopez dever\u00e1 comparecer a todos os atos do processo que for intimado, n\u00e3o poder\u00e1 mudar de endere\u00e7o, n\u00e3o poder\u00e1 se ausentar por mais de oito dias de casa sem comunicar com anteced\u00eancia os agentes nem sair do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O empres\u00e1rio e ex-jogador de futebol tamb\u00e9m est\u00e1 proibido de atuar em apostas esportivas e de ter contato com os outros 16 acusados no processo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Entenda o caso<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Em fevereiro deste ano, o <strong>Minist\u00e9rio P\u00fablico de Goi\u00e1s<\/strong> <strong>(MP-GO)<\/strong> come\u00e7ou a investigar um esquema de fraude em apostas esportivas em pelo menos tr\u00eas jogos da S\u00e9rie B do Brasileir\u00e3o no final do ano passado. O presidente do Vila Nova, <strong>Hugo Jorge Bravo<\/strong>, foi quem fez a den\u00fancia que deu in\u00edcio \u00e0s opera\u00e7\u00f5es <a href=\"https:\/\/sbcnoticias.com\/br\/fraude-em-apostas-esportivas-mp-goias-romario\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Penalidade M\u00e1xima I e II<\/em><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 \u00e9poca da den\u00fancia dos fatos, oito jogadores de diferentes clubes foram indiciados: <strong>Rom\u00e1rio<\/strong> (ex-Vila Nova), <strong>Joseph<\/strong> (Tombense), <strong>Mateusinho<\/strong> (ex-Sampaio Corr\u00eaa, atualmente no Cuiab\u00e1), <strong>Gabriel Domingos<\/strong> (ex-Vila Nova), <strong>Allan God\u00f3i<\/strong> (Sampaio Corr\u00eaa), <strong>Andr\u00e9 Queixo<\/strong> (ex-Sampaio Corr\u00eaa, atualmente no Ituano), <strong>Ygor Catatau<\/strong> (ex-Sampaio Corr\u00eaa, atualmente em Sepahan, no Ir\u00e3) e <strong>Paulo S\u00e9rgio<\/strong> (ex-Sampaio Corr\u00eaa, atualmente no Oper\u00e1rio-PR).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento, o <strong>Superior Tribunal de Justi\u00e7a Desportiva (STJD)<\/strong> j\u00e1 puniu oito jogadores e outros 12, incluindo <strong>Nino Para\u00edba<\/strong> (Paysandu),<strong> Diego <\/strong>(Desportivo Alian\u00e7a\/AL),<strong> Alef Manga <\/strong>(Coritiba FC) e<strong> Vitor Mendes<\/strong> (CA Mineiro). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os atletas, que estariam supostamente envolvidos no caso de manipula\u00e7\u00e3o esportiva, foram a julgamento nesta quarta-feira. As puni\u00e7\u00f5es levam a multas de R$ 100 a R$ 100 mil, al\u00e9m da possibilidade de suspens\u00e3o das atividades esportivas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na quarta-feira, 9, o Tribunal de Justi\u00e7a do Estado de Goi\u00e1s (TJ-GO) emitiu o alvar\u00e1 de soltura de Bruno Lopez de Moura, apontado como um dos chefes do esquema de [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":27640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[4543,3723,3685,4037,4025,3948,4544],"class_list":["post-27638","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-bruno-lopes","tag-fraude-em-apostas","tag-fraude-em-apostas-esportivas","tag-investigacao","tag-mp-go","tag-operacao-penalidade-maxima","tag-tj-go"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=27638"}],"version-history":[{"count":5,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27638\/revisions"}],"predecessor-version":[{"id":37996,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27638\/revisions\/37996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/27640"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=27638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=27638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=27638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}