{"id":27707,"date":"2023-08-16T09:00:40","date_gmt":"2023-08-16T12:00:40","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=27707"},"modified":"2023-08-16T13:09:44","modified_gmt":"2023-08-16T16:09:44","slug":"copa-do-mundo-feminina-casa-de-apostas","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/copa-do-mundo-feminina-casa-de-apostas\/","title":{"rendered":"Copa do Mundo Feminina est\u00e1 entre os eventos mais apostados nas casas de apostas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>Copa do Mundo Feminina da FIFA <\/strong>atingiu o p\u00f3dio nas casas de apostas on-line. Em um levantamento realizado pela <strong>Novibet<\/strong>, o Mundial Feminino ocupa o terceiro lugar da lista dos cinco campeonatos mais apostados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/sbcnoticias.com\/br\/betfair-doacao-palmeiras-cruzeiro\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Brasileir\u00e3o<\/strong><\/a><strong> <\/strong>\u00e9 o primeiro colocado, seguido pelos amistosos entre os grandes times da pr\u00e9-temporada europeia. Nas quarta e quinta posi\u00e7\u00f5es, encontram-se o <a href=\"https:\/\/sbcnoticias.com\/br\/betano-adquire-naming-rights-da-serie-b-do-brasileirao\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Campeonato Brasileiro da S\u00e9rie B<\/strong><\/a> e o <strong>Campeonato Argentino<\/strong>, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a plataforma informou que o Brasil foi a sele\u00e7\u00e3o que mais recebeu apostas entre julho e a primeira quinzena de agosto. Estados Unidos, Fran\u00e7a, Canad\u00e1 e Argentina completam a lista das cinco primeiras sele\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na televis\u00e3o, a Copa do Mundo Feminina bateu recordes de audi\u00eancia e superou dados de torcedores nos est\u00e1dios da Austr\u00e1lia e da Nova Zel\u00e2ndia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em julho, o campeonato j\u00e1 havia <a href=\"https:\/\/sbcnoticias.com\/br\/copa-do-mundo-feminina-patrocinios\/\" target=\"_blank\" rel=\"noreferrer noopener\">esgotado os pacotes de patroc\u00ednio<\/a>. O CBO da FIFA, <strong>Romy Gai<\/strong>, na \u00e9poca, comentou: \u201cA Copa do Mundo Feminina da FIFA 2023 se tornar\u00e1 no maior evento esportivo feminino independente da hist\u00f3ria. \u00c9 incr\u00edvel ver nossos fant\u00e1sticos parceiros e apoiadores se envolverem com o potencial deste evento \u00fanico\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Copa do Mundo Feminina da FIFA atingiu o p\u00f3dio nas casas de apostas on-line. Em um levantamento realizado pela Novibet, o Mundial Feminino ocupa o terceiro lugar da lista [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":27708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,3667],"tags":[3644,1519,1527,4236,636,3748,3621],"class_list":["post-27707","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-internacional-2","tag-apostas-esportivas","tag-brasileirao","tag-casa-de-apostas","tag-copa-do-mundo-feminina","tag-fifa","tag-futebol-feminino","tag-novibet"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=27707"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27707\/revisions"}],"predecessor-version":[{"id":27709,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27707\/revisions\/27709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/27708"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=27707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=27707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=27707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}