{"id":27812,"date":"2023-08-23T15:34:13","date_gmt":"2023-08-23T18:34:13","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=27812"},"modified":"2023-08-23T17:05:10","modified_gmt":"2023-08-23T20:05:10","slug":"copa-do-mundo-feminina-fifa-sem-manipulacao","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/copa-do-mundo-feminina-fifa-sem-manipulacao\/","title":{"rendered":"Nenhuma aposta suspeita foi detectada na Copa do Mundo Feminina da FIFA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Grupo de Trabalho de Integridade da <strong>Federa\u00e7\u00e3o Internacional de Futebol (FIFA)<\/strong> revelou que concluiu com \u00eaxito sua avalia\u00e7\u00e3o sobre as apostas esportivas realizadas globalmente durante a<strong> Copa do Mundo Feminina <\/strong>2023, que colocou a Sele\u00e7\u00e3o da Espanha como campe\u00e3 pela primeira vez na hist\u00f3ria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O \u00f3rg\u00e3o respons\u00e1vel por monitorar a competi\u00e7\u00e3o e todas as atividades de apostas relacionadas informou que n\u00e3o houve sinais de alerta relacionados a comportamentos suspeitos, como tentativas de manipula\u00e7\u00e3o de jogos ou outras amea\u00e7as semelhantes, nos 64 jogos disputados no \u00faltimo m\u00eas na Austr\u00e1lia e na Nova Zel\u00e2ndia.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o grupo de controle de integridade das apostas utilizou uma rede de representantes designados de v\u00e1rias unidades internacionais de combate ao crime, como <strong>FBI<\/strong>, <strong>INTERPOL<\/strong>, <strong>Sport Integrity Australia<\/strong> e a <strong>Pol\u00edcia da Nova Zel\u00e2ndia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A FIFA detalhou que utilizou um \u201cfoco centralizado\u201d para analisar todos os dados coletados do seguimento de apostas, incluindo a vigil\u00e2ncia fiscal do lugar, para tirar suas conclus\u00f5es finais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO esfor\u00e7o colaborativo entre a FIFA e as principais entidades internacionais interessadas no setor de integridade esportiva garantiu uma resposta experiente, coordenada e oportuna com cada um dos \u00f3rg\u00e3os participantes, que contribu\u00edram com sua experi\u00eancia espec\u00edfica (investiga\u00e7\u00e3o e\/ou t\u00e9cnica) durante todo o torneio\u201d, disse a FIFA em seu relat\u00f3rio de monitoramento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grupo de trabalho do \u00f3rg\u00e3o internacional de futebol foi criado antes da final da Copa do Mundo Feminina da FIFA de 2019 e, desde ent\u00e3o, junto a v\u00e1rias partes interessadas na integridade, dedica-se a tomar medidas contr\u00e1rias \u00e0s atividades ilegais de jogo relacionadas ao evento.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Depois do \u00faltimo domingo (20), a FIFA comemorou positivamente a conclus\u00e3o do campeonato. A Sele\u00e7\u00e3o Espanhola, que enfrentou a Inglaterra &#8211; com um resultado de 1 a 0 -, tornou-se campe\u00e3 mundial pela primeira vez na hist\u00f3ria. O terceiro lugar foi ocupado pela Sele\u00e7\u00e3o da Su\u00e9cia, que venceu a Austr\u00e1lia por 2 a 0 no s\u00e1bado, dia 19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Copa do Mundo Feminina tem gerado grandes impactos no mundo esportivo devido \u00e0 crescente chegada nas maiores audi\u00eancias globais. A \u00faltima edi\u00e7\u00e3o atingiu recordes, com mais de 1 milh\u00e3o de pessoas nos est\u00e1dios, o que significa um aumento de 29% em rela\u00e7\u00e3o \u00e0 edi\u00e7\u00e3o na Fran\u00e7a, em 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lee Anderson<\/strong>, da <strong>bwin<\/strong>, falou ao <a href=\"https:\/\/insidersport.com\/2023\/08\/14\/bwin-betting-engagement-set-to-be-boosted-by-womens-world-cup\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Insider Sport<\/em><\/a>, site irm\u00e3o do <em>SBC Not\u00edcias Brasil<\/em>, sobre o engajamento que o torneio geraria nas plataformas internacionais de apostas esportiva: \u201cO futebol feminino tem algumas jogadoras muito talentosas e o interesse em apostas neste esporte aumento esse comprometimento e d\u00e1 mais vida ao esporte\u201d, comentou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Grupo de Trabalho de Integridade da Federa\u00e7\u00e3o Internacional de Futebol (FIFA) revelou que concluiu com \u00eaxito sua avalia\u00e7\u00e3o sobre as apostas esportivas realizadas globalmente durante a Copa do Mundo [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":27815,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[1461,939,4236,3813,4335,636,3748,1771,4558,4641],"class_list":["post-27812","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-australia","tag-bwin","tag-copa-do-mundo-feminina","tag-copa-do-mundo-feminina-2023","tag-copa-do-mundo-feminina-da-fifa","tag-fifa","tag-futebol-feminino","tag-insider-sport","tag-lee-anderson","tag-sport-integrity-australia"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=27812"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27812\/revisions"}],"predecessor-version":[{"id":27816,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/27812\/revisions\/27816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/27815"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=27812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=27812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=27812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}