{"id":28049,"date":"2023-09-08T09:24:23","date_gmt":"2023-09-08T12:24:23","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=28049"},"modified":"2023-09-08T11:50:27","modified_gmt":"2023-09-08T14:50:27","slug":"playtech-jogo-responsavel-relatorio-online","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/playtech-jogo-responsavel-relatorio-online\/","title":{"rendered":"Playtech publica relat\u00f3rio sobre Jogo Respons\u00e1vel"},"content":{"rendered":"\n<p>No in\u00edcio deste m\u00eas, a <strong>Playtech<\/strong>, empresa l\u00edder na ind\u00fastria de jogos e de apostas esportivas a n\u00edvel mundial, lan\u00e7ou o e-book <em>\u2018Juego Responsable: Perspectivas y tendencias de consumo en Am\u00e9rica Latina 2022\u2019<\/em> para o mercado iGaming na Am\u00e9rica Latina.&nbsp;<\/p>\n\n\n\n<p>A publica\u00e7\u00e3o explora as preocupa\u00e7\u00f5es e os interesses do p\u00fablico e proporciona uma vis\u00e3o mais ampla sobre as pr\u00e1ticas de jogo respons\u00e1vel.<\/p>\n\n\n\n<p>O relat\u00f3rio, ainda, ressalta o compromisso da Playtech em promover um ambiente de jogo seguro e justo, ao mesmo tempo que impulsiona os padr\u00f5es da ind\u00fastria mundialmente.&nbsp;<\/p>\n\n\n\n<p>Na quinta-feira (7), a Playtech disponibilizou a segunda edi\u00e7\u00e3o do relat\u00f3rio de Jogo Respons\u00e1vel e incluiu dados sobre o mercado de apostas on-line na Am\u00e9rica Latina.&nbsp;<\/p>\n\n\n\n<p>\u201cO e-book oferece uma an\u00e1lise sem precedentes sobre as prefer\u00eancias dos jogadores on-line e sobre suas percep\u00e7\u00f5es sobre a seguran\u00e7a da ind\u00fastria\u201d, declarou a empresa em comunicado.&nbsp;<\/p>\n\n\n\n<p>O relat\u00f3rio completo em espanhol pode ser conferido <a href=\"https:\/\/www.playtech.com\/application\/files\/4616\/9381\/4192\/Playtech-Ebook-2022_FINAL-SPA.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio deste m\u00eas, a Playtech, empresa l\u00edder na ind\u00fastria de jogos e de apostas esportivas a n\u00edvel mundial, lan\u00e7ou o e-book \u2018Juego Responsable: Perspectivas y tendencias de consumo en [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":28051,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3667],"tags":[57,4701,3644,3659,4781,3744,4504,3767,326,4780],"class_list":["post-28049","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional-2","tag-america-latina","tag-apostas-em-esportes","tag-apostas-esportivas","tag-cassino-online","tag-e-book","tag-jogo-responsavel","tag-jogos-de-cassino-na-america-latina","tag-jogos-de-cassino-online","tag-playtech","tag-relato-de-jogo-responsavel"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=28049"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28049\/revisions"}],"predecessor-version":[{"id":28050,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28049\/revisions\/28050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/28051"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=28049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=28049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=28049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}