{"id":28093,"date":"2023-09-11T17:01:21","date_gmt":"2023-09-11T20:01:21","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=28093"},"modified":"2023-09-11T17:08:18","modified_gmt":"2023-09-11T20:08:18","slug":"blaze-sites-espelhos-decisao-judicial","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/blaze-sites-espelhos-decisao-judicial\/","title":{"rendered":"Para driblar a justi\u00e7a, Blaze desenvolve sites iguais ao original e segue operando no pa\u00eds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No in\u00edcio do m\u00eas, a<strong> Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel) <\/strong>acatou a <a href=\"https:\/\/sbcnoticias.com\/br\/blaze-anatel-decisao-judicial\/\" target=\"_blank\" rel=\"noreferrer noopener\">decis\u00e3o da Justi\u00e7a de S\u00e3o Paulo<\/a> e determinou o bloqueio do site de cassino e de apostas esportivas <strong>Blaze<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, a casa utilizou sua conta no <em>X<\/em> (antigo <em>Twitter<\/em>) para informar a cria\u00e7\u00e3o dos dois \u2018sites espelhos\u2019 de seu endere\u00e7o principal. Nesse caso, as plataformas s\u00e3o exatamente iguais \u00e0s original, mas com URLs diferentes, na tentativa de burlar a decis\u00e3o judicial.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">N\u00e3o consegue acessar o Blaze? Experimente um destes espelhos abaixo:<br><br>URL: <a href=\"https:\/\/t.co\/gDu6pgdw7G\">https:\/\/t.co\/gDu6pgdw7G<\/a><br>URL: <a href=\"https:\/\/t.co\/dX0csC4138\">https:\/\/t.co\/dX0csC4138<\/a><br><br>Quer ser atualizado instantaneamente sobre novas URLs da Blaze? Marque nosso site nos favoritos: <a href=\"https:\/\/t.co\/g6Zsin0Bpq\">https:\/\/t.co\/g6Zsin0Bpq<\/a> <a href=\"https:\/\/t.co\/rzNJPNrwhC\">pic.twitter.com\/rzNJPNrwhC<\/a><\/p>&mdash; Blaze \ud83c\udfb0 (@blazecombr) <a href=\"https:\/\/twitter.com\/blazecombr\/status\/1699104135184879945?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">September 5, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A operadora ainda forneceu um website voltado apenas para a divulga\u00e7\u00e3o dos sites espelhos, garantindo que fornecer\u00e1 atualiza\u00e7\u00f5es instant\u00e2neas sobre as novas URLs da plataforma.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/gx1yj794DeWmr135dr6Z9AUP3OecUMFsEjpjnfCyn9Urj-R4CwDRUWkTA49sU0_rQaEik91bDso189Halyhbe1j15jwiEZ-UjhKIParQnmGslsrnnixVJJMkYR3V0GghJ455SRW_TtfXIsde9WVwMJw\" alt=\"\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a influencer <strong>Juju Ferrari<\/strong>, que realizava divulga\u00e7\u00f5es da Blaze em sua conta no <em>Instagram<\/em>, teve sua conta retirada do ar. A casa j\u00e1 acumula mais de 26 mil reclama\u00e7\u00f5es no <em>Reclame Aqui<\/em>, e os coment\u00e1rios s\u00e3o, majoritariamente, relacionados a travamentos de saques.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">A defesa da Blaze<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nos \u00faltimos meses, a operadora havia negado qualquer tipo de ilegalidade em sua plataforma. A casa alegou que n\u00e3o houve manipula\u00e7\u00e3o de resultados de seus jogos e classificaram as publica\u00e7\u00f5es como \u201cabsolutamente falsas\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Blaze explicou, ainda, que o conte\u00fado dispon\u00edvel na plataforma \u00e9 desenvolvido por alguns dos principais provedores da ind\u00fastria, assim como os produtos originais da casa, garantindo um sistema de honestidade provada e aleatoriedade nos resultados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio do m\u00eas, a Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel) acatou a decis\u00e3o da Justi\u00e7a de S\u00e3o Paulo e determinou o bloqueio do site de cassino e de apostas esportivas [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":28096,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,3665],"tags":[4763,3644,3755,3582,3659,4810,3723,3655,3925,4811],"class_list":["post-28093","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-cassinos-online","tag-anatel","tag-apostas-esportivas","tag-apostas-no-brasil","tag-blaze","tag-cassino-online","tag-decisao-judicial","tag-fraude-em-apostas","tag-jogos-de-cassino","tag-manipulacao-de-resultados","tag-sites-de-cassino"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=28093"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28093\/revisions"}],"predecessor-version":[{"id":28099,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/28093\/revisions\/28099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/28096"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=28093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=28093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=28093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}