{"id":31589,"date":"2024-05-24T12:54:00","date_gmt":"2024-05-24T15:54:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=31589"},"modified":"2024-05-24T12:54:10","modified_gmt":"2024-05-24T15:54:10","slug":"loteria-estadual-sao-paulo-edital","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/loteria-estadual-sao-paulo-edital\/","title":{"rendered":"Governo de SP deve publicar edital de licita\u00e7\u00e3o de loteria estadual em breve"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Tarc\u00edsio Gomes de Freitas <\/strong>(Republicanos), governador de S\u00e3o Paulo, deve publicar, em breve, edital de licita\u00e7\u00e3o de loteria estadual. Toda quantia arrecadada proveniente de jogos e de apostas ser\u00e1 destinada \u00e0 \u00e1rea da sa\u00fade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O projeto foi avaliado pelo <strong>Conselho Diretor do Programa de Desestatiza\u00e7\u00e3o (CDPED)<\/strong> ontem, 23, e, ap\u00f3s a aprova\u00e7\u00e3o, a publica\u00e7\u00e3o do edital deve ser feita at\u00e9 o come\u00e7o de junho. A escolha da empresa dever\u00e1 ser feita em setembro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A iniciativa \u00e9 dirigida pela <strong>Companhia Paulista de Parcerias (CPP)<\/strong>, integrada \u00e0 <strong>Secretaria de Parcerias em Investimentos<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos com altas expectativas\u201d, disse o diretor-presidente da CPP, <strong>Edgard Benozatti Neto<\/strong>, \u00e0 <em>Folha<\/em>, afirmando que \u00e9 um dos principais projetos do governo de SP.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2023, um estudo relacionado ao projeto foi aprovado. Para o governo, os questionamentos t\u00e9cnicos abordados pelo <strong>Tribunal de Contas do Estado de S\u00e3o Paulo (TCE-SP)<\/strong>, os quais impediram que o edital de loteria estadual fosse publicado em 2022, foram corrigidos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO TCE tem sempre a prerrogativa de fazer questionamentos e entrar com ressalvas, mas olhamos com aten\u00e7\u00e3o o projeto anterior e a decis\u00e3o do TCE em rela\u00e7\u00e3o a ele para mitigar qualquer questionamento&#8221;, disse Bezonatti, e acrescentou: \u201cO TCE levantou pontos relevantes, ent\u00e3o trouxemos especialistas e tivemos bons insights com o mercado\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A CPP ainda n\u00e3o divulgou quais s\u00e3o as estimativas de receita do governo com a loteria estadual. No entanto, a empresa vencedora precisar\u00e1 dividir o monop\u00f3lio com a <strong>Caixa Econ\u00f4mica Federal (CEF)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o diretor-presidente CPP, a loteria estadual de SP est\u00e1 explorando um novo modelo, \u201cimportando a experi\u00eancia do governo em concess\u00f5es e Parcerias P\u00fablico-Privadas (PPPs) para os servi\u00e7os lot\u00e9ricos\u201d, relatou a <em>Folha<\/em>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O estado s\u00f3 intervir\u00e1 quando for necess\u00e1rio, como em casos de combate ao v\u00edcio em jogos (ludopatia). As empresas ter\u00e3o liberdade para explorar a atividade, conforme explicou Bezonatti.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Cria\u00e7\u00e3o da Loteria Municipal de Campinas \u00e9 aprovada por vereadores<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Na segunda-feira, 20, a <a href=\"https:\/\/sbcnoticias.com\/br\/loteria-municipal-campinas-aprovada-vereadores\/\" target=\"_blank\" rel=\"noreferrer noopener\">cria\u00e7\u00e3o da\u00a0<strong>Loteria Municipal<\/strong><\/a><strong> de Campinas (Locamp)<\/strong>\u00a0foi aprovada pelos vereadores do munic\u00edpio paulista. A proposta foi enviada ao prefeito\u00a0<strong>D\u00e1rio Saadi<\/strong>\u00a0para que seja aprovada como lei municipal. Al\u00e9m disso, a\u00a0<strong>Secretaria Municipal de Finan\u00e7as\u00a0<\/strong>ser\u00e1 respons\u00e1vel por dirigir o processo.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, os operadores da Locamp definir\u00e3o os valores das apostas, dos bilhetes numerados, assim como das cartelas rasp\u00e1veis, dos demais produtos de loteria, os quais ser\u00e3o explorados, e das premia\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs loterias municipais foram viabilizadas por lei federal e s\u00e3o uma fonte importante de recursos para as cidades\u201d, declarou<strong>&nbsp;Fernando Mendes<\/strong>, vereador e vice-l\u00edder de governo na C\u00e2mara.&nbsp;Mendes ressaltou, ainda, que todos os valores arrecadados com as vendas lot\u00e9ricas, com exce\u00e7\u00e3o dos pr\u00eamios, ser\u00e3o destinados \u00e0s secretarias municipais de<strong>&nbsp;Desenvolvimento e Assist\u00eancia Social<\/strong>, de<strong>&nbsp;Esportes e Lazer&nbsp;<\/strong>e de&nbsp;<strong>Cultura e Turismo<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tarc\u00edsio Gomes de Freitas (Republicanos), governador de S\u00e3o Paulo, deve publicar, em breve, edital de licita\u00e7\u00e3o de loteria estadual. Toda quantia arrecadada proveniente de jogos e de apostas ser\u00e1 destinada [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":31590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3668],"tags":[3989,3644,3953,89,1152,6997,3633,6998,6996,3673,6995,6993,191,3655,3202,3674,6925,3963,4355,6922,3874,5463,5460,6992,7001],"class_list":["post-31589","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loterias","tag-america-latina-2","tag-apostas-esportivas","tag-apostas-online","tag-brasil","tag-caixa-economica-federal-2","tag-cdped","tag-cef","tag-companhia-paulista-de-parcerias","tag-conselho-diretor-do-programa-de-desestatizacao","tag-edital","tag-governador","tag-governo-de-sao-paulo","tag-igaming","tag-jogos-de-cassino","tag-latam","tag-licitacao","tag-locamp","tag-loteria-estadual","tag-loteria-municipal","tag-loteria-municipal-de-campinas","tag-sao-paulo-2","tag-secretaria-de-parcerias-em-investimentos","tag-sp-2","tag-tarcisio-gomes-de-freitas","tag-tce-sp"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=31589"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31589\/revisions"}],"predecessor-version":[{"id":31591,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31589\/revisions\/31591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/31590"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=31589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=31589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=31589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}