{"id":31595,"date":"2024-05-24T15:39:00","date_gmt":"2024-05-24T18:39:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=31595"},"modified":"2024-05-24T15:43:23","modified_gmt":"2024-05-24T18:43:23","slug":"everymatrix-mihnea-dobre-cto","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/everymatrix-mihnea-dobre-cto\/","title":{"rendered":"EveryMatrix nomeia Mihnea Dobre nova CTO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/sbcdirectory.com\/\/company\/everymatrix\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>EveryMatrix<\/strong><\/a> anunciou a nomea\u00e7\u00e3o de <strong>Mihnea Dobre <\/strong>como diretora de Tecnologia (CTO) do grupo, que faz parte da equipe de lideran\u00e7a do fornecedor de software de jogos on-line.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anteriormente respons\u00e1vel pela governan\u00e7a de TI e parte do neg\u00f3cio por quase uma d\u00e9cada, Dobre agora liderar\u00e1 a estrat\u00e9gia e as <a href=\"https:\/\/sbcnoticias.com\/br\/everymatrix-ebitda-trimestre-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\">opera\u00e7\u00f5es de tecnologia<\/a> da EveryMatrix em sua nova fun\u00e7\u00e3o, encabe\u00e7ando o desenvolvimento t\u00e9cnico, fornecendo orienta\u00e7\u00e3o t\u00e9cnica e apoiando os CTOs em todas as unidades de neg\u00f3cios da empresa para atingir seus objetivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTrabalhar ao lado de Mihnea nos \u00faltimos oito anos foi um prazer desde o primeiro dia. Sua nomea\u00e7\u00e3o como CTO do grupo \u00e9 uma progress\u00e3o l\u00f3gica, pois a empresa prospera em meio a um crescimento exponencial e tem uma for\u00e7a de trabalho de mais de 1.000 funcion\u00e1rios\u201d, disse <strong>Ebbe Groes<\/strong>, CEO da EveryMatrix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSua experi\u00eancia garantir\u00e1 uma gest\u00e3o tranquila das opera\u00e7\u00f5es, o que \u00e9 crucial para manter os elevados padr\u00f5es de servi\u00e7o que os nossos clientes exigem\u201d, acrescentou Groes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dobre inicialmente ingressou na EveryMatrix como head de Gerenciamento de Incidentes com uma equipe de apenas quatro pessoas, antes de formar as equipes de Suporte T\u00e9cnico e de Governan\u00e7a de TI um ano depois, ajudando a melhorar os processos de libera\u00e7\u00e3o e de gerenciamento de mudan\u00e7as da empresa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAssumir o papel de CTO me enche de entusiasmo. N\u00e3o se trata do cargo, mas sim de mergulhar em um mundo em que a tecnologia encontra mudan\u00e7as reais\u201d, observou Dobre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAssumir essa fun\u00e7\u00e3o foi \u00f3bvio \u2013 aproveitei a oportunidade de fazer a diferen\u00e7a com criatividade e novas ideias e estou verdadeiramente grata pela confian\u00e7a que me deram. Mal posso esperar para arrega\u00e7ar as mangas com a equipe e projetar o futuro passo a passo\u201d, declarou a nova CTO.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A EveryMatrix anunciou a nomea\u00e7\u00e3o de Mihnea Dobre como diretora de Tecnologia (CTO) do grupo, que faz parte da equipe de lideran\u00e7a do fornecedor de software de jogos on-line. Anteriormente [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":31597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3665],"tags":[3647,4287,3659,4505,3742,4834,169,191,4504,3767,3660,7003],"class_list":["post-31595","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cassinos-online","tag-apostas","tag-apostas-na-america-latina","tag-cassino-online","tag-cassinos-na-america-latina","tag-cassinos-online","tag-cto","tag-everymatrix","tag-igaming","tag-jogos-de-cassino-na-america-latina","tag-jogos-de-cassino-online","tag-jogos-online","tag-mihnea-dobre"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=31595"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31595\/revisions"}],"predecessor-version":[{"id":31596,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31595\/revisions\/31596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/31597"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=31595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=31595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=31595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}