{"id":31749,"date":"2024-06-03T11:49:48","date_gmt":"2024-06-03T14:49:48","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=31749"},"modified":"2024-06-03T12:39:04","modified_gmt":"2024-06-03T15:39:04","slug":"lotesul-edital-credenciamento-anulado-stj","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/lotesul-edital-credenciamento-anulado-stj\/","title":{"rendered":"STJ mant\u00e9m anula\u00e7\u00e3o do edital da nova Lotesul"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O <strong>Supremo Tribunal de Justi\u00e7a (STJ) <\/strong>negou o recurso da <strong>Procuradoria-Geral do Estado (PGE) <\/strong>e manteve a anula\u00e7\u00e3o do edital para a <strong>Loteria do Estado de Mato Grosso do Sul (Lotesul)<\/strong>.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O recurso foi negado por unanimidade durante a sess\u00e3o virtual da Primeira Turma, composta pelos ministros <strong>Alexandre de Moraes<\/strong>, presidente do STJ, <strong>Luiz Fux<\/strong>, <strong>Cristiano Zanin<\/strong>, <strong>Fl\u00e1vio Dino<\/strong> e <strong>C\u00e1rmen L\u00facia<\/strong>, que aconteceu entre 21 e 27 de maio.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Lotesul possui uma proje\u00e7\u00e3o de faturamento de R$ 9,8 bilh\u00f5es em dez anos de opera\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Irregularidades na Lotesul<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Em 23 de setembro de 2021, o ex-governador do Estado, <strong>Reinaldo Azambuja Silva<\/strong>, publicou a <a href=\"https:\/\/www.legisweb.com.br\/legislacao\/?id=420709#:~:text=Disp%C3%B5e%20sobre%20o%20servi%C3%A7o%20p%C3%BAblico,de%20Mato%20Grosso%20do%20Sul.\" target=\"_blank\" rel=\"noreferrer noopener\">Lei n\u00ba 5.720<\/a>, alterando a Lei n\u00ba 4.640\/2014 e regulamentando as atividades lot\u00e9ricas em Mato Grosso do Sul.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quase um ano depois, em agosto de 2022, o governo do Estado publicou o edital de chamamento para as empresas interessadas em operar servi\u00e7os lot\u00e9ricos na regi\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, ainda no mesmo m\u00eas, a <strong>NGT Brasil Tecnologia e Atividades Lot\u00e9ricas Ltda<\/strong>, sediada em Curitiba, no Paran\u00e1, entrou com um mandado de seguran\u00e7a no <strong>Tribunal de Justi\u00e7a de Mato Grosso do Sul (TJ-MS)<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa entrou com recurso administrativo para alertar a <strong>Secretaria Estadual de Fazenda (Sefaz)<\/strong> e destacou irregularidades da lei dos servi\u00e7os lot\u00e9ricos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No final do m\u00eas, o governo de Mato Grosso do Sul rejeitou as impugna\u00e7\u00f5es e, em dezembro, o edital foi anulado. A PGE ainda aguardava o julgamento do recurso no STJ.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No mandado de seguran\u00e7a, apresentado ao TJ-MS, a NGT Brasil Tecnologia e Atividades Lot\u00e9ricas Ltda afirmou que \u201co Edital cria, em verdade, um processo seletivo de um operador de forma disfar\u00e7ada\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIsso ocorre porque o Edital prev\u00ea limita\u00e7\u00e3o de empresas aptas que ser\u00e3o contratadas\u201d, ressaltou, alegando que, al\u00e9m de atenderem os requisitos do Edital, ser\u00e3o contratadas as empresas que \u201cprotocolarem o pedido com maior anteced\u00eancia, o que n\u00e3o possui amparo legal\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa abordou outras viola\u00e7\u00f5es e irregularidades da Lotesul, indicando que n\u00e3o haver\u00e1 um \u201cverdadeiro procedimento de credenciamento\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O governo recusou-se, ainda, a aceitar protocolos digitais: \u201cSendo vedado o envio de qualquer tipo de documento por via eletr\u00f4nica, o que dificulta o acesso dos participantes ao Processo de Credenciamento, configurando restri\u00e7\u00e3o indevida de participa\u00e7\u00e3o do processo seletivo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Supremo Tribunal de Justi\u00e7a (STJ) negou o recurso da Procuradoria-Geral do Estado (PGE) e manteve a anula\u00e7\u00e3o do edital para a Loteria do Estado de Mato Grosso do Sul [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":31750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3668],"tags":[7115,3989,3644,89,4758,3673,3202,7118,7117,3800,7112,1062,7109,7122,3499,7121,5831,7114,7110,7116,7123,7124,7125,7113,7120,7119],"class_list":["post-31749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-loterias","tag-alexandre-de-moraes","tag-america-latina-2","tag-apostas-esportivas","tag-brasil","tag-credenciamento","tag-edital","tag-latam","tag-lei-no-4-640-2014","tag-lei-no-5-720-2021","tag-loteria-2","tag-loteria-estadual-do-estado-de-mato-grosso-do-sul","tag-loterias-2","tag-lotesul","tag-mandado-de-seguranca","tag-mato-grosso-do-sul","tag-ngt-brasil-tecnologia-e-atividades-lotericas-ltda","tag-operacao","tag-pge","tag-procuradoria-geral-do-estado","tag-reinaldo-azambuja-silva","tag-secretaria-estadual-de-fazenda","tag-sefaz","tag-servicos-lotericos","tag-stj","tag-tj-ms","tag-tribunal-de-justica-de-mato-grosso-do-sul"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=31749"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31749\/revisions"}],"predecessor-version":[{"id":31752,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31749\/revisions\/31752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/31750"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=31749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=31749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=31749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}