{"id":31890,"date":"2024-06-07T09:38:51","date_gmt":"2024-06-07T12:38:51","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=31890"},"modified":"2024-06-07T13:50:37","modified_gmt":"2024-06-07T16:50:37","slug":"digitain-diretor-regional-vendas-latam","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/digitain-diretor-regional-vendas-latam\/","title":{"rendered":"Digitain nomeia Alonso Jibaja diretor regional de Vendas para a Am\u00e9rica Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/sbcdirectory.com\/company\/digitain\" target=\"_blank\" rel=\"noreferrer noopener\">Digitain<\/a><\/strong>, provedora de apostas esportivas e de plataforma de cassino, anunciou a nomea\u00e7\u00e3o de <strong>Alonso<\/strong> <strong>Jibaja<\/strong> como diretor Regional de Vendas para a Am\u00e9rica Latina. Entre as novas atribui\u00e7\u00f5es, Jibaja apoiar\u00e1 a estrat\u00e9gia de expans\u00e3o da Digitain no mercado de apostas e de jogos da regi\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstou realmente entusiasmado por fazer parte da Digitain, uma empresa que tem expandido constantemente suas solu\u00e7\u00f5es de neg\u00f3cios dentro da cadeia regulamentada de fornecimento de jogos on-line em todo o mundo\u201d, comemorou Jibaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA abordagem centrada no cliente da empresa e o compromisso com seu pessoal no fornecimento de solu\u00e7\u00f5es complexas para as operadoras regulamentadas multijurisdicionais de hoje sempre me impressionaram\u201d, acrescentou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo l\u00edder de vendas possui mais de 10 anos de experi\u00eancia no cen\u00e1rio comercial e de vendas do setor, assumindo fun\u00e7\u00f5es anteriores na <a href=\"https:\/\/sbcnoticias.com\/br\/digitain-potencial-america-latina-entrevista\/\" target=\"_blank\" rel=\"noreferrer noopener\">Am\u00e9rica Latina<\/a> e na Am\u00e9rica do Norte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstou ansioso para conhecer parceiros novos e existentes e colaborar com a equipe de vendas da Am\u00e9rica Latina e de todos os departamentos nos pr\u00f3ximos meses\u201d, pontuou Jibaja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O novo diretor de Vendas se reportar\u00e1 ao CRO da Digitain, <strong>Iain Hutchison<\/strong>, que deu as boas-vindas a seu novo colega: \u201cEstou muito satisfeito por ter Alonso se juntando \u00e0 nossa equipe. Com ampla experi\u00eancia em vendas e em fun\u00e7\u00f5es de desenvolvimento de neg\u00f3cios para alguns dos principais fornecedores de plataformas, Alonso apoiar\u00e1, fornecer\u00e1 e facilitar\u00e1 solu\u00e7\u00f5es ponta a ponta, \u00e0 medida que a Digitain expande seus servi\u00e7os para operadoras parceiras B2C em mercados regulamentados em toda a regi\u00e3o da Am\u00e9rica Latina\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Digitain, provedora de apostas esportivas e de plataforma de cassino, anunciou a nomea\u00e7\u00e3o de Alonso Jibaja como diretor Regional de Vendas para a Am\u00e9rica Latina. Entre as novas atribui\u00e7\u00f5es, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":31891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3665],"tags":[7216,57,3647,7218,4287,3953,3659,3742,692,191,3660,3202,7217],"class_list":["post-31890","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cassinos-online","tag-alonso-jibaja","tag-america-latina","tag-apostas","tag-apostas-esportivas-na-latam","tag-apostas-na-america-latina","tag-apostas-online","tag-cassino-online","tag-cassinos-online","tag-digitain","tag-igaming","tag-jogos-online","tag-latam","tag-vendas-latam"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=31890"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31890\/revisions"}],"predecessor-version":[{"id":31892,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/31890\/revisions\/31892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/31891"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=31890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=31890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=31890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}