{"id":32282,"date":"2024-06-27T08:52:15","date_gmt":"2024-06-27T11:52:15","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=32282"},"modified":"2024-06-27T14:13:23","modified_gmt":"2024-06-27T17:13:23","slug":"betnation-ibia-parceria-holanda","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/betnation-ibia-parceria-holanda\/","title":{"rendered":"Betnation faz parceria com IBIA na Holanda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ontem, 26, a <strong>Betnation<\/strong>, casa de apostas esportivas e de cassino on-line da <strong>Smart Gaming B.V.<\/strong>, anunciou parceria com a<strong> International Betting Integrity Association (<a href=\"https:\/\/sbcnoticias.com\/br\/genius-sports-ibia-parceria-integridade-esportiva\/\" target=\"_blank\" rel=\"noreferrer noopener\">IBIA<\/a>)<\/strong>. A nova colabora\u00e7\u00e3o est\u00e1 relacionada com o recente lan\u00e7amento de apostas esportivas da operadora na Holanda.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos entusiasmados por ingressar na IBIA\u201d, disse <strong>Robert Schouten<\/strong>, CEO da Smart Gaming B.V.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O CEO refor\u00e7ou o compromisso da empresa em \u201cpromover os mais altos padr\u00f5es de integridade nas apostas esportivas\u201d e afirmou que pretende \u201cgarantir uma experi\u00eancia de apostas segura e justa para todos os usu\u00e1rios\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a IBIA, a parceria com a Betnation a posiciona como o principal \u00f3rg\u00e3o de monitoramento de integridade de apostas esportivas do pa\u00eds, com a Associa\u00e7\u00e3o representando, atualmente, mais de 90% das plataformas licenciadas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA IBIA est\u00e1 muito satisfeita que a Betnation tenha a escolhido como sua parceira preferida de monitoramento de integridade\u201d, afirmou <strong>Khalid Ali<\/strong>, CEO da IBIA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO acordo destaca o compromisso da Betnation em proteger a integridade de seus produtos de apostas, de seus consumidores e de eventos esportivos relacionados\u201d, acrescentou Ali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A rede global de monitoramento da IBIA \u00e9 uma ferramenta de anticorrup\u00e7\u00e3o, que detecta e relata atividades suspeitas em mercados regulamentados de apostas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA IBIA espera trabalhar em estreita colabora\u00e7\u00e3o com a Betnation e integrar a operadora ao nosso sistema global de integridade de apostas esportivas\u201d, disse o CEO da IBIA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem, 26, a Betnation, casa de apostas esportivas e de cassino on-line da Smart Gaming B.V., anunciou parceria com a International Betting Integrity Association (IBIA). A nova colabora\u00e7\u00e3o est\u00e1 relacionada [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":32284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3667],"tags":[3646,7410,3644,3953,7378,7409,3659,4957,5679,7408,718,191,3771,3293,3925,3653],"class_list":["post-32282","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional-2","tag-acordo","tag-anticorrupcao","tag-apostas-esportivas","tag-apostas-online","tag-atividades-suspeitas","tag-betnation","tag-cassino-online","tag-colaboracao","tag-combate-a-manipulacao","tag-holanda","tag-ibia","tag-igaming","tag-integridade-esportiva","tag-international-betting-integrity-association","tag-manipulacao-de-resultados","tag-parceria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=32282"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32282\/revisions"}],"predecessor-version":[{"id":32285,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32282\/revisions\/32285"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/32284"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=32282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=32282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=32282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}