{"id":32871,"date":"2024-07-29T09:37:00","date_gmt":"2024-07-29T12:37:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=32871"},"modified":"2024-07-30T12:06:54","modified_gmt":"2024-07-30T15:06:54","slug":"big-brazil-autorizacao-para-operar-no-brasil","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/big-brazil-autorizacao-para-operar-no-brasil\/","title":{"rendered":"Big Brazil, da Caesars, solicita autoriza\u00e7\u00e3o para operar no mercado brasileiro de apostas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A<strong> Big Brazil<\/strong>, de propriedade da<strong> Caesars Sportsbook <\/strong>no Brasil &#8211; empresa associada \u00e0 <strong>Associa\u00e7\u00e3o Nacional de Jogos e Loterias (<a href=\"https:\/\/sbcnoticias.com\/br\/wepayments-membro-anjl\/\" target=\"_blank\" rel=\"noreferrer noopener\">ANJL<\/a>)<\/strong> -, registrou-se no <strong>Sistema de Gest\u00e3o de Apostas (SIGAP)<\/strong> do <strong>Minist\u00e9rio da Fazenda<\/strong> para solicitar licen\u00e7a federal para operar no mercado brasileiro de apostas e de jogos on-line.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para realizar a solicita\u00e7\u00e3o da autoriza\u00e7\u00e3o, a Big Brazil precisou atendeu a todos os requisitos exigidos pelas portarias publicadas pela <strong>Secretaria de Pr\u00eamios e Apostas (SPA) <\/strong>do Minist\u00e9rio da Fazenda.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a ANJL, \u201ca Big Brazil \u00e9 mais um exemplo de como as empresas s\u00e9rias, que j\u00e1 est\u00e3o atuando no Brasil legalmente e est\u00e3o se submetendo ao processo de regulariza\u00e7\u00e3o, ainda em curso, est\u00e3o comprometidas a respeitarem as regras que j\u00e1 foram e as que vierem a ser fixadas pela SPA\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pl\u00ednio Lemos Jorge<\/strong>, presidente da ANJL, informou que outras empresas de apostas j\u00e1 entraram com pedido de autoriza\u00e7\u00e3o para operar no pa\u00eds, mas os processos ainda est\u00e3o em andamento: \u201cPara constarem no SIGAP, a casa de apostas precisa enviar uma s\u00e9rie de documentos, cumprir uma extensa lista de requisitos exigidos pelo regulador. Ent\u00e3o, por isso, muitas empresas ainda n\u00e3o aparecem no sistema, embora j\u00e1 tenham dado in\u00edcio ao processo, que pode durar meses\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da Big Brazil, outras operadoras j\u00e1 protocolaram o pedido para operar no mercado brasileiro de apostas, incluindo a <a href=\"https:\/\/sbcnoticias.com\/br\/sportingbet-requerimento-licenca-para-operar-mercado-brasileiro\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sportingbet<\/strong><\/a><strong> <\/strong>e a <a href=\"https:\/\/sbcnoticias.com\/br\/betano-kaizen-gaming-cadastro-autorizacao-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Betano<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>Portaria SPA\/MF n\u00ba 827<\/strong>, respons\u00e1vel por regulamentar os pedidos de autoriza\u00e7\u00e3o, d\u00e1 prazo de 180 para as solicita\u00e7\u00f5es serem analisadas. No entanto, para as empresas que protocolarem o pedido at\u00e9 20 de agosto deste ano, o Minist\u00e9rio da Fazenda responder\u00e1 at\u00e9 31 de dezembro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO setor est\u00e1 confiante de que muitos operadores conseguir\u00e3o submeter seus pedidos dentro dessa janela\u201d, acrescentou Lemos Jorge.&nbsp;Al\u00e9m disso, a Big Brazil j\u00e1 possui o credenciamento da <strong>Loteria do Estado do Rio de Janeiro (<a href=\"https:\/\/sbcnoticias.com\/br\/loterj-okto-metodo-oficial-pagamento\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/loterj-okto-metodo-oficial-pagamento\/\" rel=\"noreferrer noopener\">LOTERJ<\/a>)<\/strong> para operar na regi\u00e3o. A licen\u00e7a \u00e9 v\u00e1lida por cinco anos para a explora\u00e7\u00e3o de servi\u00e7os de apostas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Big Brazil, de propriedade da Caesars Sportsbook no Brasil &#8211; empresa associada \u00e0 Associa\u00e7\u00e3o Nacional de Jogos e Loterias (ANJL) -, registrou-se no Sistema de Gest\u00e3o de Apostas (SIGAP) [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":32872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[3810,3644,1390,89,3659,3655,1140,6715,3946,7827,5817,7067,4055],"class_list":["post-32871","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-anjl","tag-apostas-esportivas","tag-betano","tag-brasil","tag-cassino-online","tag-jogos-de-cassino","tag-loterj","tag-mercado-de-apostas-online","tag-ministerio-da-fazenda","tag-portaria-spa-mf-no-827","tag-secretaria-de-premios-e-apostas","tag-sigap","tag-sportingbet"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=32871"}],"version-history":[{"count":3,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32871\/revisions"}],"predecessor-version":[{"id":32902,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32871\/revisions\/32902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/32872"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=32871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=32871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=32871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}