{"id":32913,"date":"2024-07-30T16:01:14","date_gmt":"2024-07-30T19:01:14","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=32913"},"modified":"2024-07-30T16:08:58","modified_gmt":"2024-07-30T19:08:58","slug":"copas-do-mundo-fifa-candidaturas-2030-2034","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/copas-do-mundo-fifa-candidaturas-2030-2034\/","title":{"rendered":"FIFA recebe propostas para sediar as Copas do Mundo de 2030 e 2034"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">As federa\u00e7\u00f5es-membros relevantes da <strong>Federa\u00e7\u00e3o Internacional de Futebol (<a href=\"https:\/\/sbcnoticias.com\/br\/fifa-gianni-infantino-integridade-esportiva-paris\/\" target=\"_blank\" rel=\"noreferrer noopener\">FIFA<\/a>) <\/strong>apresentaram candidaturas para sediarem as Copas do Mundo FIFA de 2030 e de 2034.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As Copas est\u00e3o previstas para acontecerem na Europa, na Espanha, em Portugal e em Marrocos &#8211; em que organizariam em conjunto o campeonato -, e na Am\u00e9rica Latina para o centen\u00e1rio de 2030, em que Argentina, Paraguai e Uruguai sediariam juntos o torneio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o processo de apresenta\u00e7\u00e3o, <strong>Gianni<\/strong> <strong>Infantino<\/strong>, presidente da FIFA, e o secret\u00e1rio-geral <strong>Mattias<\/strong> <strong>Grafstr\u00f6m<\/strong> receberam as propostas para as sedes das Copas do Mundo de 2030 e 2034 durante o per\u00edodo em que estavam em Paris, na Fran\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fouzi Lekjaa<\/strong>, do Marrocos, <strong>Fernando<\/strong> <strong>Gomes<\/strong>, de Portugal, e <strong>\u00c1lvaro<\/strong> <strong>de<\/strong> <strong>Miguel<\/strong> <strong>Casanueva<\/strong>, da Espanha, apresentaram os documentos para o campeonato de 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Claudio<\/strong> <strong>Tapia<\/strong>, da Argentina, <strong>Robert<\/strong> <strong>Harrison<\/strong>, do Paraguai, <strong>Ignacio<\/strong> <strong>Alonso<\/strong>, do Uruguai, e <strong>Alejandro<\/strong> <strong>Dom\u00ednguez<\/strong>, presidente da <strong><a href=\"https:\/\/sbcnoticias.com\/br\/betplay-conmebol-patrocinio-local\/\" target=\"_blank\" rel=\"noreferrer noopener\">CONMEBOL<\/a><\/strong>, tamb\u00e9m apresentaram a candidatura para o do centen\u00e1rio de 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizando detalhes j\u00e1 disponibilizados sobre a candidatura, a Copa do Mundo de 2030 ser\u00e1 sediada pelos pa\u00edses parceiros Espanha, Portugal e Marrocos, e os jogos de anivers\u00e1rio ser\u00e3o realizados na Argentina, no Uruguai e no Paraguai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a Copa do Mundo FIFA de 2034, Pr\u00edncipe Abdulaziz bin Turki Al Faisal, ministro dos Esportes da Ar\u00e1bia Saudita, Yasser Al Misehal, presidente da Federa\u00e7\u00e3o Saudita de Futebol (SAFF), e Hammad Albalawi, chefe da Unidade de Nomea\u00e7\u00f5es da SAFF, entregaram o livro de candidaturas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">At\u00e9 o momento, nenhuma outra candidatura foi feita para receber ambas as Copas do Mundo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">O processo para envio das propostas para as Copas do Mundo<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o prazo oficial para apresenta\u00e7\u00e3o de propostas, em 31 de julho, os cadernos de candidaturas e os documentos relacionados ser\u00e3o veiculados no site da FIFA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A federa\u00e7\u00e3o avaliar\u00e1 as candidaturas e publicar\u00e1 o relat\u00f3rio de avalia\u00e7\u00e3o no quarto trimestre de 2024. Se as candidaturas atenderem aos requisitos, o Congresso Extraordin\u00e1rio da FIFA decidir\u00e1 quais ser\u00e3o os anfitri\u00f5es das Copas do Mundo FIFA de 2030 e de 2034 ainda neste ano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infantino comentou: \u201cA apresenta\u00e7\u00e3o dos livros de candidatura representa um marco fundamental nos processos licitat\u00f3rios para as edi\u00e7\u00f5es de 2030 e de 2034 da Copa do Mundo FIFA, uma vez que nosso objetivo \u00e9 organizar celebra\u00e7\u00f5es ic\u00f4nicas do futebol e da humanidade\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOs sete pa\u00edses candidatos de quatro confedera\u00e7\u00f5es j\u00e1 deram muito ao futebol e s\u00e3o pa\u00edses com uma grande paix\u00e3o pelo jogo, grandes capacidades organizacionais e uma vis\u00e3o compartilhada do que o futebol e seus valores devem ser. Da mesma forma, os processos de candidatura demonstram que o futebol une o mundo\u201d, completou Infantino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A aus\u00eancia de concorr\u00eancia para sediar os torneios foi agravada pelos avisos enviados pela <a href=\"https:\/\/sbcnoticias.com\/br\/fifa-anistia-internacional-candidaturas-copa-do-mundo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amnistia Internacional<\/a> \u00e0 organiza\u00e7\u00e3o sobre os pa\u00edses anfitri\u00f5es e a rela\u00e7\u00e3o negativa que possuem com direitos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora se concentre em ambas as Copas do Mundo, o relat\u00f3rio feito pela organiza\u00e7\u00e3o n\u00e3o governamental enfatiza a de 2034. Se a Ar\u00e1bia Saudita for aprovada para sediar o torneio, ser\u00e1 a segunda vez que a Copa do Mundo ser\u00e1 realizada no Oriente M\u00e9dio, depois do Catar em 2022, que gerou uma tempestade midi\u00e1tica de preocupa\u00e7\u00f5es e de reclama\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As federa\u00e7\u00f5es-membros relevantes da Federa\u00e7\u00e3o Internacional de Futebol (FIFA) apresentaram candidaturas para sediarem as Copas do Mundo FIFA de 2030 e de 2034. As Copas est\u00e3o previstas para acontecerem na [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":32914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3667],"tags":[3647,3644,7859,7858,3953,3659,4365,636,191,7860],"class_list":["post-32913","post","type-post","status-publish","format-standard","has-post-thumbnail","category-internacional-2","tag-apostas","tag-apostas-esportivas","tag-apostas-na-copa-do-mundo","tag-apostas-na-fifa","tag-apostas-online","tag-cassino-online","tag-copa-do-mundo-fifa","tag-fifa","tag-igaming","tag-jogos-copa-do-mundo"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=32913"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32913\/revisions"}],"predecessor-version":[{"id":32915,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/32913\/revisions\/32915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/32914"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=32913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=32913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=32913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}