{"id":33046,"date":"2024-08-06T14:54:17","date_gmt":"2024-08-06T17:54:17","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=33046"},"modified":"2024-08-06T14:54:25","modified_gmt":"2024-08-06T17:54:25","slug":"kto-licenca-operacao-brasil","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/kto-licenca-operacao-brasil\/","title":{"rendered":"KTO solicita licen\u00e7a para operar no Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Na segunda-feira, 5, a <a href=\"https:\/\/sbcnoticias.com\/br\/kto-group-andreas-bardun-entrevista\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>KTO<\/strong><\/a> cadastrou-se no <strong>Sistema de Gest\u00e3o de Apostas (SIGAP)<\/strong> para obter licen\u00e7a de opera\u00e7\u00e3o no Brasil. Tendo protocolado o pedido junto \u00e0 <strong>Secretaria de Pr\u00eamios e Apostas (SPA)<\/strong>, a operadora de apostas atendeu a todos os requisitos da Lei n\u00ba 14.790 e das portarias publicadas pelo Minist\u00e9rio da Fazenda.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A KTO, que patrocina o <a href=\"https:\/\/sbcnoticias.com\/br\/kto-acordo-de-patrocinio-minas-tenis-clube-volei-basquete\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Minas T\u00eanis Clube<\/strong><\/a> e o <a href=\"https:\/\/sbcnoticias.com\/br\/kto-patrocinio-oficial-chapecoense\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Chapecoense<\/strong><\/a>, tamb\u00e9m est\u00e1 presente nas transmiss\u00f5es das Olimp\u00edadas de Paris, no Sportv, do Brasileir\u00e3o, no Caz\u00e9TV, e das Copas Libertadores e Sul-Americana, no Paramount+.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o in\u00edcio das opera\u00e7\u00f5es da marca no Rio Grande do Sul, <a href=\"https:\/\/sbcnoticias.com\/br\/kto-group-mercado-brasileiro-andreas-bardun\/\"><strong>Andreas Bardun<\/strong><\/a>, CEO do KTO Group, disse que a licen\u00e7a para atuar em territ\u00f3rio nacional representa um passo importante para a expans\u00e3o da empresa no Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cH\u00e1 mais de dois anos, v\u00ednhamos nos preparando para estar entre as primeiras marcas do segmento a requerir a licen\u00e7a no pa\u00eds. Ficamos felizes e entusiasmados com essa nova fase do mercado brasileiro, que tende a ser um dos maiores do mundo\u201d, comemorou Bardun.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na segunda-feira, 5, a KTO cadastrou-se no Sistema de Gest\u00e3o de Apostas (SIGAP) para obter licen\u00e7a de opera\u00e7\u00e3o no Brasil. Tendo protocolado o pedido junto \u00e0 Secretaria de Pr\u00eamios e [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":33047,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[3647,3644,3720,3953,3659,3742,3660],"class_list":["post-33046","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-apostas","tag-apostas-esportivas","tag-apostas-esportivas-no-brasil","tag-apostas-online","tag-cassino-online","tag-cassinos-online","tag-jogos-online"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=33046"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33046\/revisions"}],"predecessor-version":[{"id":33048,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33046\/revisions\/33048"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/33047"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=33046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=33046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=33046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}