{"id":33188,"date":"2024-08-14T12:04:55","date_gmt":"2024-08-14T15:04:55","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=33188"},"modified":"2024-08-14T12:30:34","modified_gmt":"2024-08-14T15:30:34","slug":"betcomply-diretora-operacoes","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/betcomply-diretora-operacoes\/","title":{"rendered":"BetComply anuncia diretora de Opera\u00e7\u00f5es"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ontem, 14, a <strong>BetComply<\/strong>, empresa de conformidade regulat\u00f3ria e t\u00e9cnica de apostas e de jogos, anunciou a contrata\u00e7\u00e3o s\u00eanior de <strong>Loes Wetzer<\/strong> para ocupar o cargo de diretora de Opera\u00e7\u00f5es da marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Daniel Brookes<\/strong>, CEO da empresa, disse: \u201c\u00c9 um privil\u00e9gio receber Loes na equipe da BetComply. Crescemos al\u00e9m das expectativas nos \u00faltimos meses, impulsionados por uma demanda de nossa ind\u00fastria por experi\u00eancia em conformidade confi\u00e1vel e confi\u00e1vel\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c0 medida que damos nossos pr\u00f3ximos passos, Loes ser\u00e1 uma parte vital de nossa miss\u00e3o de levar suporte de conformidade de classe mundial a ainda mais parceiros\u201d, comemorou Brookes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wetzer possui mais de 20 anos de experi\u00eancia em gerenciamento de projetos e em consultoria de conformidade. Na BetComply, supervisionar\u00e1 as opera\u00e7\u00f5es da marca.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wetzer acrescentou: \u201cEu n\u00e3o poderia estar mais animada para me juntar \u00e0 equipe din\u00e2mica da BetComply. Este j\u00e1 \u00e9 o lar de muitas das mentes mais brilhantes em conformidade da ind\u00fastria de apostas e de jogos, e o que eles conquistaram em t\u00e3o pouco tempo \u00e9 not\u00e1vel. Estou ansiosa para desempenhar meu papel\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ontem, 14, a BetComply, empresa de conformidade regulat\u00f3ria e t\u00e9cnica de apostas e de jogos, anunciou a contrata\u00e7\u00e3o s\u00eanior de Loes Wetzer para ocupar o cargo de diretora de Opera\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":33189,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,3665],"tags":[3647,3644,3953,3659,3742,3660],"class_list":["post-33188","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-cassinos-online","tag-apostas","tag-apostas-esportivas","tag-apostas-online","tag-cassino-online","tag-cassinos-online","tag-jogos-online"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=33188"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33188\/revisions"}],"predecessor-version":[{"id":33191,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33188\/revisions\/33191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/33189"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=33188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=33188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=33188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}