{"id":33207,"date":"2024-08-15T08:10:00","date_gmt":"2024-08-15T11:10:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=33207"},"modified":"2024-08-15T16:19:42","modified_gmt":"2024-08-15T19:19:42","slug":"estrelabet-santa-casa-bh-uniforme-atletas-publicidade","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/estrelabet-santa-casa-bh-uniforme-atletas-publicidade\/","title":{"rendered":"EstrelaBet cede espa\u00e7o nobre do uniforme do time sub-20 do Am\u00e9rica-MG ao Santa Casa BH"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/sbcnoticias.com\/br\/estrelabet-licenca-para-operar-brasil-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">EstrelaBet<\/a><\/strong>, patrocinadora m\u00e1ster dos times masculino e feminino do <strong><a href=\"https:\/\/sbcnoticias.com\/br\/estrelabet-america-mg-patrocinio\/\" target=\"_blank\" rel=\"noreferrer noopener\">Am\u00e9rica-MG<\/a><\/strong>, cedeu o espa\u00e7o nobre da camiseta dos jogadores do time sub-20 para o <strong>Santa Casa BH<\/strong>, hospital localizado em Belo Horizonte, Minas Gerais.\u00a0O uniforme com a nova publicidade foi lan\u00e7ado ontem, 14, na partida entre Am\u00e9rica-MG e <strong>Cear\u00e1 <\/strong>pelo <strong>Brasileir\u00e3o Sub-20<\/strong> masculino.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Marcone Barbosa<\/strong>, diretor de Marketing e Neg\u00f3cios do Am\u00e9rica-MG, apreciou a iniciativa da EstrelaBet: \u201c\u00c9 louv\u00e1vel o que a EstrelaBet fez, oferecendo seu espa\u00e7o em nossa camiseta para colocar o nome de uma Institui\u00e7\u00e3o muito respeitada e importante para o povo mineiro. Isso s\u00f3 corrobora os valores que buscamos em nossos parceiros\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a EstrelaBet, a medida ir\u00e1 gerar mais visibilidade \u00e0 uma causa de grande impacto social, atendendo \u00e0s novas diretrizes da regulamenta\u00e7\u00e3o das apostas no mercado brasileiro e evitando que menores de idade tenham acesso \u00e0 publicidade das apostas.\u00a0Nas demais modalidades profissionais, a EstrelaBet manter\u00e1 as apari\u00e7\u00f5es at\u00e9 o final deste ano.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara nos adequarmos \u00e0 nova legisla\u00e7\u00e3o, retiramos a EstrelaBet dos uniformes do time sub-20 do Am\u00e9rica. Ao fazermos essa altera\u00e7\u00e3o, decidimos ceder o espa\u00e7o para apoiar uma causa importante e nobre. A escolha do Santa Casa BH se deu porque \u00e9 um projeto que gera um impacto positivo na comunidade e que necessita dessa visibilidade\u201d, comentou <strong>Leandro Figueiredo<\/strong>, head de Patroc\u00ednios da EstrelaBet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Roberto Otto Augusto de Lima<\/strong>, provedor do Santa Casa BH, agradeceu \u00e0 empresa de apostas: \u201cA EstrelaBet est\u00e1 unindo duas institui\u00e7\u00f5es comprometidas com os mineiros, cada uma em sua \u00e1rea de atua\u00e7\u00e3o. Estampar a nossa marca no uniforme de uma equipe jovem e promissora, como a sub-20 do Am\u00e9rica, \u00e9 uma honra, e um reconhecimento da nossa miss\u00e3o de cuidar e promover sa\u00fade de ponta para todos\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo a institui\u00e7\u00e3o de sa\u00fade mais relevante de Minas Gerais, sermos abra\u00e7ados por um dos clubes mais tradicionais do estado \u00e9 um reflexo de nossa marca, que \u00e9 querida e admirada por toda a comunidade mineira\u201d, afirmou Lima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A EstrelaBet, patrocinadora m\u00e1ster dos times masculino e feminino do Am\u00e9rica-MG, cedeu o espa\u00e7o nobre da camiseta dos jogadores do time sub-20 para o Santa Casa BH, hospital localizado em [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":33208,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[7984,3644,7983,1430,2880,4120,3898,3889,7982],"class_list":["post-33207","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-america-mg-2","tag-apostas-esportivas","tag-brasileirao-sub-20","tag-ceara","tag-estrelabet","tag-mercado-de-apostas-brasileiro","tag-patrocinio-master-2","tag-regulamentacao-das-apostas","tag-santa-casa-bh"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=33207"}],"version-history":[{"count":6,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33207\/revisions"}],"predecessor-version":[{"id":33225,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33207\/revisions\/33225"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/33208"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=33207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=33207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=33207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}