{"id":33529,"date":"2024-09-03T13:46:56","date_gmt":"2024-09-03T16:46:56","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=33529"},"modified":"2024-09-03T17:02:50","modified_gmt":"2024-09-03T20:02:50","slug":"cpi-das-apostas-robinson-barreirinhas-depoimento","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/cpi-das-apostas-robinson-barreirinhas-depoimento\/","title":{"rendered":"CPI das Apostas Esportivas ouve secret\u00e1rio especial da Receita Federal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A<strong> Comiss\u00e3o Parlamentar de Inqu\u00e9rito (<a href=\"https:\/\/sbcnoticias.com\/br\/anjl-cpi-das-apostas-depoimento-wesley-cardia\/\">CPI<\/a>) da Manipula\u00e7\u00e3o de Jogos e Apostas Esportivas <\/strong>receber\u00e1 <strong>Robinson Barreirinhas<\/strong>, secret\u00e1rio especial da <strong>Receita Federa<\/strong>l, na quarta-feira, 4.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a <em>Ag\u00eancia Senado<\/em>, ele dever\u00e1 explicar as obriga\u00e7\u00f5es tribut\u00e1rias das empresas de apostas e a incid\u00eancia de impostos sobre os pr\u00eamios obtidos na modalidade de apostas de quota fixa.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O requerimento foi feito pelo senador <strong>Carlos Portinho<\/strong> (PL-RJ), que citou a reportagem da <em>Folha de S\u00e3o Paulo<\/em> do dia 20 de maio deste ano, destacando as elevadas remessas para o exterior por meio de apostas esportivas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cImperioso saber inicialmente se essas plataformas de apostas esportivas que operam abertamente no mercado nacional, inclusive patrocinando in\u00fameros clubes das s\u00e9ries A e B do<strong> Campeonato Brasileiro<\/strong> de Futebol e anunciando em diversos ve\u00edculos midi\u00e1ticos de TV aberta, est\u00e3o atuando de forma l\u00edcita ou il\u00edcita no pa\u00eds, movimentando bilh\u00f5es de reais, enviando esses recursos para outros pa\u00edses, n\u00e3o recolhendo os tributos devidos\u201d, disse o senador.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Requerimentos da CPI da Manipula\u00e7\u00e3o de Resultados&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Portinho tamb\u00e9m apresentou requerimento para ouvir<strong> Lu\u00eds Ot\u00e1vio Ver\u00edssimo Teixeira<\/strong>, presidente do <strong>Superior Tribunal de Justi\u00e7a Desportiva do Futebol (STJD)<\/strong>, e <strong>Paulo Em\u00edlio Dantas Nazar\u00e9<\/strong>, procurador-geral do STJD. O objetivo do senador \u00e9 esclarecer as medidas planejadas para tratar a <a href=\"https:\/\/sbcnoticias.com\/br\/itia-supensao-tenistas-fraude-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">manipula\u00e7\u00e3o de resultados<\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alfredo Loebeling<\/strong>, ex-\u00e1rbitro de futebol, tamb\u00e9m foi convidado a participar da CPI pelo senador, para conversar sobre as den\u00fancias de falhas e de limita\u00e7\u00f5es tecnol\u00f3gicas do sistema de VAR (\u00c1rbitro Assistente de V\u00eddeo, em portugu\u00eas) adquirido pela <strong>Confedera\u00e7\u00e3o Brasileira de Futebol (<a href=\"https:\/\/sbcnoticias.com\/br\/cbf-regulamento-novas-regras-publicidade-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">CBF<\/a>)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O senador <strong>Rom\u00e1rio <\/strong>(PL-RJ), relator da CPI, requer a presen\u00e7a de <strong>Andr\u00e9 Gelfi<\/strong>, presidente do<strong> Instituto Brasileiro de Jogo Respons\u00e1vel (<a href=\"https:\/\/sbcnoticias.com\/br\/ibjr-webinario-fornecedores-de-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">IBJR<\/a>)<\/strong>, para entender a posi\u00e7\u00e3o do IBJR em rela\u00e7\u00e3o \u00e0 regulamenta\u00e7\u00e3o das apostas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o Parlamentar de Inqu\u00e9rito (CPI) da Manipula\u00e7\u00e3o de Jogos e Apostas Esportivas receber\u00e1 Robinson Barreirinhas, secret\u00e1rio especial da Receita Federal, na quarta-feira, 4.&nbsp; Segundo a Ag\u00eancia Senado, ele dever\u00e1 [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":33530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[4748,3644,5368,1264,3978,3805,3925,4043,4156],"class_list":["post-33529","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-andre-gelfi-2","tag-apostas-esportivas","tag-carlos-portinho","tag-cbf","tag-cpi-das-apostas","tag-ibjr","tag-manipulacao-de-resultados","tag-romario-2","tag-stjd"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=33529"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33529\/revisions"}],"predecessor-version":[{"id":33537,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33529\/revisions\/33537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/33530"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=33529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=33529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=33529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}