{"id":33856,"date":"2024-09-17T11:08:50","date_gmt":"2024-09-17T14:08:50","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=33856"},"modified":"2024-09-17T11:48:21","modified_gmt":"2024-09-17T14:48:21","slug":"sites-apostas-sem-licencas-suspensos-spa","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/sites-apostas-sem-licencas-suspensos-spa\/","title":{"rendered":"Sites de apostas que n\u00e3o pediram autoriza\u00e7\u00e3o ser\u00e3o suspensos a partir de outubro, diz Fazenda"},"content":{"rendered":"\n<p>Hoje, 17, a <strong>Secretaria de Pr\u00eamios e Apostas<\/strong> <strong>(SPA)<\/strong>, vinculada ao <strong>Minist\u00e9rio da Fazenda<\/strong>,<strong> <\/strong>publicou, no Di\u00e1rio Oficial da Uni\u00e3o (DOU), a <strong><a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/portaria-spa\/mf-n-1.475-de-16-de-setembro-de-2024-584820215\" target=\"_blank\" rel=\"noreferrer noopener\">Portaria n\u00ba 1.475<\/a><\/strong>, proibindo o funcionamento de sites de apostas esportivas e de jogos on-line que ainda n\u00e3o solicitaram licen\u00e7a para opera\u00e7\u00e3o no Brasil. A suspens\u00e3o entra em vigor no dia 1\u00ba de outubro.<\/p>\n\n\n\n<p>Visando n\u00e3o prejudicar os apostadores que t\u00eam pr\u00eamios em casas de apostas n\u00e3o regularizadas, a SPA estabeleceu que o levantamento desse dinheiro possa ser feito at\u00e9 10 de outubro. A partir do dia 11 de outubro, acontecer\u00e1 o bloqueio e a exclus\u00e3o dos sites e dos aplicativos que n\u00e3o solicitaram a outorga para atuarem no pa\u00eds.<\/p>\n\n\n\n<p>As empresas que apresentaram o requerimento ao Minist\u00e9rio da Fazenda t\u00eam at\u00e9 o dia 30 de setembro para indicar as marcas em atividade e os dom\u00ednios de internet em que os servi\u00e7os ser\u00e3o prestados a partir da vig\u00eancia da regulamenta\u00e7\u00e3o, no dia 1\u00ba de janeiro de 2025.<\/p>\n\n\n\n<p>Empresas que solicitaram o requerimento mas ainda n\u00e3o estavam em atua\u00e7\u00e3o ter\u00e3o de esperar at\u00e9 a virada do ano para iniciarem a opera\u00e7\u00e3o. A partir de ent\u00e3o, apenas agentes autorizados poder\u00e3o atuar, utilizando dom\u00ednio brasileiro de internet com extens\u00e3o bet.br.<\/p>\n\n\n\n<p>De acordo com a portaria, o descumprimento ou \u201co cometimento de atos il\u00edcitos ser\u00e1 considerado na an\u00e1lise do pedido de autoriza\u00e7\u00e3o para explora\u00e7\u00e3o comercial da modalidade lot\u00e9rica de apostas de quota fixa, tendo em vista o interesse nacional e a prote\u00e7\u00e3o dos interesses da coletividade\u201d.<\/p>\n\n\n\n<p><strong>Regis Dudena<\/strong>, secret\u00e1rio de Pr\u00eamios e Apostas da SPA, se manifestou por nota oficial: \u201cEssa foi a forma que encontramos de n\u00e3o aguardar at\u00e9 janeiro para come\u00e7ar a separar o joio do trigo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje, 17, a Secretaria de Pr\u00eamios e Apostas (SPA), vinculada ao Minist\u00e9rio da Fazenda, publicou, no Di\u00e1rio Oficial da Uni\u00e3o (DOU), a Portaria n\u00ba 1.475, proibindo o funcionamento de sites [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":33857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3666],"tags":[3713,3644,3946,3889,3870,5817,6426],"class_list":["post-33856","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regulamento","tag-apostas-brasil","tag-apostas-esportivas","tag-ministerio-da-fazenda","tag-regulamentacao-das-apostas","tag-regulamentacao-das-apostas-esportivas-no-brasil","tag-secretaria-de-premios-e-apostas","tag-spa"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=33856"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33856\/revisions"}],"predecessor-version":[{"id":33871,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/33856\/revisions\/33871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/33857"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=33856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=33856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=33856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}