{"id":35139,"date":"2024-10-18T14:25:21","date_gmt":"2024-10-18T17:25:21","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=35139"},"modified":"2024-10-18T14:44:55","modified_gmt":"2024-10-18T17:44:55","slug":"cassinos-podem-gerar-mais-10-milhoes-empregos","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/cassinos-podem-gerar-mais-10-milhoes-empregos\/","title":{"rendered":"Legaliza\u00e7\u00e3o de cassinos f\u00edsicos pode gerar mais de 10 milh\u00f5es de empregos, diz presidente do IDT-CEMA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O presidente do <strong>Instituto de Desenvolvimento e Turismo (IDT-CEMA)<\/strong>, <strong>Bruno Omori<\/strong>, participou de uma audi\u00eancia com o Minist\u00e9rio do Turismo e com a Secretaria Nacional de Pol\u00edticas de Turismo nesta segunda-feira, 14, para discutir os impactos da Lei 2.234\/2022, que legaliza cassinos f\u00edsicos e bingos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Omori destacou o impacto positivo com a aprova\u00e7\u00e3o da lei e frisou o potencial de gerar mais de 10 milh\u00f5es de empregos no setor de turismo no pa\u00eds, com inje\u00e7\u00e3o de investimentos nacionais e internacionais superiores a US$ 70 bilh\u00f5es na macroeconomia. O presidente tamb\u00e9m relembrou que a entrada de cassinos geraria \u201cbilh\u00f5es em impostos\u201d para os cofres p\u00fablicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo da reuni\u00e3o foi mostrar as oportunidades na cria\u00e7\u00e3o de pontos de vendas, investimentos em hotelaria, restaurantes, parques tem\u00e1ticos, trazendo ainda mais movimenta\u00e7\u00e3o tur\u00edstica para o Brasil.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">O que diz o ministro do Turismo sobre cassinos f\u00edsicos<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Em setembro, o ministro do Turismo, <strong><a href=\"https:\/\/sbcnoticias.com\/br\/celso-sabino-preve-turismo-com-cassinos-fisicos\/\" target=\"_blank\" rel=\"noreferrer noopener\">Celso Sabino<\/a><\/strong>, em reuni\u00e3o com membros do G20, deixou claro que essa Lei dos Cassinos deve trazer mais visibilidade ao turismo brasileiro, j\u00e1 que deve \u201cmovimentar a cultura, a gastronomia e trazer mais turistas estrangeiros\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cResorts-cassinos s\u00e3o projetos que empregam muitos recursos para sua implanta\u00e7\u00e3o. [\u2026] O projeto \u00e9 adequado e vai ajudar os brasileiros a se movimentarem pelo pa\u00eds e a atrair mais visitantes estrangeiros.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A ideia \u00e9 que a constru\u00e7\u00e3o dos cassinos incentive a cria\u00e7\u00e3o de polos tur\u00edsticos que fujam do \u00f3bvio. \u201cN\u00e3o vamos buscar instalar um resort desses num grande centro urbano que j\u00e1 possui grande visita\u00e7\u00e3o. Vamos buscar afastar um pouco para fazer com que novos polos tur\u00edsticos surjam\u201d, disse o ministro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente do Instituto de Desenvolvimento e Turismo (IDT-CEMA), Bruno Omori, participou de uma audi\u00eancia com o Minist\u00e9rio do Turismo e com a Secretaria Nacional de Pol\u00edticas de Turismo nesta [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":35140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3666],"tags":[7144,8500,5645],"class_list":["post-35139","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regulamento","tag-cassino-fisico","tag-cassinos-fisicos-no-brasil","tag-idt-cema"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/35139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=35139"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/35139\/revisions"}],"predecessor-version":[{"id":35142,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/35139\/revisions\/35142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/35140"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=35139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=35139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=35139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}