{"id":36922,"date":"2024-12-30T10:02:00","date_gmt":"2024-12-30T13:02:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=36922"},"modified":"2024-12-30T10:04:26","modified_gmt":"2024-12-30T13:04:26","slug":"fazenda-divulga-instrucao-normativa-habilitacao-siscoaf","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/fazenda-divulga-instrucao-normativa-habilitacao-siscoaf\/","title":{"rendered":"Fazenda divulga Instru\u00e7\u00e3o Normativa que orienta habilita\u00e7\u00e3o SISCOAF para operadores de apostas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda <\/strong>(SPA\/MF) divulgou hoje, 30, a <strong><a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/instrucao-normativa-spa\/mf-n-4-de-27-de-dezembro-de-2024-604396013\" target=\"_blank\" rel=\"noreferrer noopener\">Instru\u00e7\u00e3o Normativa SPA\/MF n\u00ba4<\/a><\/strong>, que disp\u00f5e sobre a solicita\u00e7\u00e3o de habilita\u00e7\u00e3o para uso do <strong>Sistema de Controle de Atividades Financeiras <\/strong>(Siscoaf) por parte de agentes operadores autorizados a explorar a modalidade lot\u00e9rica de apostas de quota fixa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo \u00e9 viabilizar o encaminhamento das comunica\u00e7\u00f5es que tratam o inciso II do art.11 da Lei n\u00ba 9613\/1998, e os arts. 27 a 29 da Portaria SPA\/MF n\u00ba 1143\/2024, que versam sobre <strong>Preven\u00e7\u00e3o \u00e0 Lavagem de Dinheiro, ao Financiamento do Terrorismo e ao Financiamento da Prolifera\u00e7\u00e3o de Armas de Destrui\u00e7\u00e3o em Massa<\/strong> (LD\/FTP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o documento, a solicita\u00e7\u00e3o de habilita\u00e7\u00e3o para uso do Siscoaf \u00e9 de responsabilidade do agente operador de apostas, e o prazo para realizar a solicita\u00e7\u00e3o \u00e9 de at\u00e9 dez dias ap\u00f3s a data de publica\u00e7\u00e3o, no <strong>Di\u00e1rio Oficial da Uni\u00e3o<\/strong> (DOU), do instrumento que autoriza o agente operador a explorar a modalidade lot\u00e9rica de apostas de quota fixa em \u00e2mbito nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A comunica\u00e7\u00e3o de n\u00e3o ocorr\u00eancia dos ind\u00edcios de LD\/FTP deve ser encaminhada \u00e0 SPA por meio do <strong>Sistema de Gest\u00e3o de Apostas<\/strong> (SIGAP) ou outro canal criado e informado pela SPA at\u00e9 o \u00faltimo dia \u00fatil de janeiro do ano subsequente ao ano em que n\u00e3o houve ocorr\u00eancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O documento, assinado por <strong>Regis<\/strong> <strong>Dudena<\/strong>, entra em vigor hoje, 30 de dezembro de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF) divulgou hoje, 30, a Instru\u00e7\u00e3o Normativa SPA\/MF n\u00ba4, que disp\u00f5e sobre a solicita\u00e7\u00e3o de habilita\u00e7\u00e3o para uso do Sistema [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":36923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3666],"tags":[3644,3953,3742,191,3660,3889],"class_list":["post-36922","post","type-post","status-publish","format-standard","has-post-thumbnail","category-regulamento","tag-apostas-esportivas","tag-apostas-online","tag-cassinos-online","tag-igaming","tag-jogos-online","tag-regulamentacao-das-apostas"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/36922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=36922"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/36922\/revisions"}],"predecessor-version":[{"id":36925,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/36922\/revisions\/36925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/36923"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=36922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=36922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=36922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}