{"id":38746,"date":"2025-03-27T10:19:27","date_gmt":"2025-03-27T13:19:27","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=38746"},"modified":"2025-03-27T10:23:50","modified_gmt":"2025-03-27T13:23:50","slug":"sbc-summit-rio-entrevista-iraja-abreu-2025","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/sbc-summit-rio-entrevista-iraja-abreu-2025\/","title":{"rendered":"SBC Summit Rio 2025: senador Iraj\u00e1 revela perspectivas e insights sobre ind\u00fastria de apostas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">No<strong> <\/strong><a href=\"https:\/\/sbcnoticias.com\/br\/soft2bet-entrevista-sbc-summit-rio-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SBC Summit Rio 2025<\/strong><\/a>, que aconteceu entre os dias 25 e 27 de fevereiro, no Riocentro, no Rio de Janeiro, o senador <strong>Iraj\u00e1 Abreu<\/strong> (PSD-TO) conversou com o<em> SBC Not\u00edcias Brasil<\/em> sobre a ind\u00fastria nacional de apostas e o futuro do mercado ap\u00f3s a legaliza\u00e7\u00e3o de cassinos no pa\u00eds.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A entrevista abordou quest\u00f5es envolvendo o setor on-line, a legaliza\u00e7\u00e3o de cassinos f\u00edsicos no Brasil e o pr\u00f3prio evento da SBC &#8211; o primeiro evento de apostas e de jogos ap\u00f3s o in\u00edcio da vig\u00eancia do mercado regulamentado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O senador comentou, ainda, o <a href=\"https:\/\/sbcnoticias.com\/br\/loterj-suspensa-operacao-ambito-nacional\/\" target=\"_blank\" rel=\"noreferrer noopener\">caso<\/a> da <strong>Loteria Estadual do Rio de Janeiro (LOTERJ)<\/strong>, que n\u00e3o poder\u00e1 mais fornecer licen\u00e7as para empresas operarem no \u00e2mbito nacional &#8211; essas marcas poder\u00e3o atuar apenas dentro do estado do Rio de Janeiro.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o senador, a regulamenta\u00e7\u00e3o dos jogos on-line ser\u00e1 uma \u201cgrande escola\u201d e \u201cum bom exemplo\u201d para a legaliza\u00e7\u00e3o de cassinos f\u00edsicos no pa\u00eds. Iraj\u00e1 destacou que tanto as institui\u00e7\u00f5es envolvidas no desenvolvimento da ind\u00fastria quanto o Governo Federal est\u00e3o mais maduros para entender como o mercado realmente funciona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cE o mercado, como um todo [&#8230;], j\u00e1 digere isso [a ind\u00fastria] com mais naturalidade. Porque, realmente, existia um certo preconceito, como se isso fosse uma atividade criminosa ou que fosse algo de errado, e as pessoas est\u00e3o entendendo que n\u00e3o &#8211; \u00e9 uma atividade como qualquer outra, que precisa ser legalizada, regulada, fiscalizada e depurada\u201d, concluiu Iraj\u00e1.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"ilrG6J0U-4I\"><iframe loading=\"lazy\" title=\"Senador Iraj\u00e1 Abreu analisa cen\u00e1rio pol\u00edtico para legaliza\u00e7\u00e3o dos Cassinos F\u00edsicos\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/ilrG6J0U-4I?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption class=\"wp-element-caption\"><em>Entrevista do SBC Not\u00edcias Brasil com o senador Iraj\u00e1 Abreu (PSD-TO) no SBC Summit Rio 2025 no YouTube<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O SBC Not\u00edcias Brasil tamb\u00e9m conversou com <strong>Carolina Yumi<\/strong>, secret\u00e1ria adjunta da <strong>Secretaria de Pr\u00eamios e Apostas (SPA)<\/strong> do <strong>Minist\u00e9rio da Fazenda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>O link da entrevista est\u00e1 dispon\u00edvel <\/em><a href=\"https:\/\/sbcnoticias.com\/br\/reflexoes-regulamentacao-carolina-yumi-spa\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>aqui<\/em><\/a><em>.\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No SBC Summit Rio 2025, que aconteceu entre os dias 25 e 27 de fevereiro, no Riocentro, no Rio de Janeiro, o senador Iraj\u00e1 Abreu (PSD-TO) conversou com o SBC [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":38756,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,8892],"tags":[3644,4828,1036,191,7281,1140,9140,4320,6426],"class_list":["post-38746","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-destacado","tag-apostas-esportivas","tag-cassinos-fisicos","tag-entrevista","tag-igaming","tag-iraja-abreu","tag-loterj","tag-mercado-brasileiro-de-apostas-on-line","tag-sbc-summit-rio","tag-spa"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/38746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=38746"}],"version-history":[{"count":3,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/38746\/revisions"}],"predecessor-version":[{"id":38755,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/38746\/revisions\/38755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/38756"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=38746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=38746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=38746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}