{"id":43358,"date":"2025-11-12T12:48:35","date_gmt":"2025-11-12T15:48:35","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=43358"},"modified":"2025-11-12T12:52:00","modified_gmt":"2025-11-12T15:52:00","slug":"7k-mirassol-100-aniversario","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/7k-mirassol-100-aniversario\/","title":{"rendered":"Centen\u00e1rio: 7K celebra anivers\u00e1rio do Mirassol"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O <strong>Mirassol<\/strong>, clube patrocinado pela <strong>7K<\/strong>, celebrou o 100\u00ba anivers\u00e1rio no \u00faltimo domingo, 9. Para comemorar esse marco, a operadora do <strong>Grupo Ana Gaming<\/strong> realizou ativa\u00e7\u00f5es para os torcedores presentes na partida contra o <strong>Palmeiras<\/strong>, no Est\u00e1dio Municipal Jos\u00e9 Maria de Campos Maia, em S\u00e3o Paulo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 7K entregou bandeira de mais de 240 metros quadrados \u00e0 torcida e montou est\u00fadio com flash tattoo dentro do est\u00e1dio para atender os f\u00e3s, oferecendo diferentes op\u00e7\u00f5es de tatuagens relacionadas ao clube.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nickolas Tadeu Ribeiro de Campos<\/strong>, fundador e presidente do Conselho da Ana Gaming, disse: \u201c\u00c9 motivo de imensa alegria para n\u00f3s participar desse momento t\u00e3o glorioso da hist\u00f3ria do clube. Estamos h\u00e1 quase tr\u00eas anos juntos e tem sido um tempo de conquistas, aprendizados e muito sucesso para ambas as partes\u201d.\u00a0<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"440\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa8e96b63.png\" alt=\"\" class=\"wp-image-43362\" style=\"width:315px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa8e96b63.png 750w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa8e96b63-300x176.png 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa8e96b63-716x420.png 716w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa8e96b63-696x408.png 696w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: 7K<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">\u201cTemos grande confian\u00e7a no trabalho realizado pela diretoria do Mirassol, com seriedade, credibilidade e pensamento estrat\u00e9gico. Ser\u00e1 um dia muito especial para o clube e, por isso, queremos participar ativamente, promovendo a\u00e7\u00f5es para celebrar junto \u00e0 sua apaixonada torcida, que tem feito uma grande festa e levado o time a grandes resultados dentro de campo\u201d, concluiu Campos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em comunicado oficial, a 7K destacou que a parceria com o Mirassol come\u00e7ou em 2022, quando o time disputou a S\u00e9rie C do Campeonato Brasileiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDe l\u00e1 para c\u00e1, o \u2018Le\u00e3o Caipira\u2019 tem vivido o melhor momento de sua hist\u00f3ria\u201d, afirmou a operadora. Neste ano, o Mirassol estreou na S\u00e9rie A e est\u00e1 em busca de uma vaga na <strong>Copa Libertadores<\/strong>.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hulk \u00e9 homenageado pela 7K<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"961\" height=\"991\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db.png\" alt=\"\" class=\"wp-image-43360\" style=\"width:234px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db.png 961w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db-291x300.png 291w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db-768x792.png 768w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db-407x420.png 407w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6914aa2b390db-696x718.png 696w\" sizes=\"auto, (max-width: 961px) 100vw, 961px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: 7K<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Na primeira semana deste m\u00eas, a 7K homenageou o atacante <strong>Hulk<\/strong>, do <strong>Atl\u00e9tico-MG<\/strong>, que chegou aos 500 gols na carreira profissional ap\u00f3s marcar um dos pontos da vit\u00f3ria do time na partida contra o <strong>Bahia<\/strong> pelo Brasileir\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 7K, como <a href=\"https:\/\/sbcnoticias.com\/br\/7k-jogador-hulk-embaixador-brasil\/\">patrocinadora oficial do jogador<\/a>, afirmou que o presentearia com bra\u00e7adeira, camisa e fl\u00e2mula personalizadas e carta \u201cpela marca hist\u00f3rica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A parceria entre a operadora e o jogador come\u00e7ou em mar\u00e7o deste ano. A colabora\u00e7\u00e3o prev\u00ea a participa\u00e7\u00e3o de Hulk em campanhas publicit\u00e1rias e em conte\u00fados digitais, refor\u00e7ando o jogo respons\u00e1vel e a conscientiza\u00e7\u00e3o sobre as boas pr\u00e1ticas do mercado de apostas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c9 uma marca que ratifica a carreira vitoriosa do Hulk e o coloca como um dos principais nomes do futebol mundial. \u00c9 um atleta de prest\u00edgio, de carreira consolidada e vencedora. Ele nunca fugiu da responsabilidade &#8211; sempre teve consci\u00eancia da sua import\u00e2ncia para a equipe e, dentro de campo, tem feito hist\u00f3ria, acumulando anos de alta performance e novos recordes. O perfil dele \u00e9 extremamente alinhado \u00e0 empresa, pautado pelo comprometimento e pela entrega de qualidade&#8221;, comentou <strong>Marco T\u00falio<\/strong>, CEO da Ana Gaming.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"K1xjDyQmY-c\"><iframe loading=\"lazy\" title=\"HULK \u00e9 o novo embaixador da 7K!\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/K1xjDyQmY-c?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption class=\"wp-element-caption\"><em>Divulga\u00e7\u00e3o oficial de Hulk como embaixador da 7K no YouTube<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, recentemente, anunciou o canal \u201cVoc\u00ea Sabia?\u201d, apresentado por&nbsp; <strong>Lukas Marques<\/strong> e <strong>Daniel Molo<\/strong>, como embaixador da marca, conforme reportado pela <a href=\"https:\/\/sbcnoticias.com\/br\/7k-anuncia-voce-sabia-como-embaixador\/\">jornalista <strong>Ana Maria<\/strong><\/a> no dia 3 de novembro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA chegada do \u2018Voc\u00ea Sabia?\u2019 refor\u00e7a o nosso compromisso em transformar o setor de iGaming em um espa\u00e7o de confian\u00e7a, transpar\u00eancia e divers\u00e3o. Lukas e Daniel inspiram milh\u00f5es de pessoas com um conte\u00fado que educa e entret\u00e9m ao mesmo tempo. Essa sinergia \u00e9 perfeita para o que a 7K acredita: unir tecnologia e prop\u00f3sito, levando conhecimento e emo\u00e7\u00e3o para todos os p\u00fablicos\u201d, afirmou Campos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Acompanhe os maiores e mais importantes acontecimentos do mercado brasileiro de apostas online regularmente. Todas as segundas, ter\u00e7as e quintas-feiras, o portal envia para voc\u00ea um resumo com as \u00faltimas not\u00edcias da ind\u00fastria do Brasil. Para ter acesso \u00e0 newsletter do SBC Not\u00edcias Brasil, inscreva-se&nbsp;<a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Mirassol, clube patrocinado pela 7K, celebrou o 100\u00ba anivers\u00e1rio no \u00faltimo domingo, 9. Para comemorar esse marco, a operadora do Grupo Ana Gaming realizou ativa\u00e7\u00f5es para os torcedores presentes [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":43364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664],"tags":[9051,9077,8756,3642,9857,8400],"class_list":["post-43358","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","tag-7k","tag-ana-gaming","tag-atletico-mg","tag-futebol","tag-mirassol","tag-parceria-de-apostas"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=43358"}],"version-history":[{"count":3,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43358\/revisions"}],"predecessor-version":[{"id":43368,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43358\/revisions\/43368"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/43364"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=43358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=43358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=43358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}