{"id":43540,"date":"2025-11-25T09:30:00","date_gmt":"2025-11-25T12:30:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=43540"},"modified":"2025-11-24T15:37:28","modified_gmt":"2025-11-24T18:37:28","slug":"ibia-silvia-paleari-integridade-apostas-brasil","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/ibia-silvia-paleari-integridade-apostas-brasil\/","title":{"rendered":"Silvia Paleari, IBIA: Brasil avan\u00e7a na integridade esportiva"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Com a <strong><a href=\"https:\/\/sbcnoticias.com\/br\/gastos-brasileiros-copa-do-mundo-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Copa do Mundo<\/a><\/strong> se aproximando no pr\u00f3ximo ano e o <a href=\"https:\/\/sbcnoticias.com\/br\/gastos-brasileiros-copa-do-mundo-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brasil<\/a> entrando em um per\u00edodo de aten\u00e7\u00e3o m\u00e1xima no cen\u00e1rio esportivo, o tema da <a href=\"https:\/\/sbcnoticias.com\/br\/giovanni-rocco-comenta-manipulacao-futebol\/\" target=\"_blank\" rel=\"noreferrer noopener\">manipula\u00e7\u00e3o de resultados<\/a> ganha destaque.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/ibia.bet\/team-member-profile\/16\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/ibia.bet\/team-member-profile\/16\" rel=\"noreferrer noopener\">Silvia Paleari<\/a><\/strong>, head de Assuntos Corporativos da<strong> International Betting Integrity Association (<a href=\"https:\/\/sbcnoticias.com\/br\/ibia-alerta-manipulacao-brasileirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">IBIA<\/a>)<\/strong>, comentou que o pa\u00eds vive um momento decisivo para consolidar mecanismos de integridade. Para Paleari, o avan\u00e7o da regulamenta\u00e7\u00e3o, a expans\u00e3o do monitoramento independente e a integra\u00e7\u00e3o de mais operadores ao sistema licenciado oferecem maior visibilidade sobre atividades suspeitas do mercado brasileiro.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em entrevista ao<em> SBC Not\u00edcias Brasil<\/em>, Paleari refor\u00e7ou que esse fortalecimento ser\u00e1 essencial para proteger competi\u00e7\u00f5es nacionais e internacionais &#8211; como a Copa do Mundo -, garantindo mais transpar\u00eancia e capacidade de resposta diante de poss\u00edveis amea\u00e7as \u00e0 integridade esportiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Ao longo dos \u00faltimos 12 a 24 meses, a IBIA observou aumento ou redu\u00e7\u00e3o nos alertas vindos do mercado brasileiro? Quais fatores-chave voc\u00ea acredita que est\u00e3o impulsionando essa tend\u00eancia?<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6924a4dfa1757.jpg\" alt=\"\" class=\"wp-image-43542\" style=\"width:236px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6924a4dfa1757.jpg 400w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6924a4dfa1757-300x300.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2025\/11\/image-6924a4dfa1757-150x150.jpg 150w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\">Silvia Paleari<br>Cr\u00e9dito: IBIA<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: O Brasil continua sendo um dos mercados mais monitorados pela IBIA, e o que estamos observando n\u00e3o \u00e9 uma deteriora\u00e7\u00e3o da integridade, mas sim uma maior visibilidade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 medida que mais operadores migram para o modelo regulamentado no pa\u00eds e passam a integrar o monitoramento independente, o volume e a qualidade dos dados dispon\u00edveis para a IBIA aumentaram substancialmente. Essa maior visibilidade naturalmente resulta na detec\u00e7\u00e3o e no reporte de mais casos &#8211; algo que consideramos um sinal positivo de amadurecimento do sistema.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A verdadeira hist\u00f3ria aqui \u00e9 que a regulamenta\u00e7\u00e3o est\u00e1 funcionando. Ela est\u00e1 iluminando \u00e1reas antes obscuras e permitindo a\u00e7\u00f5es mais r\u00e1pidas e baseadas em evid\u00eancias por parte das autoridades brasileiras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Quais tipos de competi\u00e7\u00f5es no Brasil tendem a gerar mais alertas &#8211; ligas regionais, s\u00e9ries nacionais ou esportes de nicho? H\u00e1 algum padr\u00e3o espec\u00edfico identificado em atividades de apostas suspeitas?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: A maioria dos alertas no Brasil est\u00e1 relacionada ao futebol, o que reflete o tamanho e a profundidade do ecossistema do esporte no pa\u00eds, e n\u00e3o um problema excepcional de integridade.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Plataforma Global de Monitoramento e Alertas (Global MAP) da IBIA mostra que o n\u00famero de alertas caiu no trimestre mais recente, e nossa coopera\u00e7\u00e3o com entidades esportivas e autoridades regulat\u00f3rias continua se fortalecendo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alertas ocasionais em outros esportes permanecem isolados e devem ser vistos como um sinal de melhoria na cobertura do monitoramento, e n\u00e3o como um risco ampliado. O que importa \u00e9 que o sistema est\u00e1 funcionando &#8211; problemas s\u00e3o identificados cedo, compartilhados rapidamente e tratados pelas autoridades competentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Como o cen\u00e1rio de integridade no Brasil se compara a mercados mais maduros, como o do Reino Unido ou dos Estados Unidos, e a outros mercados emergentes da Am\u00e9rica Latina?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: O Brasil est\u00e1 avan\u00e7ando rapidamente e j\u00e1 adotou medidas que alguns mercados maduros levaram mais tempo para implementar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A exig\u00eancia de que operadores licenciados integrem um \u00f3rg\u00e3o independente de monitoramento de integridade est\u00e1 alinhada \u00e0s melhores pr\u00e1ticas globais e vai al\u00e9m do que vemos em muitos mercados novos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em compara\u00e7\u00e3o com a regi\u00e3o mais ampla da Am\u00e9rica Latina, a estrutura e a escala do Brasil o posicionam para se tornar refer\u00eancia regional em integridade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Em quais \u00e1reas o Brasil se destaca e em quais ainda precisa avan\u00e7ar na detec\u00e7\u00e3o e resposta a irregularidades relacionadas \u00e0s apostas? H\u00e1 pr\u00e1ticas internacionais que a IBIA considera priorit\u00e1rias para o pa\u00eds adotar?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: O Brasil est\u00e1 \u00e0 frente de muitos mercados emergentes ao exigir monitoramento independente e ao engajar de forma proativa com o ecossistema de integridade. Isso oferece \u00e0s autoridades visibilidade imediata sobre grande parte do mercado &#8211; algo que levou mais tempo para ser alcan\u00e7ado em jurisdi\u00e7\u00f5es mais antigas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 medida que a capacidade de fiscaliza\u00e7\u00e3o cresce, o Brasil deve continuar avan\u00e7ando em dire\u00e7\u00e3o aos padr\u00f5es observados em ambientes regulat\u00f3rios mais estabelecidos. As principais boas pr\u00e1ticas incluem manter canais robustos de coopera\u00e7\u00e3o entre operadores, entidades esportivas e reguladores, e garantir respostas r\u00e1pidas e coordenadas quando surgem problemas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, um aspecto importante em que o Brasil deve focar &#8211; e que est\u00e1 intimamente ligado \u00e0 integridade das apostas esportivas &#8211; \u00e9 reduzir a dist\u00e2ncia em rela\u00e7\u00e3o ao mercado ilegal. Esse segmento representa uma amea\u00e7a \u00e0 integridade, pois atividades suspeitas n\u00e3o s\u00e3o reportadas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo do regulador brasileiro \u00e9 trazer o m\u00e1ximo poss\u00edvel de consumidores para o ambiente regulamentado, e n\u00e3o afast\u00e1-los. Isso garantir\u00e1 que os mecanismos de integridade estabelecidos funcionem em sua melhor forma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Como voc\u00ea avalia o atual n\u00edvel de coopera\u00e7\u00e3o entre operadores, federa\u00e7\u00f5es esportivas e autoridades no Brasil? A IBIA identifica alguma lacuna de dados ou de infraestrutura que ainda prejudique a detec\u00e7\u00e3o eficaz de manipula\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: A coopera\u00e7\u00e3o no Brasil se aprofundou significativamente \u00e0 medida que o arcabou\u00e7o regulat\u00f3rio tomou forma, e a IBIA tem estado diretamente envolvida nesse avan\u00e7o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a abertura do mercado no in\u00edcio deste ano, agimos rapidamente para formalizar nossa colabora\u00e7\u00e3o com as principais institui\u00e7\u00f5es respons\u00e1veis por proteger a integridade do esporte brasileiro. Firmamos Memorandos de Entendimento (MoUs) tanto com a <strong>Secretaria de Pr\u00eamios e Apostas (<a href=\"https:\/\/sbcnoticias.com\/br\/forum-ibia-se-reune-ministerio-da-fazenda\/\" target=\"_blank\" rel=\"noreferrer noopener\">SPA<\/a>)<\/strong>, do <strong>Minist\u00e9rio da Fazenda<\/strong>, quanto com o <strong><a href=\"https:\/\/sbcnoticias.com\/br\/me-acordo-ibia-monitorar-apostas-esportivas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Minist\u00e9rio do Esporte<\/a><\/strong>, estabelecendo canais estruturados de troca de informa\u00e7\u00f5es e de a\u00e7\u00e3o coordenada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destaco que essa coopera\u00e7\u00e3o n\u00e3o \u00e9 apenas formal &#8211; ela \u00e9 operacional. No in\u00edcio deste ano, a IBIA organizou a primeira sess\u00e3o t\u00e9cnica de treinamento em integridade para autoridades brasileiras, reunindo representantes da SPA e do Minist\u00e9rio da Fazenda, entre outros, para fortalecer o entendimento sobre manipula\u00e7\u00e3o relacionada a apostas e como responder de maneira eficaz. Essa atua\u00e7\u00e3o pr\u00e1tica \u00e9 crucial em um mercado da escala do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As organiza\u00e7\u00f5es esportivas tamb\u00e9m est\u00e3o cada vez mais atentas \u00e0 import\u00e2ncia da integridade das apostas para proteger suas competi\u00e7\u00f5es. Embora a capacidade varie entre os esportes, a visibilidade proporcionada pelo monitoramento est\u00e1 ajudando as federa\u00e7\u00f5es a compreender onde est\u00e3o os riscos e como agir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O desafio ainda \u00e9 garantir que essa coopera\u00e7\u00e3o crescente se traduza em respostas operacionais r\u00e1pidas e coordenadas sempre que um alerta for emitido. Pap\u00e9is bem definidos, procedimentos acordados e capacidade investigativa dedicada ser\u00e3o essenciais. O arcabou\u00e7o e a inten\u00e7\u00e3o j\u00e1 existem, e o pr\u00f3ximo passo \u00e9 a plena operacionaliza\u00e7\u00e3o para que os alertas resultem em a\u00e7\u00f5es r\u00e1pidas, coordenadas e consistentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Brasil est\u00e1 avan\u00e7ando, e as <a href=\"https:\/\/sbcnoticias.com\/br\/ibia-iugu-parceria-integridade-esportiva\/\" target=\"_blank\" rel=\"noreferrer noopener\">parcerias da IBIA<\/a> nos posicionam para desempenhar um papel central nesse desenvolvimento &#8211; alinhado \u00e0 <a href=\"https:\/\/sbcnoticias.com\/br\/ibia-mission-2030-integridade-esportiva\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mission 2030<\/a>, que prioriza colabora\u00e7\u00e3o mais profunda, monitoramento mais robusto e preven\u00e7\u00e3o mais eficaz em todos os mercados regulamentados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Quais s\u00e3o as expectativas da IBIA para o mercado brasileiro de apostas esportivas at\u00e9 2026, especialmente em rela\u00e7\u00e3o ao crescimento, \u00e0 maturidade regulat\u00f3ria e aos padr\u00f5es de integridade?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: At\u00e9 2026, esperamos que o Brasil esteja entre os mercados regulamentados mais relevantes do mundo, tanto em tamanho quanto em integridade. De acordo com a H2 Gambling Capital, nossa parceira de dados, o mercado brasileiro de apostas e de jogos online deve alcan\u00e7ar cerca de 20 milh\u00f5es de jogadores \u00fanicos ativos at\u00e9 2026. A previs\u00e3o tamb\u00e9m indica que as apostas esportivas representar\u00e3o aproximadamente 45% do segmento de jogos online no pa\u00eds em 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nossa expectativa \u00e9 que o Brasil deixe de ser apenas um mercado emergente de r\u00e1pido crescimento e se torne refer\u00eancia em como combinar expans\u00e3o, prote\u00e7\u00e3o ao consumidor e integridade esportiva. Esse \u00e9 exatamente o resultado que a IBIA deseja &#8211; um mercado regulamentado amplo e vibrante, sustentado por um arcabou\u00e7o de alta integridade. Para que isso se concretize, medidas firmes contra a oferta n\u00e3o regulamentada s\u00e3o essenciais.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aumentos potenciais de tributa\u00e7\u00e3o tamb\u00e9m representam um risco claro &#8211; impostos mais altos podem empurrar consumidores para operadores n\u00e3o regulamentados, reduzindo a visibilidade e enfraquecendo os mecanismos de integridade. Manter o mercado competitivo e bem canalizado \u00e9 fundamental &#8211; e esse direcionamento est\u00e1 alinhado \u00e0 estrat\u00e9gia Mission 2030 da IBIA, que enfatiza monitoramento mais robusto, preven\u00e7\u00e3o eficaz e colabora\u00e7\u00e3o mais profunda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, esperamos que esse avan\u00e7o n\u00e3o seja prejudicado por medidas que levem operadores licenciados a operar offshore, uma vez que isso reduziria a supervis\u00e3o e amea\u00e7aria os avan\u00e7os obtidos na integridade que o Brasil trabalhou tanto para construir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: Quais indicadores ou m\u00e9tricas a IBIA pretende utilizar para avaliar o progresso do Brasil at\u00e9 2026?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: Vamos analisar uma combina\u00e7\u00e3o de indicadores quantitativos e sinais mais amplos de maturidade do sistema. O volume e a tend\u00eancia dos alertas continuam sendo m\u00e9tricas fundamentais, mas \u00e9 igualmente importante observar como esses alertas s\u00e3o tratados e se resultam em investiga\u00e7\u00f5es completas e san\u00e7\u00f5es adequadas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cobertura tamb\u00e9m \u00e9 um fator cr\u00edtico. A efic\u00e1cia do monitoramento aumenta toda vez que um operador regulamentado entra no sistema, ent\u00e3o, n\u00f3s iremos acompanhar a propor\u00e7\u00e3o do mercado que opera dentro do ambiente licenciado e o n\u00edvel geral de canaliza\u00e7\u00e3o, j\u00e1 que \u00e9 essencial para manter a visibilidade sobre a atividade de apostas.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m vamos monitorar os tempos de resposta e a qualidade da coordena\u00e7\u00e3o entre os envolvidos, pois esses indicadores operacionais muitas vezes revelam mais sobre a maturidade de um sistema do que os n\u00fameros brutos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, avaliaremos sinais mais amplos do mercado, como o n\u00edvel de confian\u00e7a dos stakeholders, os resultados das a\u00e7\u00f5es de fiscaliza\u00e7\u00e3o e a consist\u00eancia da coopera\u00e7\u00e3o entre entidades esportivas, reguladores e operadores. Esses fatores, em conjunto, mostram se as medidas de integridade est\u00e3o realmente incorporadas ao funcionamento di\u00e1rio do mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SBC Not\u00edcias Brasil: A IBIA pretende publicar algum relat\u00f3rio ou dado espec\u00edfico sobre o Brasil em 2025\/2026 que ajude a acompanhar esses avan\u00e7os? Quais insights as pessoas podem esperar encontrar nesses materiais?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Silvia Paleari<\/strong>: A IBIA continuar\u00e1 publicando seus <a href=\"https:\/\/sbcnoticias.com\/br\/ibia-apostas-suspeitas-primeiro-trimestre-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\">relat\u00f3rios trimestrais<\/a> e o relat\u00f3rio anual de integridade, que seguem sendo as an\u00e1lises baseadas em evid\u00eancias mais completas sobre atividades suspeitas de apostas no mercado regulamentado global.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses relat\u00f3rios apresentam dados claros e objetivos &#8211; n\u00famero de alertas registrados, esportes envolvidos, distribui\u00e7\u00e3o regional e as san\u00e7\u00f5es aplicadas por entidades esportivas e autoridades ap\u00f3s as investiga\u00e7\u00f5es. Os documentos tamb\u00e9m destacam tend\u00eancias de longo prazo, mudan\u00e7as nos padr\u00f5es de alerta e compara\u00e7\u00f5es ano a ano que ajudam os stakeholders a entender como os riscos est\u00e3o evoluindo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O que os stakeholders podem esperar \u00e9 que os n\u00fameros do Brasil continuem aparecendo de forma consistente em nossas publica\u00e7\u00f5es, incluindo o detalhamento por modalidade esportiva e sua posi\u00e7\u00e3o comparativa na Am\u00e9rica Latina e no cen\u00e1rio global.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 medida que a cobertura de monitoramento no pa\u00eds se expande e mais operadores ingressam no ambiente licenciado, esses relat\u00f3rios oferecer\u00e3o um retrato cada vez mais abrangente do cen\u00e1rio de integridade, garantindo transpar\u00eancia e contribuindo para pol\u00edticas p\u00fablicas baseadas em evid\u00eancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A transpar\u00eancia \u00e9 um compromisso central da Mission 2030, e nossos dados publicados continuar\u00e3o desempenhando um papel essencial no fortalecimento dos padr\u00f5es de integridade no Brasil e no mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a Copa do Mundo se aproximando no pr\u00f3ximo ano e o Brasil entrando em um per\u00edodo de aten\u00e7\u00e3o m\u00e1xima no cen\u00e1rio esportivo, o tema da manipula\u00e7\u00e3o de resultados ganha [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":43543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,8892],"tags":[3644,4399,3642,718,3771],"class_list":["post-43540","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-destacado","tag-apostas-esportivas","tag-copa-do-mundo","tag-futebol","tag-ibia","tag-integridade-esportiva"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=43540"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43540\/revisions"}],"predecessor-version":[{"id":43544,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/43540\/revisions\/43544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/43543"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=43540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=43540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=43540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}