{"id":44593,"date":"2026-02-05T14:43:35","date_gmt":"2026-02-05T17:43:35","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=44593"},"modified":"2026-02-05T14:45:59","modified_gmt":"2026-02-05T17:45:59","slug":"hugo-motta-comenta-pl-proibe-propaganda-apostas","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/hugo-motta-comenta-pl-proibe-propaganda-apostas\/","title":{"rendered":"Hugo Motta comenta sobre PL que pro\u00edbe propagandas de apostas: \u201cA gente tem que ir com muita prud\u00eancia nisso\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Hugo Motta <\/strong>(Republicanos-PB), presidente da <strong>C\u00e2mara dos Deputados<\/strong>, afirmou em entrevista ao portal <em><a href=\"https:\/\/www.poder360.com.br\/poder-congresso\/motta-pede-cautela-sobre-proibicao-de-propaganda-de-bets\/\" data-type=\"link\" data-id=\"https:\/\/www.poder360.com.br\/poder-congresso\/motta-pede-cautela-sobre-proibicao-de-propaganda-de-bets\/\" target=\"_blank\" rel=\"noreferrer noopener\">Poder360<\/a><\/em> nesta quinta-feira, 5, que a C\u00e2mara deve ter \u201ccautela\u201d antes de avan\u00e7ar com propostas que pro\u00edbem a publicidade de apostas no <strong>Brasil<\/strong>. Motta deu seu parecer um dia ap\u00f3s a <strong>Comiss\u00e3o de Ci\u00eancia e Tecnologia (CCT)<\/strong>\u00a0do\u00a0<strong>Senado Federal<\/strong> aprovar um <a href=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">projeto de lei<\/a> que pro\u00edbe publicidade, patroc\u00ednio e promo\u00e7\u00e3o de apostas esportivas e de jogos online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA gente tem que ir com muita prud\u00eancia nisso\u201d, afirmou Motta, ao ser questionado pelo <em>Poder360<\/em>. O presidente da C\u00e2mara dos Deputados tamb\u00e9m afirmou que n\u00e3o h\u00e1 consenso entre os l\u00edderes partid\u00e1rios acerca do tema, antes de reconhecer que o assunto deve ganhar espa\u00e7o no <strong>Congresso Nacional<\/strong> nas pr\u00f3ximas semanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Motta, uma proibi\u00e7\u00e3o total de publicidade de apostas pode causar efeitos colaterais graves no setor do esporte, especialmente no <a href=\"https:\/\/sbcnoticias.com\/br\/michel-mattar-fia-patrocinios-brasileirao\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/michel-mattar-fia-patrocinios-brasileirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">futebol brasileiro e seus clubes<\/a>, j\u00e1 que afetaria acordos de patroc\u00ednio. Atualmente, por exemplo, 12 dos 20 clubes do <strong>Campeonato Brasileiro &#8211; S\u00e9rie A (Brasileir\u00e3o S\u00e9rie A)<\/strong> possuem uma casa de apostas como patrocinadora m\u00e1ster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEu acho que hoje voc\u00ea tem [publicidade e patroc\u00ednio das bets] tanto nos meios de comunica\u00e7\u00e3o como no pr\u00f3prio futebol, eventos. [H\u00e1] uma depend\u00eancia grande desse setor que ajuda a patrocinar, financiar. Isso tamb\u00e9m \u00e9 importante levar em considera\u00e7\u00e3o. Eu vejo que talvez o rem\u00e9dio n\u00e3o seja esse [proibir toda a publicidade de apostas] at\u00e9 porque \u00e9 uma atividade legalizada, assim como \u00e9 legalizada a bebida, o fumo no Brasil. Isso a\u00ed [apostas] tamb\u00e9m \u00e9 legal por lei. Est\u00e3o pagando impostos. Ent\u00e3o, o abuso talvez n\u00e3o esteja a\u00ed [a publicidade das apostas]. Esteja em combater o ilegal, fazer essa constru\u00e7\u00e3o mais de maneira arrazoada\u201d, concluiu Motta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s o <a href=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/165405\" data-type=\"link\" data-id=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/165405\" target=\"_blank\" rel=\"noopener\">projeto de lei n\u00ba 3.563\/2024<\/a>, de autoria original do senador <strong>Randolfe Rodrigues<\/strong> (PT-AP) e altera\u00e7\u00e3o feita pela relatora Damares Alves (Republicanos-DF), ter sido aprovado na CCT na quarta-feira, 3, ele segue para an\u00e1lise da\u00a0<strong>Comiss\u00e3o de Constitui\u00e7\u00e3o, Justi\u00e7a e Cidadania (CCJ)<\/strong> do Senado Federal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de Motta, o <a href=\"https:\/\/sbcnoticias.com\/br\/ibjr-reage-pl-proibe-publicidade-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/ibjr-reage-pl-proibe-publicidade-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Instituto Brasileiro de Jogo Respons\u00e1vel<\/strong> <strong>(IBJR)<\/strong><\/a> tamb\u00e9m se manifestou acerca do projeto de lei, afirmando que a proibi\u00e7\u00e3o de propagandas de apostas enfraqueceria o mercado regulado e fortaleceria o mercado clandestino. Atualmente, a publicidade de apostas \u00e9 regularizada por meio da <a href=\"https:\/\/sbcnoticias.com\/br\/lula-lei-apostas-esportivas-jogos-on-line\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/lula-lei-apostas-esportivas-jogos-on-line\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lei de Apostas<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do\u00a0<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hugo Motta (Republicanos-PB), presidente da C\u00e2mara dos Deputados, afirmou em entrevista ao portal Poder360 nesta quinta-feira, 5, que a C\u00e2mara deve ter \u201ccautela\u201d antes de avan\u00e7ar com propostas que pro\u00edbem [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,26,8892,3666],"tags":[3644,3731,10030,10028,3675,8291,3676],"class_list":["post-44593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-brasil","category-destacado","category-regulamento","tag-apostas-esportivas","tag-camara-dos-deputados","tag-hugo-motta","tag-pl-no-3-563-2024","tag-projeto-de-lei","tag-regulacao","tag-senado-federal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=44593"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44593\/revisions"}],"predecessor-version":[{"id":44595,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44593\/revisions\/44595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/44594"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=44593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=44593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=44593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}