{"id":44828,"date":"2026-02-20T10:00:00","date_gmt":"2026-02-20T13:00:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=44828"},"modified":"2026-02-19T16:38:01","modified_gmt":"2026-02-19T19:38:01","slug":"atfx-torneio-poker-sbc-summit-rio-2026","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/atfx-torneio-poker-sbc-summit-rio-2026\/","title":{"rendered":"ATFX patrocina o Torneio de Poker do SBC Summit Rio 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/www.atfx.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ATFX<\/strong><\/a>, corretora fintech global multi-premiada, foi confirmada como patrocinadora oficial do Torneio de Poker do <a href=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SBC Summit Rio 2026<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento exclusivo para convidados acontece na ter\u00e7a-feira, <strong>3 de mar\u00e7o<\/strong>, no <strong>Rio Beach Club<\/strong>, durante a Festa de Abertura oficial do SBC Summit Rio. O credenciamento come\u00e7a \u00e0s 16h30, e o torneio ser\u00e1 realizado das 17h \u00e0s 20h.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao todo, <strong>100<\/strong> jogadores colocar\u00e3o sua estrat\u00e9gia \u00e0 prova. No melhor estilo high stakes, a disputa ser\u00e1 no formato \u201cwinner-takes-all\u201d: o \u00faltimo jogador da mesa ser\u00e1 coroado campe\u00e3o e receber\u00e1 um pr\u00eamio exclusivo oferecido pela ATFX.<br><br>O grande campe\u00e3o levar\u00e1 para casa um iPhone 17 novinho, al\u00e9m de US$ 1.000 (aproximadamente R$ 5.225) creditados em uma conta de trading da ATFX. O segundo colocado receber\u00e1 US$ 800 (aproximadamente R$ 4.180) em conta de trading, enquanto o terceiro lugar receber\u00e1 US$ 500 (aproximadamente R$ 2.612). Al\u00e9m disso, os tr\u00eas primeiros colocados tamb\u00e9m ganhar\u00e3o um kit premium de poker da ATFX.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Paul<\/strong> <strong>Mills<\/strong>, diretor de Eventos da<strong> SBC<\/strong>, comentou sobre o torneio: \u201cO poker \u00e9 um dos jogos mais populares do mundo. Exige disciplina, estrat\u00e9gia e a capacidade de manter a calma sob press\u00e3o. A parceria com a ATFX aconteceu de forma natural. Poucas marcas entendem t\u00e3o bem risco calculado, timing e pensamento estrat\u00e9gico quanto a ATFX\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os participantes ser\u00e3o selecionados por meio de um processo exclusivo por convite, conduzido pela SBC e pela ATFX. As vagas ser\u00e3o destinadas a executivos s\u00eaniores, parceiros e stakeholders estrat\u00e9gicos que estar\u00e3o presentes no SBC Summit Rio 2026. A sele\u00e7\u00e3o priorizar\u00e1 tomadores de decis\u00e3o, garantindo um n\u00edvel elevado de competi\u00e7\u00e3o, alinhado ao perfil estrat\u00e9gico e relacional do torneio. Interessados poder\u00e3o manifestar interesse por meio deste <a href=\"https:\/\/info.sbcevents.com\/rio26-poker-interest\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>formul\u00e1rio<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fundada no Reino Unido em 2017, a ATFX se consolidou como uma das principais corretoras fintech do mundo, com presen\u00e7a f\u00edsica em <strong>24 localidades distribu\u00eddas por cinco continentes<\/strong>. A empresa opera sob <strong>nove licen\u00e7as regulat\u00f3rias ao redor do mundo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconhecida por seu ecossistema completo de trading, a ATFX oferece negocia\u00e7\u00e3o de CFDs em forex, \u00edndices, commodities, a\u00e7\u00f5es e outros ativos, al\u00e9m das plataformas MT4 e MT5, spreads competitivos e ferramentas avan\u00e7adas. Atendendo clientes de varejo, profissionais e institucionais globalmente, a empresa \u00e9 pautada por tecnologia, precis\u00e3o e execu\u00e7\u00e3o disciplinada \u2014 qualidades igualmente valorizadas tanto no trading competitivo quanto na mesa de poker.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Line Peteri<\/strong>, VP de Parcerias Estrat\u00e9gicas da <strong>ATFX<\/strong>, declarou: \u201cO SBC Summit Rio re\u00fane tomadores de decis\u00e3o que atuam em ambientes de alta press\u00e3o e foco em performance, assim como no universo do trading. O torneio cria um ambiente onde estrat\u00e9gia e gest\u00e3o de risco n\u00e3o s\u00e3o apenas discutidas, mas vivenciadas, tornando-se uma plataforma natural para a ATFX se conectar com l\u00edderes da ind\u00fastria de jogos de forma leve e descontra\u00edda.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O patroc\u00ednio da ATFX ao Torneio de Poker do SBC Summit Rio 2026 refor\u00e7a a forte sinergia entre o poker e o mercado de forex. Ambos exigem gest\u00e3o disciplinada de risco, vis\u00e3o estrat\u00e9gica e tomada de decis\u00e3o assertiva \u2014 caracter\u00edsticas que definem tanto traders de sucesso quanto jogadores de alto n\u00edvel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O Torneio de Poker do SBC Summit Rio 2026 integra a programa\u00e7\u00e3o oficial do <a href=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SBC Summit Rio 2026<\/strong><\/a>, que acontece de 3 a 5 de mar\u00e7o de 2026, no Riocentro, no Rio de Janeiro. O evento contar\u00e1 com dois dias de <a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/agenda\/\" target=\"_blank\" rel=\"noreferrer noopener\">confer\u00eancia<\/a>, uma ampla \u00e1rea de <a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/exhibitors\/\" target=\"_blank\" rel=\"noreferrer noopener\">exposi\u00e7\u00e3o<\/a>, diversos eventos de <a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/networking\/\" target=\"_blank\" rel=\"noreferrer noopener\">networking<\/a> e dois summits paralelos dedicados: o <a href=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/affiliate-leaders-summit\/\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/affiliate-leaders-summit\/\" target=\"_blank\" rel=\"noreferrer noopener\">Affiliate Leaders Summit<\/a> e o <a href=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/payment-expert-summit\/\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/payment-expert-summit\/\" target=\"_blank\" rel=\"noreferrer noopener\">Payment Expert Summit<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Os ingressos para o SBC Summit Rio 2026 est\u00e3o dispon\u00edveis&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/ticket-options\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>aqui<\/em><\/a><em>.&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/for-operators\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Operadores<\/em><\/a><em>&nbsp;e&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/for-affiliates\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>afiliados<\/em><\/a><em>&nbsp;podem solicitar ingressos VIP gratuitamente.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Garanta seu lugar no evento com o&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/vip-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>VIP Event Pass<\/em><\/a><em>&nbsp;por R$ 3 mil e tenha acesso a todas as confer\u00eancias, ao piso de exposi\u00e7\u00e3o, aos eventos exclusivos de networking e ao festival gastron\u00f4mico. Para grupos de tr\u00eas ou mais pessoas, adquira o Group Pass Discount e economize R$ 1.200 por ingresso.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>O evento conta, ainda, com o\u00a0<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/expo-plus-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Expo+ Pass<\/em><\/a><em>, dispon\u00edvel por R$ 500, que garante acesso integral ao piso de exposi\u00e7\u00e3o e \u00e0s confer\u00eancias, al\u00e9m do\u00a0<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/expo-only-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Expo Only Pass<\/em><\/a><em>, gratuito, que oferece acesso restrito ao piso de exposi\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><br><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do\u00a0<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>.\u00a0A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ATFX, corretora fintech global multi-premiada, foi confirmada como patrocinadora oficial do Torneio de Poker do SBC Summit Rio 2026. O evento exclusivo para convidados acontece na ter\u00e7a-feira, 3 de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,8892],"tags":[10053,1170,4320,10049],"class_list":["post-44828","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-destacado","tag-atfx","tag-sbc-events","tag-sbc-summit-rio","tag-sbc-summit-rio-2026"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=44828"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44828\/revisions"}],"predecessor-version":[{"id":44832,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44828\/revisions\/44832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/44831"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=44828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=44828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=44828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}