{"id":44974,"date":"2026-02-26T14:20:58","date_gmt":"2026-02-26T17:20:58","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=44974"},"modified":"2026-02-26T14:26:18","modified_gmt":"2026-02-26T17:26:18","slug":"sbc-parceria-ibjr-jogo-responsavel","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/sbc-parceria-ibjr-jogo-responsavel\/","title":{"rendered":"SBC anuncia parceria estrat\u00e9gica com o IBJR para promover o jogo respons\u00e1vel no Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>SBC<\/strong> anunciou uma nova parceria estrat\u00e9gica com o <strong>Instituto Brasileiro de Jogo Respons\u00e1vel (IBJR)<\/strong> antes do <a href=\"https:\/\/sbcevents.com\/en\/sbc-summit-rio\/?promo=sbcmrktng-5L7BsCNr&amp;utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=RIO-26&amp;utm_content=en-search-brand-rioeventname-ad1&amp;tr=true&amp;utm_term=sbc%20summit%20rio&amp;utm_campaign=EN+%7C+SBC+Summit+Rio+2026+%7C+Brand+%26+Event+name+%7C+Search+%7C+WBS1651&amp;utm_source=adwords&amp;utm_medium=ppc&amp;hsa_acc=9027956280&amp;hsa_cam=23205075759&amp;hsa_grp=187493774363&amp;hsa_ad=781825221986&amp;hsa_src=g&amp;hsa_tgt=kwd-2449891548438&amp;hsa_kw=sbc%20summit%20rio&amp;hsa_mt=p&amp;hsa_net=adwords&amp;hsa_ver=3&amp;gad_source=1&amp;gad_campaignid=23205075759&amp;gbraid=0AAAAABJMA8sYuj5AT3Nfv0ywVyOpz88HG&amp;gclid=CjwKCAiAtLvMBhB_EiwA1u6_Pg8NNXp6dyTxvrF1EodwWYgwY7FmjRRM1SeCC1KhUaLcDHaO1BaT4RoCz9MQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SBC Summit Rio<\/strong><\/a>, alinhando o evento a uma das principais vozes na defini\u00e7\u00e3o de padr\u00f5es de jogo respons\u00e1vel no Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento acontecer\u00e1 de 3 a 5 de mar\u00e7o de 2026, no Riocentro, no Rio de Janeiro, reunindo milhares de participantes, incluindo operadores, fornecedores e reguladores, para explorar o futuro do mercado rec\u00e9m-regulamentado do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/ibjr.org.br\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>IBJR<\/strong><\/a> foi fundado em 2023, ap\u00f3s o avan\u00e7o do Brasil na cria\u00e7\u00e3o de um mercado regulamentado de iGaming e apostas esportivas. A organiza\u00e7\u00e3o representa as principais empresas de apostas do pa\u00eds e tem como compromisso a constru\u00e7\u00e3o de um ecossistema de apostas justo, sustent\u00e1vel e respons\u00e1vel. No centro da sua miss\u00e3o est\u00e1 o combate ao mercado ilegal, ao mesmo tempo em que promove o jogo respons\u00e1vel para jogadores e empresas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A entidade re\u00fane algumas das marcas internacionais e brasileiras mais influentes entre seus membros, incluindo <strong>bet365<\/strong>, <strong>BetMGM<\/strong>, <strong>Betsson<\/strong> <strong>Group<\/strong>, <strong>Entain (Sportingbet)<\/strong>, <strong>Flutter Brazil (Betnacional e Betfair)<\/strong>, <strong>Kaizen Gaming (Betano)<\/strong> e <strong>KTO<\/strong>, al\u00e9m de muitos outros nomes de destaque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Andre Gelfi<\/strong>, diretor, membro do conselho e cofundador do IBJR, celebrou o acordo como um passo importante para o mercado regulamentado, afirmando: \u201cEsta parceria \u00e9 extremamente importante n\u00e3o apenas do ponto de vista institucional, mas tamb\u00e9m para refor\u00e7ar o trabalho que temos realizado na promo\u00e7\u00e3o de um ecossistema de apostas esportivas e jogos online ainda mais robusto, sustent\u00e1vel e respons\u00e1vel\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstar ao lado de um parceiro t\u00e3o relevante como a SBC nos conecta a outras iniciativas e plataformas de di\u00e1logo com os principais stakeholders do setor, autoridades p\u00fablicas e a sociedade\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por sua vez, a parceria da SBC com o IBJR leva uma das principais vozes regulat\u00f3rias do Brasil ao SBC Summit Rio, fortalecendo o foco do evento em jogo respons\u00e1vel e governan\u00e7a de mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Luc\u00eda Mouri\u00f1o<\/strong>, VP Relationships LATAM da SBC, afirmou: \u201cA parceria com o IBJR nos permite alinhar o SBC Summit Rio a uma das principais organiza\u00e7\u00f5es que est\u00e3o moldando o cen\u00e1rio regulamentado de apostas no Brasil. \u00c0 medida que o mercado amadurece, \u00e9 essencial que as discuss\u00f5es sobre sustentabilidade, compliance e integridade permane\u00e7am no centro das aten\u00e7\u00f5es\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO IBJR desempenha um papel crucial no combate ao mercado ilegal, na manuten\u00e7\u00e3o de altos padr\u00f5es de prote\u00e7\u00e3o ao jogador e na garantia de que seus membros estejam em conformidade com as regulamenta\u00e7\u00f5es. Trabalhar juntos assegura que essas prioridades estejam refletidas no mais alto n\u00edvel de di\u00e1logo do setor durante o nosso summit\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O SBC Summit Rio reunir\u00e1 a ind\u00fastria de apostas e jogos do Brasil ao longo de tr\u00eas dias de networking, conte\u00fado educacional e desenvolvimento de neg\u00f3cios. Mais de 150 dos principais palestrantes do setor no Brasil compartilhar\u00e3o insights em trilhas de confer\u00eancia dedicadas, incluindo Lideran\u00e7a, Inova\u00e7\u00e3o Tecnol\u00f3gica e Marketing, al\u00e9m de summits especializados como o Affiliate Leaders Summit e o Payment Expert Summit, oferecendo an\u00e1lises focadas nos ecossistemas de afiliados e pagamentos do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A \u00e1rea de exposi\u00e7\u00e3o contar\u00e1 com expositores nas \u00e1reas de jogo respons\u00e1vel, prote\u00e7\u00e3o ao jogador e compliance, oferecendo insights pr\u00e1ticos sobre as bases do mercado regulamentado do Brasil. Ao reunir operadores e stakeholders do setor, o SBC Summit Rio atua como uma plataforma central para fortalecer um ecossistema sustent\u00e1vel e focado no jogador.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Os ingressos para o SBC Summit Rio 2026 est\u00e3o dispon\u00edveis&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/ticket-options\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>aqui<\/em><\/a><em>.&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/for-operators\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Operadores<\/em><\/a><em>&nbsp;e&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/for-affiliates\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>afiliados<\/em><\/a><em>&nbsp;podem solicitar ingressos VIP gratuitamente.&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Garanta seu lugar no evento com o&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/vip-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>VIP Event Pass<\/em><\/a><em>&nbsp;por R$ 3 mil e tenha acesso a todas as confer\u00eancias, ao piso de exposi\u00e7\u00e3o, aos eventos exclusivos de networking e ao festival gastron\u00f4mico. Para grupos de tr\u00eas ou mais pessoas, adquira o Group Pass Discount e economize R$ 1.200 por ingresso.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>O evento conta, ainda, com o&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/expo-plus-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Expo+ Pass<\/em><\/a><em>, dispon\u00edvel por R$ 500, que garante acesso integral ao piso de exposi\u00e7\u00e3o e \u00e0s confer\u00eancias, al\u00e9m do&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-rio\/expo-only-pass\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Expo Only Pass<\/em><\/a><em>, gratuito, que oferece acesso restrito ao piso de exposi\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>.&nbsp;A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A SBC anunciou uma nova parceria estrat\u00e9gica com o Instituto Brasileiro de Jogo Respons\u00e1vel (IBJR) antes do SBC Summit Rio, alinhando o evento a uma das principais vozes na defini\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,26,8892],"tags":[89,3805,3744,588,1170,4320],"class_list":["post-44974","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-brasil","category-destacado","tag-brasil","tag-ibjr","tag-jogo-responsavel","tag-sbc","tag-sbc-events","tag-sbc-summit-rio"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=44974"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44974\/revisions"}],"predecessor-version":[{"id":44977,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44974\/revisions\/44977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/44975"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=44974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=44974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=44974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}