{"id":44989,"date":"2026-02-27T11:16:35","date_gmt":"2026-02-27T14:16:35","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=44989"},"modified":"2026-02-27T13:33:48","modified_gmt":"2026-02-27T16:33:48","slug":"hugo-motta-cide-bets-pl-antifaccao","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/hugo-motta-cide-bets-pl-antifaccao\/","title":{"rendered":"Hugo Motta diz que CIDE-Bets foi retirada de PL Antifac\u00e7\u00e3o por conta de \u201cincompatibilidade t\u00e9cnica\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Hugo Motta<\/strong> (Republicanos-PB), atual presidente da <strong>C\u00e2mara dos Deputados<\/strong>, explicou, em entrevista ao rep\u00f3rter <strong>Igor Gadelha<\/strong> do <em><a href=\"https:\/\/www.metropoles.com\/colunas\/igor-gadelha\/nao-ha-protecao-as-bets-na-camara-diz-motta-sobre-pl-antifaccao\" data-type=\"link\" data-id=\"https:\/\/www.metropoles.com\/colunas\/igor-gadelha\/nao-ha-protecao-as-bets-na-camara-diz-motta-sobre-pl-antifaccao\" target=\"_blank\" rel=\"noopener\">Metr\u00f3poles<\/a><\/em>, por que a cria\u00e7\u00e3o da <strong>Contribui\u00e7\u00e3o de Interven\u00e7\u00e3o no Dom\u00ednio Econ\u00f4mico<\/strong> sobre apostas online (<strong>CIDE-Bets<\/strong>) foi retirada do texto final do Projeto de Lei n\u00ba 5.582\/2025, conhecido como <a href=\"https:\/\/sbcnoticias.com\/br\/camara-aprova-pl-antifaccao-sem-cide-bets\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/camara-aprova-pl-antifaccao-sem-cide-bets\/\" target=\"_blank\" rel=\"noreferrer noopener\">PL Antifac\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este novo tributo, que taxaria em 15% os dep\u00f3sitos feitos por pessoas f\u00edsicas em plataformas de apostas esportivas e seria destinado ao combate ao crime organizado, foi originalmente adicionado ao texto do PL Antifac\u00e7\u00e3o pelo relator do projeto no <strong>Senado Federal<\/strong>, <strong>Alessandro Vieira<\/strong> (MDB-SE). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora o Senado tenha <a href=\"https:\/\/sbcnoticias.com\/br\/senado-cide-bets-posicionamento-ibjr-anjl\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/senado-cide-bets-posicionamento-ibjr-anjl\/\" target=\"_blank\" rel=\"noreferrer noopener\">aprovado<\/a> a medida em dezembro, a cria\u00e7\u00e3o da CIDE-Bets foi exclu\u00edda do PL Antifac\u00e7\u00e3o em vota\u00e7\u00e3o na C\u00e2mara dos Deputados esta semana. O relator do projeto na C\u00e2mara, <strong>Guilherme Derrite<\/strong> (PP-SP), tamb\u00e9m era a favor da CIDE-Bets, mas seu pr\u00f3prio partido optou por retirar o tributo por meio de um destaque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <em>Metr\u00f3poles<\/em> perguntou a Motta se a remo\u00e7\u00e3o da CIDE-Bets n\u00e3o era contradit\u00f3ria, j\u00e1 que o imposto serviria para financiar o combate ao crime organizado, uma pauta frequente na C\u00e2mara dos Deputados. Motta, por\u00e9m, disse que o tributo \u00e9 invi\u00e1vel e afirmou que a C\u00e2mara n\u00e3o  protege as casas de apostas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA cria\u00e7\u00e3o da CIDE-Bets vai justamente no sentido daquilo que n\u00f3s n\u00e3o podemos ficar contra, que \u00e9 um financiamento mais forte da seguran\u00e7a p\u00fablica. A \u00fanica coisa que precisa ser honesta ao se colocar \u00e9 a viabilidade de se cobrar esse imposto. \u00c9 importante dizer que a C\u00e2mara dos Deputados aprovou no final do ano um aumento da cobran\u00e7a de impostos das &#8216;bets&#8217;. Ent\u00e3o n\u00e3o h\u00e1 prote\u00e7\u00e3o \u00e0s &#8216;bets&#8217; na C\u00e2mara dos Deputados. Esse discurso n\u00e3o \u00e9 verdadeiro\u201d, respondeu Motta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente da C\u00e2mara dos Deputados afirmou, em seguida, que a inclus\u00e3o da CIDE-Bets por parte do Senado Federal contraria o pr\u00f3prio <strong>Minist\u00e9rio da Fazenda<\/strong> <strong>(MF)<\/strong>, cuja equipe t\u00e9cnica chamou a operacionaliza\u00e7\u00e3o do imposto de \u201cimposs\u00edvel\u201d, de acordo com Motta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Motta, os c\u00e1lculos de arrecada\u00e7\u00e3o com a CIDE-Bets \u2014 15% de R$ 30 bilh\u00f5es \u2014 eram uma \u201cestimativa irreal\u201d e explicou que o imposto acabaria favorecendo o mercado clandestino de apostas: \u201cSe voc\u00ea cobra uma al\u00edquota que \u00e9 imposs\u00edvel de ser paga por um setor, voc\u00ea favorece a ilegalidade e a consolida\u00e7\u00e3o dentro do setor de quem n\u00e3o paga imposto algum. Hoje n\u00f3s temos o governo arrecadando; temos como ter o compartilhamento e a transfer\u00eancia de dados sobre o apostador \u2014 voc\u00ea tem que colocar o seu CPF \u2014, voc\u00ea n\u00e3o sonega mais\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEnt\u00e3o, de maneira alguma n\u00f3s quisemos proteger as &#8216;bets&#8217;; n\u00f3s enfrentamos o debate com honestidade e a decis\u00e3o da C\u00e2mara foi retirar essa cobran\u00e7a que foi colocada no Senado justamente por incompatibilidade t\u00e9cnica, por j\u00e1 termos aumentado o imposto das &#8216;bets&#8217; e para n\u00e3o favorecer a ilegalidade num setor que est\u00e1 come\u00e7ando a se legalizar\u201d, finalizou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No come\u00e7o de fevereiro, Motta tamb\u00e9m indicou ser <a href=\"https:\/\/sbcnoticias.com\/br\/hugo-motta-comenta-pl-proibe-propaganda-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/hugo-motta-comenta-pl-proibe-propaganda-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">contra<\/a> proibir propagandas de apostas em todo o territ\u00f3rio nacional, ap\u00f3s um projeto de lei ter sido <a href=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" rel=\"noreferrer noopener\">aprovado<\/a> pela <strong>Comiss\u00e3o de Ci\u00eancia e Tecnologia (CCT)<\/strong>&nbsp;do&nbsp;Senado Federal. Na \u00e9poca, Motta alegou que os l\u00edderes partid\u00e1rios na C\u00e2mara dos Deputados n\u00e3o haviam chegado a um consenso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cria\u00e7\u00e3o da CIDE-Bets deve tramitar em outro projeto, j\u00e1 que o Senado Federal havia dado parecer favor\u00e1vel ao imposto. Deputados da ala governista tamb\u00e9m expressaram descontentamento ap\u00f3s o tributo ficar de fora do PL Antifac\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ministro da Justi\u00e7a comenta sobre pr\u00f3ximos passos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wellington Lima<\/strong>, <a href=\"https:\/\/www.gov.br\/planalto\/pt-br\/acompanhe-o-planalto\/notas-oficiais\/notas-a-imprensa\/wellington-cesar-lima-e-silva-assume-ministerio-da-justica-e-seguranca-publica\" target=\"_blank\" rel=\"noreferrer noopener\">ministro da Justi\u00e7a<\/a> desde janeiro deste ano, afirmou que h\u00e1 possibilidade de apresenta\u00e7\u00e3o de novas propostas voltadas ao combate ao crime organizado, ap\u00f3s a <strong>C\u00e2mara dos Deputados <\/strong>aprovar o PL Antifac\u00e7\u00e3o sem a CIDE-Bets.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lima informou que o <strong>Minist\u00e9rio da Justi\u00e7a<\/strong> visa apoiar um novo PL que foque exclusivamente em tributos e em outras duas iniciativas, embora n\u00e3o tenha detalhado quais seriam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs &#8216;bets&#8217; s\u00e3o uma alternativa, e existem muitas proposi\u00e7\u00f5es discutidas de outras origens. O problema \u00e9 que cada origem pensada tem que ser cotejada com o sentido de responsabilidade fiscal\u201d, disse o ministro<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lima tamb\u00e9m afirmou que \u00e9 necess\u00e1rio tratar o tema como prioridade e que, se for necess\u00e1rio, pode haver flexibiliza\u00e7\u00e3o ou supera\u00e7\u00e3o de certos limites \u2014 provavelmente legais, institucionais ou operacionais \u2014 para enfrentar a quest\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>.&nbsp;A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hugo Motta (Republicanos-PB), atual presidente da C\u00e2mara dos Deputados, explicou, em entrevista ao rep\u00f3rter Igor Gadelha do Metr\u00f3poles, por que a cria\u00e7\u00e3o da Contribui\u00e7\u00e3o de Interven\u00e7\u00e3o no Dom\u00ednio Econ\u00f4mico sobre [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":44994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,26,8892,3666],"tags":[3644,3731,9987,10030,3729,10062],"class_list":["post-44989","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-brasil","category-destacado","category-regulamento","tag-apostas-esportivas","tag-camara-dos-deputados","tag-cide-bets","tag-hugo-motta","tag-imposto","tag-pl-antifaccao"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=44989"}],"version-history":[{"count":4,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44989\/revisions"}],"predecessor-version":[{"id":45007,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/44989\/revisions\/45007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/44994"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=44989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=44989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=44989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}