{"id":45664,"date":"2026-04-02T11:45:30","date_gmt":"2026-04-02T14:45:30","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=45664"},"modified":"2026-04-02T11:45:44","modified_gmt":"2026-04-02T14:45:44","slug":"spa-autoriza-logame-a-suprimir-b2xbet","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/spa-autoriza-logame-a-suprimir-b2xbet\/","title":{"rendered":"SPA determina mudan\u00e7a na explora\u00e7\u00e3o das marcas da Logame"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF)<\/strong> publicou hoje, 2, no <strong>Di\u00e1rio Oficial da Uni\u00e3o (DOU)<\/strong>, a <a href=\"https:\/\/in.gov.br\/web\/dou\/-\/portaria-spa\/mf-n-931-de-1-de-abril-de-2026-697095303\" target=\"_blank\" rel=\"noreferrer noopener\">Portaria SPA\/MF n\u00ba 931\/2026<\/a>. O documento altera a <a href=\"https:\/\/in.gov.br\/en\/web\/dou\/-\/portaria-spa\/mf-n-324-de-17-de-fevereiro-de-2025-613397608\" target=\"_blank\" rel=\"noreferrer noopener\">Portaria SPA\/MF n\u00ba 324\/2025<\/a>, que autoriza a opera\u00e7\u00e3o da <strong>Logame do Brasil Ltda.<\/strong> at\u00e9 31 de dezembro de 2029.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A empresa, que antes operava com tr\u00eas marcas, <strong>B2XBET<\/strong>, <strong>L\u00edder Bet<\/strong> e <strong>Geralbet<\/strong>, agora tem autoriza\u00e7\u00e3o para explorar o setor apenas com as duas \u00faltimas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A SPA utilizou sua compet\u00eancia legal, prevista no <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2023-2026\/2024\/decreto\/D11907.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Decreto n\u00ba 11.907\/2024<\/a> e nas Leis n\u00ba <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_Ato2015-2018\/2018\/Lei\/L13756.htm\" target=\"_blank\" rel=\"noreferrer noopener\">13.756\/2018<\/a> e n\u00ba <a href=\"https:\/\/www.planalto.gov.br\/ccivil_03\/_ato2023-2026\/2023\/lei\/l14790.htm\" target=\"_blank\" rel=\"noreferrer noopener\">14.790\/2023<\/a>, para implementar mudan\u00e7as na portaria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Logame continua a atuar nos segmentos esportivo e de jogos online, nas modalidades f\u00edsica e virtual, de acordo com a Portaria SPA\/MF n\u00ba 324\/2025.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SPA e Senacon lan\u00e7am curso online&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ontem, 2, o <em>SBC Not\u00edcias Brasil<\/em> comunicou o <a href=\"https:\/\/sbcnoticias.com\/br\/spa-senacon-curso-apostadores\/\" target=\"_blank\" rel=\"noreferrer noopener\">lan\u00e7amento do curso<\/a> \u201cDireitos dos consumidores-apostadores e as bets: al\u00e9m do jogo\u201d. A iniciativa foi desenvolvida pela <strong>Secretaria Nacional do Consumidor (Senacon)<\/strong>, do <strong>Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica (MJSP)<\/strong>, em parceria com a SPA.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O objetivo \u00e9 capacitar apostadores, ampliando o acesso a informa\u00e7\u00f5es e estimulando a conscientiza\u00e7\u00e3o sobre os direitos, riscos e limites no mercado de apostas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O conte\u00fado aborda desde conceitos b\u00e1sicos at\u00e9 quest\u00f5es mais amplas relacionadas ao setor, como a defini\u00e7\u00e3o das apostas de quota fixa, o funcionamento do mercado, jogo respons\u00e1vel e sa\u00fade mental e financeira.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SPA comenta apostas ilegais no Brasil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, recentemente, em entrevista ao jornal <em>O Globo<\/em>, <strong>Daniele Correa Cardoso<\/strong>, rec\u00e9m-nomeada secret\u00e1ria de Pr\u00eamios e Apostas do <strong>Minist\u00e9rio da Fazenda<\/strong>, <a href=\"https:\/\/sbcnoticias.com\/br\/daniele-cardoso-spa-comenta-sobre-sites-ilegais\/\">comentou o mercado ilegal<\/a> de apostas online do Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para Cardoso, o combate ao setor n\u00e3o regulado \u00e9 prioridade: \u201cEsse processo de combate ao ilegal, que muitas vezes opera at\u00e9 fora do pa\u00eds, \u00e9 de interesse das empresas legais e nosso tamb\u00e9m, porque, quando o cidad\u00e3o vai para o mercado ilegal, a tutela do estado \u00e9 mais dif\u00edcil. Se a op\u00e7\u00e3o do cidad\u00e3o for usar esse marcado para se entreter, ent\u00e3o, que ele v\u00e1 para o mercado legalizado, onde h\u00e1 obriga\u00e7\u00f5es e monitoramento\u201d.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer ouvir mais hist\u00f3rias como esta? Confira o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF) publicou hoje, 2, no Di\u00e1rio Oficial da Uni\u00e3o (DOU), a Portaria SPA\/MF n\u00ba 931\/2026. O documento altera a Portaria [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":45672,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,26,3666],"tags":[3644,3742,9363,3946,6426],"class_list":["post-45664","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-brasil","category-regulamento","tag-apostas-esportivas","tag-cassinos-online","tag-logame","tag-ministerio-da-fazenda","tag-spa"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=45664"}],"version-history":[{"count":2,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45664\/revisions"}],"predecessor-version":[{"id":45671,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45664\/revisions\/45671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/45672"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=45664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=45664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=45664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}