{"id":45824,"date":"2026-04-14T13:04:16","date_gmt":"2026-04-14T16:04:16","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=45824"},"modified":"2026-04-14T13:04:22","modified_gmt":"2026-04-14T16:04:22","slug":"casas-de-apostas-distanciam-futebol-brasileiro","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/casas-de-apostas-distanciam-futebol-brasileiro\/","title":{"rendered":"Casas de apostas se distanciam da elite do futebol brasileiro em 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Atualmente, 13 das 20 equipes do\u00a0<strong>Campeonato Brasileiro \u2013 S\u00e9rie A (Brasileir\u00e3o)<\/strong>\u00a0t\u00eam acordos de patroc\u00ednio m\u00e1ster com uma casa de apostas. A participa\u00e7\u00e3o do setor, ao menos na primeira divis\u00e3o do campeonato brasileiro de futebol, diminuiu em rela\u00e7\u00e3o a 2025, quando 18 clubes tinham uma casa de apostas como patrocinadora principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas o que explica esta mudan\u00e7a de estrat\u00e9gia do setor de apostas, que antes estava mais disposto a investir significativamente em clubes de futebol? O <em><a href=\"https:\/\/sportinsider.com.br\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sportinsider.com.br\/\" rel=\"noreferrer noopener\">Sport Insider<\/a><\/em>, ve\u00edculo especializado em neg\u00f3cios no esporte, entrevistou representantes de quatro casas de apostas para uma mat\u00e9ria especial publicada no jornal <em><a href=\"https:\/\/www.estadao.com.br\/esportes\/futebol\/exodo-das-bets-por-que-casas-de-apostas-decidiram-diversificar-investimentos-para-alem-do-futebol\/\" data-type=\"link\" data-id=\"https:\/\/www.estadao.com.br\/esportes\/futebol\/exodo-das-bets-por-que-casas-de-apostas-decidiram-diversificar-investimentos-para-alem-do-futebol\/\" target=\"_blank\" rel=\"noreferrer noopener\">Estad\u00e3o<\/a><\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos os interlocutores que conversaram com o <em>Sport Insider<\/em> falaram que houve uma busca por audi\u00eancia em \u201cnichos menos inflacionados e mais est\u00e1veis\u201d do que o futebol. As casas de apostas menores, em particular, sofreram com o aumento de impostos.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs empresas do setor est\u00e3o reagindo com bastante preocupa\u00e7\u00e3o ao aumento da carga tribut\u00e1ria. Na pr\u00e1tica, isso nos obriga a rever investimentos, especialmente no esporte, e tamb\u00e9m impacta a capacidade de ofertar, por exemplo, odds competitivas ao consumidor\u201d, disse <strong>Marco Tulio Oliveira<\/strong>, CEO da <strong><a href=\"https:\/\/sbcnoticias.com\/br\/ana-gaming-antonio-guerardi-cmo\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/ana-gaming-antonio-guerardi-cmo\/\" rel=\"noreferrer noopener\">Ana Gaming<\/a><\/strong>, holding que opera as marcas <strong>7K Bet<\/strong>, <strong>Cassino Bet<\/strong> e <strong>Vera Bet<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 7K Bet, inclusive, era patrocinadora m\u00e1ster do <strong>Santos<\/strong> at\u00e9 janeiro, mas ambas as partes optaram por <a href=\"https:\/\/sbcnoticias.com\/br\/santos-7k-encerram-patrocinio-master\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/santos-7k-encerram-patrocinio-master\/\" rel=\"noreferrer noopener\">rescindir<\/a> mutuamente o contrato antes do previsto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um dos baques financeiros sentidos pelo setor de apostas aconteceu ano passado, quando o presidente <strong>Luiz In\u00e1cio Lula da Silva<\/strong> (PT) sancionou a <strong><a href=\"https:\/\/sbcnoticias.com\/br\/lula-sanciona-impostos-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/lula-sanciona-impostos-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lei Complementar n\u00ba 224\/2025<\/a><\/strong>, aumentando de 12% para 15%, at\u00e9 2028, o valor do imposto sobre o <strong><a href=\"https:\/\/sbcnoticias.com\/br\/spa-primeiro-ano-regulamentacao-37-bilhoes-ggr\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/spa-primeiro-ano-regulamentacao-37-bilhoes-ggr\/\" target=\"_blank\" rel=\"noreferrer noopener\">GGR<\/a> <\/strong>(gross gaming revenue; receita bruta de jogos).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mercado ilegal de apostas tamb\u00e9m atrapalha<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e.jpg\" alt=\"Foto representando o mercado ilegal de apostas.\" class=\"wp-image-45829\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e.jpg 800w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-300x169.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-768x432.jpg 768w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-747x420.jpg 747w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-696x392.jpg 696w, https:\/\/sbcnoticias.com\/br\/uploads\/sites\/3\/sites\/3\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-638x359.jpg 638w, https:\/\/sbcnoticias.com\/br\/uploads\/sites\/3\/sites\/3\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-476x268.jpg 476w, https:\/\/sbcnoticias.com\/br\/uploads\/sites\/3\/sites\/3\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-286x161.jpg 286w, https:\/\/sbcnoticias.com\/br\/uploads\/sites\/3\/sites\/3\/sites\/3\/2026\/04\/Apostas-Ilegais-69de6516d827e-178x100.jpg 178w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: Shutterstock<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/sbcnoticias.com\/br\/caso-beto-louco-alerta-sites-apostas-ilegais\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/caso-beto-louco-alerta-sites-apostas-ilegais\/\" rel=\"noreferrer noopener\">mercado ilegal de apostas<\/a>, que opera sem autoriza\u00e7\u00e3o da <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda<\/strong> (<strong>SPA\/MF<\/strong>), tamb\u00e9m \u00e9 um fator que afasta investimentos maiores no futebol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para representantes da ind\u00fastria, a combina\u00e7\u00e3o entre o aumento de impostos e projetos de lei que visam estrangular o setor, como o PL que <a href=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/cct-aprova-pl-proibe-publicidade-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">pro\u00edbe publicidade de apostas<\/a> em todo o territ\u00f3rio nacional e o PL que visa <a href=\"https:\/\/sbcnoticias.com\/br\/senador-girao-quer-alterar-lei-de-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/senador-girao-quer-alterar-lei-de-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">proibir cashback, programas VIP e gamifica\u00e7\u00e3o<\/a>, fortalece apenas o mercado ilegal, que n\u00e3o paga impostos e n\u00e3o segue nenhuma das diretrizes de jogo respons\u00e1vel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente Lula tamb\u00e9m tem sido bastante <a href=\"https:\/\/sbcnoticias.com\/br\/lula-ameaca-fechar-casas-de-apostas\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/lula-ameaca-fechar-casas-de-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">cr\u00edtico<\/a> ao setor, sobretudo neste ano, o que aumenta este cen\u00e1rio de inseguran\u00e7a jur\u00eddica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cApesar da falta de divulga\u00e7\u00e3o p\u00fablica, o setor das apostas esportivas j\u00e1 paga vultuosos impostos acima de 30% do faturamento das empresas. Al\u00e9m disso, o segmento contribui para a sociedade com a gera\u00e7\u00e3o de empregos e o investimento de altas quantias no esporte nacional\u201d, <strong>Leonardo Henrique Roscoe Bessa<\/strong>, s\u00f3cio do <strong>Betlaw<\/strong> e consultor do Conselho Federal da <strong>Ordem dos Advogados do Brasil<\/strong> (<strong>OAB<\/strong>), disse para o <em>Sport Insider<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNeste momento, o principal ponto de aten\u00e7\u00e3o do governo brasileiro e tamb\u00e9m dos operadores deve ser o combate ao mercado ilegal, que apresenta incont\u00e1veis malef\u00edcios para todo ecossistema de betting e, especialmente, aos usu\u00e1rios\u201d, concluiu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A mandat\u00e1ria da SPA, <strong><a href=\"https:\/\/sbcnoticias.com\/br\/daniele-cardoso-spa-comenta-sobre-sites-ilegais\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/daniele-cardoso-spa-comenta-sobre-sites-ilegais\/\" target=\"_blank\" rel=\"noreferrer noopener\">Daniele Correa Cardoso<\/a><\/strong>, disse em entrevista recente que a pasta vai continuar combatendo o mercado ilegal. A SPA e a Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel) j\u00e1 bloquearam mais de 29 mil sites clandestinos desde 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O setor tamb\u00e9m viu com bons olhos a <strong><a href=\"https:\/\/sbcnoticias.com\/br\/lei-raul-jungmann-combate-crime-organizado\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/lei-raul-jungmann-combate-crime-organizado\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lei Raul Jungmann<\/a><\/strong>, que determina que bancos e institui\u00e7\u00f5es financeiras bloqueiem contas ligadas ao mercado ilegal de apostas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Em fevereiro, o SBC Not\u00edcias Brasil publicou uma entrevista com o professor <strong>Michel Fauze Mattar<\/strong>, da <strong>FIA Business School<\/strong>, sobre a redu\u00e7\u00e3o do investimento feito por casas de apostas no Brasileir\u00e3o. Voc\u00ea pode ler a entrevista <a href=\"https:\/\/sbcnoticias.com\/br\/michel-mattar-fia-patrocinios-brasileirao\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/michel-mattar-fia-patrocinios-brasileirao\/\" rel=\"noreferrer noopener\">aqui<\/a>.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer ouvir mais hist\u00f3rias como esta? Confira o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atualmente, 13 das 20 equipes do\u00a0Campeonato Brasileiro \u2013 S\u00e9rie A (Brasileir\u00e3o)\u00a0t\u00eam acordos de patroc\u00ednio m\u00e1ster com uma casa de apostas. A participa\u00e7\u00e3o do setor, ao menos na primeira divis\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":45828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,26],"tags":[3644,89,1519,3701,3642],"class_list":["post-45824","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-brasil","tag-apostas-esportivas","tag-brasil","tag-brasileirao","tag-esportes","tag-futebol"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=45824"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45824\/revisions"}],"predecessor-version":[{"id":45830,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45824\/revisions\/45830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/45828"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=45824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=45824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=45824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}