{"id":45897,"date":"2026-04-16T14:00:00","date_gmt":"2026-04-16T17:00:00","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=45897"},"modified":"2026-04-16T11:42:23","modified_gmt":"2026-04-16T14:42:23","slug":"endividamento-brasil-apostas","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/endividamento-brasil-apostas\/","title":{"rendered":"Endividamento das fam\u00edlias brasileiras: fatores por tr\u00e1s do aumento da inadimpl\u00eancia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O termo \u201cendividamento\u201d refere-se ao uso excessivo de cr\u00e9dito, enquanto \u201cendividado\u201d designa o indiv\u00edduo que se encontra nessa situa\u00e7\u00e3o. Mas o que, de fato, leva uma pessoa a gastar mais do que ganha?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, o sal\u00e1rio m\u00ednimo no Brasil \u00e9 de <a href=\"https:\/\/www.gov.br\/esocial\/pt-br\/noticias\/novo-salario-minimo-2026-veja-como-registrar-o-reajuste-no-esocial-domestico\" target=\"_blank\" rel=\"noreferrer noopener\">R$ 1.621<\/a>. No entanto, <a href=\"https:\/\/www.serasa.com.br\/imprensa\/custo-medio-de-vida-do-brasileiro\/\" target=\"_blank\" rel=\"noreferrer noopener\">dados da <strong>Serasa<\/strong><\/a>, empresa de an\u00e1lise e informa\u00e7\u00f5es para decis\u00f5es de cr\u00e9dito, indicam que uma pessoa solteira precisa ganhar, em m\u00e9dia, R$ 3.520 para viver com relativa estabilidade, valor que pode variar conforme a regi\u00e3o.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Sul, por exemplo, o custo de vida tende a ser mais elevado, enquanto no Nordeste o gasto costuma ser menor. O levantamento observou, ainda, que oito em cada dez brasileiros consideram dif\u00edcil gerenciar seus pagamentos e despesas di\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais do que um dado isolado, essa discrep\u00e2ncia revela problema estrutural: para grande parte da popula\u00e7\u00e3o, a renda simplesmente n\u00e3o acompanha o custo de vida, o que torna o endividamento, muitas vezes, inevit\u00e1vel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Poder de compra no Brasil: real perde valor<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2024, o <a href=\"https:\/\/economia.uol.com.br\/noticias\/redacao\/2024\/06\/30\/apos-30-anos-nota-de-r-100-compra-r-1328.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><em>UOL<\/em><\/a> avaliou a mudan\u00e7a no poder de compra do real e constatou que, nos \u00faltimos 30 anos, o que antes valia R$ 100 (valor do sal\u00e1rio m\u00ednimo na \u00e9poca) hoje equivale a apenas R$ 13,28. A infla\u00e7\u00e3o reduziu o poder de compra dos brasileiros em mais de 87% desde a implementa\u00e7\u00e3o do Plano Real em 1994.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"309\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/shutterstock_1645447474.jpg\" alt=\"\" class=\"wp-image-45909\" style=\"aspect-ratio:1.6181523500810373;width:394px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/shutterstock_1645447474.jpg 500w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/shutterstock_1645447474-300x185.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/shutterstock_1645447474-356x220.jpg 356w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: Shutterstock<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o portal destacou que a infla\u00e7\u00e3o acumulada do per\u00edodo supera 700%. Embora a tend\u00eancia natural do poder de compra seja diminuir com o tempo, para <strong>Jos\u00e9 Ronaldo Souza<\/strong>, professor de Economia do <strong>Instituto Brasileiro de Mercado de Capitais do Rio de Janeiro (Ibmec-RJ)<\/strong>, o Brasil sofreu \u201cuma corros\u00e3o maior do que os pa\u00edses desenvolvidos devido a sucessivas crises que resultaram na desvaloriza\u00e7\u00e3o cambial e em anos de infla\u00e7\u00e3o elevada\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rela\u00e7\u00e3o entre infla\u00e7\u00e3o e d\u00edvidas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mas qual \u00e9 a rela\u00e7\u00e3o entre a infla\u00e7\u00e3o e as d\u00edvidas? O <a href=\"https:\/\/www.bcb.gov.br\/controleinflacao\/oqueinflacao\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Banco Central do Brasil<\/strong><\/a> explicou que, quanto maior a infla\u00e7\u00e3o, mais alto se torna o custo de vida dos cidad\u00e3os. Al\u00e9m de gerar incertezas econ\u00f4micas, esse fen\u00f4meno prejudica o crescimento do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como consequ\u00eancia, as taxas de juros sobre as d\u00edvidas tamb\u00e9m s\u00e3o elevadas, em uma tentativa de compensar os efeitos da alta inflacion\u00e1ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Fatores determinantes para endividamento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dados do <a href=\"https:\/\/www.gov.br\/investidor\/pt-br\/penso-logo-invisto\/dividas-fatores-comportamentais-e-seus-efeitos-psicologicos\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Governo Federal<\/strong><\/a>, da consultoria de finan\u00e7as <a href=\"https:\/\/planofp.com.br\/quais-as-principais-causas-do-endividamento\/#:~:text=Desemprego%20%C2%B7%20Compras%20por%20impulso%20%C2%B7%20Diminui%C3%A7%C3%A3o,sobre%20organiza%C3%A7%C3%A3o%20financeira%20%C2%B7%20Uso%20n%C3%A3o%20planejado\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Plano<\/strong><\/a> e do <a href=\"https:\/\/economia.uol.com.br\/noticias\/redacao\/2024\/11\/22\/perfil-dos-endividados.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><em>UOL Economia<\/em><\/a> revelam os principais motivos para o endividamento dos brasileiros:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comportamento de consumo compulsivo<\/strong>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A impulsividade ou a falta de autocontrole est\u00e1 fortemente associada ao ac\u00famulo de d\u00edvidas. Muitas pessoas tendem a comprar por impulso como forma de lidar com o estresse e outras emo\u00e7\u00f5es negativas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Compara\u00e7\u00e3o social<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Outro aspecto apontado como potencializador desse cen\u00e1rio \u00e9 a compara\u00e7\u00e3o social, na qual as pessoas podem se sentir pressionadas a manter padr\u00f5es de consumo e estilos de vida incompat\u00edveis com suas realidades financeiras. A busca por status social est\u00e1 entre os fatores que incentivam o uso de cr\u00e9dito e o ac\u00famulo de d\u00edvidas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Falta de organiza\u00e7\u00e3o e planejamento financeiro<\/strong>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Muitos brasileiros ainda n\u00e3o t\u00eam o h\u00e1bito de se organizar financeiramente ou de monitorar suas despesas ao longo do tempo. Esse comportamento pode estar relacionado \u00e0 car\u00eancia de educa\u00e7\u00e3o financeira nas escolas, seja pela aus\u00eancia de profissionais capacitados ou pela falta de inser\u00e7\u00e3o do tema no curr\u00edculo escolar. Essa lacuna \u00e9 ainda mais acentuada em institui\u00e7\u00f5es de ensino p\u00fablicas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Desconhecimento financeiro e desemprego<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Os brasileiros, de modo geral, n\u00e3o t\u00eam conhecimento ou n\u00e3o entendem realmente as taxas de juros e o custo total da d\u00edvida no momento de utilizar o cr\u00e9dito, seja por meio de cart\u00f5es ou de empr\u00e9stimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guilherme Casagrande<\/strong>, educador financeiro da <strong>Creditas<\/strong>, plataforma digital de cr\u00e9dito, comentou: \u201cAs pessoas ainda usam os cr\u00e9ditos mais caros que existem no mercado. Existem op\u00e7\u00f5es mais atrativas, mas elas ainda seguem o senso comum. H\u00e1 uma falta de conhecimento; as pessoas n\u00e3o conhecem, por exemplo, o custo efetivo total da opera\u00e7\u00e3o\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m das quest\u00f5es citadas, o desemprego exerce papel crucial. Dados do <strong>Instituto Brasileiro de Geografia e Estat\u00edstica (<\/strong><a href=\"https:\/\/www.bcb.gov.br\/controleinflacao\/oqueinflacao\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>IBGE<\/strong><\/a><strong>)<\/strong> indicam que 5,5 milh\u00f5es de brasileiros est\u00e3o fora do mercado de trabalho atualmente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"745\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-1024x745.jpeg\" alt=\"\" class=\"wp-image-45907\" style=\"aspect-ratio:1.375430123754905;width:586px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-1024x745.jpeg 1024w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-300x218.jpeg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-768x558.jpeg 768w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-578x420.jpeg 578w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-696x506.jpeg 696w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-1068x776.jpeg 1068w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024-324x235.jpeg 324w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/endividamento-uol-creditas-2024.jpeg 1264w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: UOL Economia, 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Endividamento e apostas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/sbcnoticias.com\/br\/lula-ameaca-fechar-casas-de-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">posicionamento contr\u00e1rio<\/a> ao mercado de apostas do presidente <strong>Luiz In\u00e1cio Lula da Silva<\/strong> (PT) em per\u00edodo eleitoral, mesmo ap\u00f3s a san\u00e7\u00e3o da <a href=\"https:\/\/sbcnoticias.com\/br\/lula-ameaca-fechar-casas-de-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lei n\u00ba 14.790<\/a>, em 2023, somado ao <a href=\"https:\/\/sbcnoticias.com\/br\/ministerio-da-fazenda-levantamento-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">projeto de lei<\/a> do Partido dos Trabalhadores (PT) que visa proibir a atividade em todo o territ\u00f3rio nacional, fomentou discuss\u00f5es sobre a rela\u00e7\u00e3o do setor com o endividamento das fam\u00edlias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O impacto direto das apostas nesse endividamento, embora debatido h\u00e1 anos, n\u00e3o foi comprovado por dados at\u00e9 o momento. Pelo contr\u00e1rio, os indicadores atuais apontam que o gasto mensal m\u00e9dio com as apostas online \u00e9 de <a href=\"https:\/\/www.cnnbrasil.com.br\/economia\/macroeconomia\/brasileiro-gasta-em-media-r-164-com-bets-por-mes\/\" target=\"_blank\" rel=\"noreferrer noopener\">R$ 164<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/sbcnoticias.com\/br\/ministerio-da-fazenda-levantamento-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Minist\u00e9rio da Fazenda<\/strong><\/a> observou que a maioria dos apostadores brasileiros desembolsa at\u00e9 R$ 50 por m\u00eas, enquanto 20% dos usu\u00e1rios gastam mais de R$ 1.000 com a atividade. O levantamento da pasta refor\u00e7ou o car\u00e1ter de entretenimento do setor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, em 2017, antes da legaliza\u00e7\u00e3o das apostas no pa\u00eds, a <a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2017-10\/endividamento-das-familias-cresce-e-atinge-584\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Ag\u00eancia Brasil<\/em><\/a> j\u00e1 noticiava o crescimento do endividamento das fam\u00edlias brasileiras, que na \u00e9poca superava 58%.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">LCA analisa endividamento no Brasil<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, um estudo da <strong>LCA<\/strong>, consultoria econ\u00f4mica, sobre endividamento e inadimpl\u00eancia avaliou o cen\u00e1rio atual do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O material foi elaborado por <strong>Eric Brasil<\/strong>, doutor em Economia e diretor de Regula\u00e7\u00e3o e Pol\u00edticas P\u00fablicas; <strong>Lu\u00eds Jorge<\/strong>, economista s\u00eanior; <strong>Lara Coelho<\/strong>, economista; <strong>Mariana Haase<\/strong>, economista e doutoranda em Economia; e <strong>Tom\u00e1s Cardoso<\/strong>, graduando em Economia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesquisa destacou que os juros s\u00e3o os principais respons\u00e1veis pelo endividamento das fam\u00edlias. Ao mesmo tempo, dados da Serasa demonstram <a href=\"https:\/\/www.serasa.com.br\/limpa-nome-online\/blog\/mapa-da-inadimplencia-e-renogociacao-de-dividas-no-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">crescimento cont\u00ednuo<\/a>, com pequenas varia\u00e7\u00f5es, no n\u00famero de consumidores inadimplentes no Brasil desde maio de 2021. O n\u00famero saltou de 62,5 milh\u00f5es para os atuais 81 milh\u00f5es de brasileiros nessa situa\u00e7\u00e3o. Fevereiro deste ano tornou-se o m\u00eas com o maior n\u00famero de inadimplentes em toda a s\u00e9rie hist\u00f3rica, ap\u00f3s 14 meses consecutivos de alta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO crescimento dos juros de cr\u00e9dito livre para pessoas f\u00edsicas tem crescido no Brasil desde 2020 por conta, principalmente, de dois fatores: Spread Banc\u00e1rio [margem de lucro bruta] e Taxa Selic [taxa b\u00e1sica de juros da economia brasileira]\u201d, afirmou a LCA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O estudo apontou, ainda, que a Taxa Selic tem se descolado do \u00edndice de infla\u00e7\u00e3o, o que posicionou o pa\u00eds no segundo lugar do ranking global de juros reais. Segundo a consultoria, juros elevados comprimem a renda, sobrecarregam o endividamento e resultam em inadimpl\u00eancia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-1024x703.jpeg\" alt=\"\" class=\"wp-image-45908\" style=\"width:656px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-1024x703.jpeg 1024w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-300x206.jpeg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-768x528.jpeg 768w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-611x420.jpeg 611w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-218x150.jpeg 218w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-696x478.jpeg 696w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-1068x734.jpeg 1068w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026-100x70.jpeg 100w, https:\/\/sbcnoticias.com\/br\/uploads\/sites\/3\/sites\/3\/sites\/3\/2026\/04\/lca-endividamento-2026-1281x504.jpeg 734w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/04\/lca-endividamento-2026.jpeg 1300w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: LCA, 2026<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Outro dado relevante do levantamento indica que, em 2017, segundo a <strong>Pesquisa de Or\u00e7amentos Familiares (POF)<\/strong>, 8,5% da renda das fam\u00edlias brasileiras era destinada ao lazer. Esse percentual inclu\u00eda alimenta\u00e7\u00e3o fora de casa (4,7%), viagens (1,9%) e consumo de m\u00eddia, ingressos e clubes (0,6%). Entre 2017 e 2018, os gastos com apostas online representavam 0,3% da renda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No documento, a LCA destacou que, embora esses dados sejam anteriores \u00e0 legaliza\u00e7\u00e3o das apostas no Brasil, eles revelam o comprometimento da renda com o setor naquela \u00e9poca. A consultoria ressaltou que, como ainda n\u00e3o houve uma nova edi\u00e7\u00e3o da POF, n\u00e3o \u00e9 poss\u00edvel afirmar com precis\u00e3o se houve altera\u00e7\u00e3o nos gastos totais com lazer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, dados da <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF)<\/strong> indicam que o setor representa hoje 0,46% do consumo das fam\u00edlias, o que ainda \u201ccaracteriza uma fra\u00e7\u00e3o modesta do gasto total familiar\u201d. Enquanto o pagamento de juros atinge R$ 696 bilh\u00f5es, representando 5,5% do Produto Interno Bruto (PIB) brasileiro, as apostas online movimentaram R$ 37 bilh\u00f5es, o que equivale a menos de 0,5% do consumo das fam\u00edlias e a 0,3% do PIB.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Apostas como entretenimento&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O real motivo para o ataque constante a um setor de entretenimento que apresenta crescimento cont\u00ednuo e gera impacto significativo na economia brasileira pode ainda n\u00e3o estar claro. Ainda assim, fatores como o ambiente pol\u00edtico, sobretudo em momentos pr\u00f3ximos a elei\u00e7\u00f5es, e a necessidade de responder a press\u00f5es sociais podem ajudar a explicar o posicionamento mais r\u00edgido em rela\u00e7\u00e3o ao segmento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Profissionais da ind\u00fastria n\u00e3o negam os efeitos nocivos da pr\u00e1tica compulsiva, contudo, conforme mencionado por diversos executivos, a proibi\u00e7\u00e3o ou a restri\u00e7\u00e3o excessiva da atividade apenas direciona os jogadores ao mercado ilegal, no qual n\u00e3o h\u00e1 fiscaliza\u00e7\u00e3o ou prote\u00e7\u00e3o aos usu\u00e1rios.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os jogos online e as apostas esportivas n\u00e3o s\u00e3o uma atividade nova; apesar da regulamenta\u00e7\u00e3o ser recente no Brasil, o setor \u00e9 consolidado em diversos outros pa\u00edses. Ele atua como segmento econ\u00f4mico regular, gerando empregos, elevando a arrecada\u00e7\u00e3o federal e beneficiando a economia nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diante desse cen\u00e1rio, a discuss\u00e3o sobre o papel das apostas no endividamento ganha outra perspectiva. Afinal, seriam as apostas online a verdadeira raz\u00e3o para a inadimpl\u00eancia das fam\u00edlias brasileiras ou apenas a face mais vis\u00edvel de um problema econ\u00f4mico muito mais complexo?<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer ouvir mais hist\u00f3rias como esta? Confira o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O termo \u201cendividamento\u201d refere-se ao uso excessivo de cr\u00e9dito, enquanto \u201cendividado\u201d designa o indiv\u00edduo que se encontra nessa situa\u00e7\u00e3o. Mas o que, de fato, leva uma pessoa a gastar mais [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":45900,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,8892,3669],"tags":[3644,5303,89,3742,9973,8827],"class_list":["post-45897","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-destacado","category-financas","tag-apostas-esportivas","tag-banco-central-do-brasil","tag-brasil","tag-cassinos-online","tag-endividamento","tag-serasa"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=45897"}],"version-history":[{"count":3,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45897\/revisions"}],"predecessor-version":[{"id":45910,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/45897\/revisions\/45910"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/45900"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=45897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=45897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=45897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}