{"id":46589,"date":"2026-05-18T10:57:19","date_gmt":"2026-05-18T13:57:19","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=46589"},"modified":"2026-05-18T13:09:58","modified_gmt":"2026-05-18T16:09:58","slug":"david-edelman-sbc-summit-americas","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/david-edelman-sbc-summit-americas\/","title":{"rendered":"David Edelman, ex-CMO da Aetna e especialista em IA, integrar\u00e1 programa\u00e7\u00e3o do SBC Summit Americas 2026"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O <strong><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/sbc-summit-americas\/\" rel=\"noreferrer noopener\">SBC Summit Americas 2026 <\/a><\/strong>receber\u00e1 <strong>David Edelman<\/strong>, ex-CMO da <strong>Aetna<\/strong>, membro do corpo docente da <strong>Harvard Business School<\/strong> e autor best-seller, para uma palestra principal exclusiva sobre como a intelig\u00eancia artificial (IA) est\u00e1 transformando a forma como as empresas entendem, alcan\u00e7am e engajam seus clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De conceitos pioneiros como \u201cCustomer Decision Journey\u201d e \u201cSegment-of-One Marketing\u201d \u00e0 consultoria para empresas da Fortune 500, Edelman construiu uma carreira de destaque moldando a forma como as companhias abordam marketing, IA e engajamento de clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A palestra acontecer\u00e1 na <strong>quinta-feira, 11 de junho, das 10h40 \u00e0s 11h<\/strong>, como parte da trilha \u201c<a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedTracks=43y21sffgtj7rta1ktf91431wc\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedTracks=43y21sffgtj7rta1ktf91431wc\" target=\"_blank\" rel=\"noreferrer noopener\">Leaders<\/a>\u201d do SBC Summit Americas. Intitulada \u201c<strong><em><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedSession=42ecb9a8hmwx0xdw9p0hsjbf5r\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedSession=42ecb9a8hmwx0xdw9p0hsjbf5r\" target=\"_blank\" rel=\"noreferrer noopener\">Unlocking AI to Drive Growth<\/a><\/em><\/strong>\u201d, a sess\u00e3o discutir\u00e1 como empresas de gaming podem ir al\u00e9m do uso da IA como ferramenta operacional e aproveit\u00e1-la como impulsionadora de vantagem comercial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edelman analisar\u00e1 como as marcas podem transformar as jornadas digitais e f\u00edsicas dos clientes por meio de personaliza\u00e7\u00e3o e automa\u00e7\u00e3o em escala, equilibrando engajamento, responsabilidade e confian\u00e7a. Com base em exemplos globais de diferentes setores, ele tamb\u00e9m apresentar\u00e1 uma estrutura pr\u00e1tica, em n\u00edvel de CEO, para transformar a IA em um motor sustent\u00e1vel de crescimento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDavid traz um n\u00edvel de experi\u00eancia que poucos palestrantes conseguem igualar, especialmente quando se trata de conectar IA a uma estrat\u00e9gia real de marketing. Esse \u00e9 exatamente o tipo de insight que o nosso p\u00fablico est\u00e1 buscando neste momento\u201d, disse <strong>Rasmus Sojmark<\/strong>, CEO e fundador da SBC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao longo de mais de quatro d\u00e9cadas, Edelman construiu uma voz influente nas \u00e1reas de marketing e tecnologia, recebendo reconhecimento da <strong>Forbes<\/strong> como um dos \u201c<strong>CMOs mais influentes do mundo<\/strong>\u201d em v\u00e1rios anos e um lugar na lista \u201c<strong>AI Trailblazers Power 100<\/strong>\u201d da <strong>Adweek<\/strong> em 2025. Ele tamb\u00e9m conta com mais de 1,1 milh\u00e3o de seguidores no LinkedIn.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Edelman come\u00e7ou sua carreira em 1986 no <strong>Boston Consulting Group (BCG)<\/strong>, trabalhando com dados de clientes e estabelecendo a base para seu reconhecido artigo de 1989, \u201c<strong>Segment-of-One Marketing<\/strong>\u201d, que introduziu a ideia de adaptar o marketing a clientes individuais em escala. Mais tarde, ele ajudou a desenvolver a pr\u00e1tica de e-commerce do BCG antes de ingressar na <strong>Digitas<\/strong>, em 1999, onde se concentrou em experi\u00eancias digitais orientadas por dados por meio de CRM e analytics.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2008, ele foi para a <strong>McKinsey &amp; Company<\/strong>, onde estruturou e liderou a pr\u00e1tica global de marketing digital. Durante esse per\u00edodo, apresentou o conceito de \u201c<strong>Customer Decision Journey<\/strong>\u201d em uma reportagem de capa marcante da Harvard Business Review, redefinindo a forma como as empresas entendem e influenciam o caminho desde a conscientiza\u00e7\u00e3o inicial at\u00e9 a compra e a fideliza\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ao comentar sua participa\u00e7\u00e3o, Edelman afirmou: \u201cExiste um equ\u00edvoco de que a IA pode simplesmente ser adicionada \u00e0s estrat\u00e9gias de marketing existentes, quando, na realidade, ela exige uma reformula\u00e7\u00e3o fundamental. Nesta sess\u00e3o, vou analisar como as empresas podem adaptar sua abordagem e usar a IA para oferecer experi\u00eancias de cliente mais relevantes e personalizadas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em 2016, Edelman assumiu uma posi\u00e7\u00e3o de lideran\u00e7a corporativa como o primeiro CMO da <strong>Aetna<\/strong>, onde liderou uma ampla transforma\u00e7\u00e3o digital e de marca. Ele aprimorou as capacidades de marketing, reposicionou a marca como uma parceira confi\u00e1vel em sa\u00fade e construiu um programa abrangente de experi\u00eancia do cliente, al\u00e9m de contribuir para a fus\u00e3o da empresa com a CVS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que deixou a Aetna, em 2020, Edelman tem se dedicado ao trabalho de consultoria por meio da <strong>Edelman Advisory Services<\/strong>, apoiando CEOs e CMOs no uso mais eficaz da IA em marketing. Seu trabalho aborda estrutura de equipes, melhor uso de dados e formas de entregar experi\u00eancias mais relevantes aos clientes, mantendo o toque humano e construindo confian\u00e7a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m do trabalho de consultoria, Edelman contribuiu para a forma\u00e7\u00e3o da pr\u00f3xima gera\u00e7\u00e3o de l\u00edderes empresariais como membro do corpo docente da Harvard Business School. Ele tamb\u00e9m \u00e9 reconhecido como autor, tendo coescrito \u201c<em><strong>Personalized: Customer Strategy in the Age of AI<\/strong><\/em>\u201d, best-seller do USA Today que explora como empresas podem usar IA e dados para oferecer experi\u00eancias de cliente mais relevantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A participa\u00e7\u00e3o de Edelman integra a ampla <a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedSession=42ecb9a8hmwx0xdw9p0hsjbf5r\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcevents.com\/sbc-summit-americas\/agenda\/?selectedSession=42ecb9a8hmwx0xdw9p0hsjbf5r\" rel=\"noreferrer noopener\">agenda de confer\u00eancias <\/a>do SBC Summit Americas, que contar\u00e1 com 250 palestrantes especialistas em seis palcos, abordando temas centrais como lideran\u00e7a, apostas esportivas e cassino, pagamentos e tecnologia, afilia\u00e7\u00e3o, regula\u00e7\u00e3o e prote\u00e7\u00e3o ao jogador. Essas sess\u00f5es fazem parte do \u201cKnowledge Vault\u201d do evento, desenvolvido para oferecer insights pr\u00e1ticos a profissionais da ind\u00fastria.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Adquira o\u00a0<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/conference-pass\/?utm_medium=PR&amp;utm_source=NEWSPAGEANDPARTNERS&amp;utm_campaign=SBCSC-26&amp;tr=true\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Conference Pass<\/em><\/a><em>\u00a0para ter acesso completo ao \u201cKnowledge Vault\u201d do SBC Summit Americas 2026, incluindo workshops, conte\u00fados p\u00f3s-evento e piso de exposi\u00e7\u00e3o.\u00a0<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/for-operators\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Operadores<\/em><\/a><em>&nbsp;e&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/for-affiliates\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>afiliados<\/em><\/a><em>&nbsp;podem solicitar o VIP Pass gratuitamente.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>A SBC tamb\u00e9m oferece VIP Pass, Expo Pass, Networking Pass e Business Pass. Confira todas as op\u00e7\u00f5es dispon\u00edveis&nbsp;<\/em><a href=\"https:\/\/sbcevents.com\/sbc-summit-americas\/ticket-options\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>aqui<\/em><\/a><em>.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O SBC Summit Americas 2026 receber\u00e1 David Edelman, ex-CMO da Aetna, membro do corpo docente da Harvard Business School e autor best-seller, para uma palestra principal exclusiva sobre como a [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":46590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[10188,2972,1170,6935],"class_list":["post-46589","post","type-post","status-publish","format-standard","has-post-thumbnail","category-uncategorized","tag-david-edelman","tag-inteligencia-artificial","tag-sbc-events","tag-sbc-summit-americas"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=46589"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46589\/revisions"}],"predecessor-version":[{"id":46591,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46589\/revisions\/46591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/46590"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=46589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=46589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=46589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}