{"id":46661,"date":"2026-05-20T13:26:27","date_gmt":"2026-05-20T16:26:27","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=46661"},"modified":"2026-05-20T13:36:39","modified_gmt":"2026-05-20T16:36:39","slug":"anjl-stf-restricao-publicidade-apostas-rs","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/anjl-stf-restricao-publicidade-apostas-rs\/","title":{"rendered":"ANJL leva ao STF a\u00e7\u00e3o contra lei ga\u00facha que restringe publicidade de apostas"},"content":{"rendered":"\n<p>Na \u00faltima sexta-feira, 15, a <strong>Associa\u00e7\u00e3o Nacional de Jogos e Loterias (<\/strong><a href=\"https:\/\/sbcnoticias.com\/br\/anjl-posicionamento-desenrola-2\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ANJL<\/strong><\/a><strong>)<\/strong> enviou ao presidente do <strong>Supremo Tribunal Federal (<\/strong><a href=\"https:\/\/sbcnoticias.com\/br\/stf-vincula-apostas-ao-endividamento\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>STF<\/strong><\/a><strong>)<\/strong>, <strong>Edson Fachin<\/strong>, a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 7971 contra a <a href=\"https:\/\/sbcnoticias.com\/br\/rs-restringe-publicidade-apostas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lei Estadual n\u00ba 16.508\/2026<\/a>. A norma, sancionada recentemente pelo governador <strong>Eduardo Leite<\/strong> (PSD-RS), imp\u00f5e restri\u00e7\u00f5es \u00e0 publicidade de apostas no Rio Grande do Sul.<\/p>\n\n\n\n<p>No documento, a ANJL afirmou que a lei \u00e9 inconstitucional por avan\u00e7ar sobre compet\u00eancias exclusivas da Uni\u00e3o e interferir em temas j\u00e1 regulados em \u00e2mbito federal, como responsabilidade civil e atividades lot\u00e9ricas.<\/p>\n\n\n\n<p>A entidade tamb\u00e9m destacou que as restri\u00e7\u00f5es impostas pelo governo do Rio Grande do Sul violam princ\u00edpios constitucionais da ordem econ\u00f4mica, como livre iniciativa e livre concorr\u00eancia, ao estabelecer interven\u00e7\u00e3o considerada desproporcional sobre a atividade.<\/p>\n\n\n\n<p>Segundo a ANJL, a a\u00e7\u00e3o n\u00e3o questiona a fiscaliza\u00e7\u00e3o estatal, mas sim a cria\u00e7\u00e3o de regime regulat\u00f3rio pr\u00f3prio sob o argumento de proteger usu\u00e1rios e grupos vulner\u00e1veis.<\/p>\n\n\n\n<p>Al\u00e9m disso, a entidade defendeu possuir legitimidade para propor a\u00e7\u00e3o ao STF, destacando que a lei ga\u00facha impacta diretamente as 23 empresas representadas pela associa\u00e7\u00e3o. Para a ANJL, a norma interfere na atua\u00e7\u00e3o dos operadores licenciados pela <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF)<\/strong> ao restringir publicidade, contratos de patroc\u00ednios, rela\u00e7\u00f5es com ve\u00edculos de comunica\u00e7\u00e3o e plataformas digitais, al\u00e9m de prever san\u00e7\u00f5es administrativas.&nbsp;<\/p>\n\n\n\n<p>O entendimento da associa\u00e7\u00e3o converge com a <a href=\"https:\/\/sbcnoticias.com\/br\/spa-aponta-inconstitucionalidade-lei-rs\/\" target=\"_blank\" rel=\"noreferrer noopener\">manifesta\u00e7\u00e3o recente da SPA<\/a>, que tamb\u00e9m apontou poss\u00edvel inconstitucionalidade da norma.<\/p>\n\n\n\n<p>\u201cA Lei ga\u00facha n\u00ba 16.508, de 2026, apresenta v\u00edcio de inconstitucionalidade formal por quatro principais motivos, quais sejam: lesar a compet\u00eancia privativa da Uni\u00e3o para legislar sobre loterias, forte no art. 22, XX; violar compet\u00eancia legislativa privativa da Uni\u00e3o para dispor sobre publicidade e propaganda, prevista no art. 22, XXIX; e invadir compet\u00eancia da Uni\u00e3o para dispor sobre telecomunica\u00e7\u00f5es, embasada no art. 22, IV, e para dispor sobre responsabilidade civil &#8211; todos da Constitui\u00e7\u00e3o Federal. Percebe-se que elas versam sobre descumprimento da compet\u00eancia legislativa privativa federal\u201d, alegou a ANJL na a\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<p>E acrescentou: \u201cOs v\u00edcios de inconstitucionalidade formal afetam a raiz e a totalidade da Lei ga\u00facha, raz\u00e3o pela qual se trata de inconstitucionalidade total do diploma legislativo. Contudo, por precau\u00e7\u00e3o, far-se-\u00e1 pedido subsidi\u00e1rio de inconstitucionalidade de artigos espec\u00edficos da Lei Estadual n\u00ba 16.508\/2026\u201d.&nbsp;<\/p>\n\n\n\n<p>Na peti\u00e7\u00e3o, a ANJL estruturou suas alega\u00e7\u00f5es em nove fundamentos de inconstitucionalidade, divididos entre v\u00edcios formais e materiais. Entre os principais pontos, a entidade argumentou que houve usurpa\u00e7\u00e3o da compet\u00eancia privativa da Uni\u00e3o para legislar sobre loterias, propaganda comercial, telecomunica\u00e7\u00f5es, radiodifus\u00e3o e responsabilidade civil.<\/p>\n\n\n\n<p>No aspecto material, a associa\u00e7\u00e3o apontou viola\u00e7\u00e3o aos princ\u00edpios da ordem econ\u00f4mica previstos na Constitui\u00e7\u00e3o, sustentando que a norma estadual extrapola os limites da interven\u00e7\u00e3o regulat\u00f3ria permitida aos entes federativos.&nbsp;<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file aligncenter\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/ANJL-ADI-7971.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorporado de Associa\u00e7\u00e3o Nacional de Jogos e Loterias, ADI-7971.\"><\/object><a id=\"wp-block-file--media-7873ad31-5f7f-4e8e-9bab-e239f6a52e10\" href=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/ANJL-ADI-7971.pdf\">Associa\u00e7\u00e3o Nacional de Jogos e Loterias, ADI-7971<\/a><a href=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/ANJL-ADI-7971.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-7873ad31-5f7f-4e8e-9bab-e239f6a52e10\">Download<\/a><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><em>Quer ouvir mais hist\u00f3rias como esta? Confira o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima sexta-feira, 15, a Associa\u00e7\u00e3o Nacional de Jogos e Loterias (ANJL) enviou ao presidente do Supremo Tribunal Federal (STF), Edson Fachin, a A\u00e7\u00e3o Direta de Inconstitucionalidade (ADI) 7971 contra [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":46663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,3665],"tags":[3810,3644,3742,4302,3888,5865],"class_list":["post-46661","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-cassinos-online","tag-anjl","tag-apostas-esportivas","tag-cassinos-online","tag-publicidade-de-apostas","tag-rio-grande-do-sul","tag-stf"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=46661"}],"version-history":[{"count":4,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46661\/revisions"}],"predecessor-version":[{"id":46668,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46661\/revisions\/46668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/46663"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=46661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=46661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=46661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}