{"id":46804,"date":"2026-05-26T11:19:27","date_gmt":"2026-05-26T14:19:27","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=46804"},"modified":"2026-05-26T11:19:31","modified_gmt":"2026-05-26T14:19:31","slug":"atlaslive-anuncia-parceria-com-onabet","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/atlaslive-anuncia-parceria-com-onabet\/","title":{"rendered":"Atlaslive fecha parceria com Onabet, do Grupo Esportes Gaming Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A <strong><a href=\"https:\/\/atlaslive.tech\/content-hub\/atlaslive-becomes-direct-technology-partner-for-onabet\" data-type=\"link\" data-id=\"https:\/\/atlaslive.tech\/content-hub\/atlaslive-becomes-direct-technology-partner-for-onabet\" target=\"_blank\" rel=\"noreferrer noopener\">Atlaslive<\/a><\/strong> anunciou nesta ter\u00e7a-feira, 26, uma parceria direta com a <strong><a href=\"https:\/\/sbcnoticias.com\/br\/onabet-foco-mercado-cassino\/\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/onabet-foco-mercado-cassino\/\" target=\"_blank\" rel=\"noreferrer noopener\">Onabet<\/a><\/strong>, marca que integra o portf\u00f3lio do <strong><a href=\"https:\/\/sbcnoticias.com\/br\/esportes-gaming-brasil-nomeacao-andrea-curral\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/esportes-gaming-brasil-nomeacao-andrea-curral\/\" rel=\"noreferrer noopener\">Grupo Esportes Gaming Brasil<\/a><\/strong>, para atuar como provedora dedicada de tecnologia da operadora no Brasil. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acordo entre Atlaslive e Onabet prev\u00ea o fornecimento de infraestrutura de plataforma, suporte operacional e acompanhamento cont\u00ednuo para a opera\u00e7\u00e3o da marca no mercado regulado de apostas brasileiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Onabet possui autoriza\u00e7\u00e3o da <strong>Secretaria de Pr\u00eamios e Apostas do Minist\u00e9rio da Fazenda (SPA\/MF)<\/strong> para operar no mercado de apostas e jogos online brasileiro desde 2025. Segundo a Atlaslive, a Onabet \u00e9 uma das maiores operadoras do Brasil em Gross Gaming Revenue (GGR, receita bruta de jogos).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onabet busca fortalecer opera\u00e7\u00e3o com o apoio da Atlaslive<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"515\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-1024x515.jpg\" alt=\"Logo da Onabet.\" class=\"wp-image-46811\" style=\"width:656px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-1024x515.jpg 1024w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-300x151.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-768x387.jpg 768w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-834x420.jpg 834w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-696x350.jpg 696w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet-1068x538.jpg 1068w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/05\/Onabet.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: Grupo Esportes Gaming Brasil<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">A Atlaslive afirmou que o modelo de parceria direta permite maior alinhamento no desenvolvimento de produtos, ciclos mais r\u00e1pidos de implanta\u00e7\u00e3o e maior integra\u00e7\u00e3o com as necessidades operacionais da Onabet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Volodymyr Taftai<\/strong>, diretor da Atlaslive no Brasil, disse que a parceria entre operador e provedor tende a acelerar a entrega de funcionalidades e a resolu\u00e7\u00e3o de problemas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuando voc\u00ea trabalha diretamente com a equipe que constr\u00f3i sua plataforma, tudo acelera, desde a entrega de recursos at\u00e9 a resolu\u00e7\u00e3o de problemas. Esse \u00e9 o modelo em que acreditamos, e estamos satisfeitos que a Onabet compartilhe essa vis\u00e3o\u201d, afirmou Taftai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O executivo da Atlaslive tamb\u00e9m destacou o n\u00edvel de exig\u00eancia do mercado brasileiro. \u201cO Brasil \u00e9 um dos mercados regulados mais exigentes do mundo. Conquistar a confian\u00e7a de um operador licenciado aqui \u00e9 algo que levamos a s\u00e9rio\u201d, acrescentou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 <strong><a href=\"https:\/\/sbcnoticias.com\/br\/hugo-baungartner-esportes-gaming-brasil-2026\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/www.linkedin.com\/in\/hugo-baungartner\/\" rel=\"noreferrer noopener\">Hugo Baungartner,<\/a><\/strong> Chief Business Officer (CBO) do Grupo Esportes Gaming Brasil, afirmou que o ambiente regulado no pa\u00eds exige opera\u00e7\u00f5es mais robustas e escal\u00e1veis, alinhadas \u00e0 din\u00e2mica local.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO mercado regulado brasileiro exige opera\u00e7\u00f5es cada vez mais robustas, escal\u00e1veis e alinhadas \u00e0s din\u00e2micas locais. Esta parceria ajuda a fortalecer nossas capacidades tecnol\u00f3gicas e apoia a evolu\u00e7\u00e3o cont\u00ednua da experi\u00eancia entregue pela Onabet\u201d, disse Baungartner.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da Onabet, o Grupo Esportes Gaming Brasil tamb\u00e9m \u00e9 respons\u00e1vel pelas marcas <strong>Esportes da Sorte <\/strong>e <strong>Lottu<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer ouvir mais hist\u00f3rias como esta? Confira o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Atlaslive anunciou nesta ter\u00e7a-feira, 26, uma parceria direta com a Onabet, marca que integra o portf\u00f3lio do Grupo Esportes Gaming Brasil, para atuar como provedora dedicada de tecnologia da [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":46810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,3665],"tags":[3644,6716,3742,9404],"class_list":["post-46804","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-cassinos-online","tag-apostas-esportivas","tag-atlaslive","tag-cassinos-online","tag-onabet"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=46804"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46804\/revisions"}],"predecessor-version":[{"id":46812,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46804\/revisions\/46812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/46810"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=46804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=46804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=46804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}