{"id":46966,"date":"2026-06-02T14:15:28","date_gmt":"2026-06-02T17:15:28","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=46966"},"modified":"2026-06-02T14:17:05","modified_gmt":"2026-06-02T17:17:05","slug":"ministro-stj-defende-legalizacao-cassinos","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/ministro-stj-defende-legalizacao-cassinos\/","title":{"rendered":"Ministro do STJ defende legaliza\u00e7\u00e3o dos cassinos no Brasil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O ministro <strong>Jo\u00e3o Ot\u00e1vio de Noronha<\/strong>, do <strong>Superior Tribunal de Justi\u00e7a (STJ)<\/strong>, defendeu a legaliza\u00e7\u00e3o dos cassinos no Brasil durante entrevista concedida ao portal <em>Migalhas<\/em> no <strong>14\u00ba F\u00f3rum de Lisboa<\/strong>. Segundo o magistrado, muitos brasileiros viajam ao exterior para participar desse tipo de atividade, o que evidencia a demanda existente no pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noronha tamb\u00e9m argumentou que os benef\u00edcios econ\u00f4micos associados aos cassinos, como a gera\u00e7\u00e3o de empregos, acabam sendo concentrados em destinos que j\u00e1 regulamentaram a atividade, como Las Vegas e diversos pa\u00edses europeus. Na avalia\u00e7\u00e3o do ministro, o Brasil deixa de captar esses impactos positivos ao manter a proibi\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apesar de afirmar que n\u00e3o tem o h\u00e1bito de apostar, o magistrado reconheceu o forte apelo da atividade entre os brasileiros e defendeu a import\u00e2ncia de ampliar o debate sobre o tema, incluindo a discuss\u00e3o de modelo regulat\u00f3rio adequado para o pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, Noronha ressaltou que a discuss\u00e3o n\u00e3o deve abranger as apostas online, \u00e0s quais se referiu como \u201cbets\u201d. Na avalia\u00e7\u00e3o do ministro, a modalidade n\u00e3o deveria ter sido regulamentada, por considerar que o ambiente digital oferece menor capacidade de controle e fiscaliza\u00e7\u00e3o da atividade quando comparado aos cassinos f\u00edsicos.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"lbbrY5P-NO4\"><iframe loading=\"lazy\" title=\"Noronha defende regulamenta\u00e7\u00e3o de jogos no Brasil, mas deixa bets de fora\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/lbbrY5P-NO4?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><figcaption class=\"wp-element-caption\"><em>Entrevista do portal Migalhas com <strong>Jo\u00e3o Ot\u00e1vio de Noronha<\/strong>, ministro do STJ, no YouTube.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Impactos da legaliza\u00e7\u00e3o dos cassinos<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/bruno-omori-.jpeg\" alt=\"\" class=\"wp-image-46968\" style=\"width:212px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/bruno-omori-.jpeg 500w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/bruno-omori--300x300.jpeg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/bruno-omori--150x150.jpeg 150w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/bruno-omori--420x420.jpeg 420w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Bruno Omori, <a href=\"https:\/\/www.linkedin.com\/in\/brunoomori\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Em janeiro deste ano, o <em>SBC Not\u00edcias Brasil<\/em> <a href=\"https:\/\/sbcnoticias.com\/br\/bruno-omori-cassinos-sbc-summit-rio-2026\/\">entrevistou <strong>Bruno Omori<\/strong><\/a>, presidente do <strong>Instituto de Desenvolvimento, Turismo, Cultura, Esporte e Meio Ambiente (IDT-CEMA)<\/strong>, sobre os impactos de legalizar os cassinos f\u00edsicos no Brasil.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na entrevista, Omori destacou o potencial dos jogos f\u00edsicos no pa\u00eds, alegando que o setor tur\u00edstico est\u00e1 entre os principais beneficiados da atividade: \u201cAprovando essa lei [n\u00ba 2.234\/2022], n\u00f3s vamos ter uma entrada de aproximadamente US$ 70 bilh\u00f5es de investimentos no Brasil\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, espera-se que, com a legaliza\u00e7\u00e3o dos cassinos, cerca de 30 milh\u00f5es de trabalhadores sejam impactados positivamente, sendo 10 milh\u00f5es de forma direta e 20 milh\u00f5es de maneira indireta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O executivo afirmou: \u201cQuando voc\u00ea cria um estabelecimento como um cassino internacional, voltado ao turismo, seja cassino ou bingo, e ele \u00e9 bonito, iluminado, conta com hospedagem, seguran\u00e7a, gastronomia e entretenimento, ele se torna mais seguro e mais abrangente. O com\u00e9rcio ao redor come\u00e7a a prosperar, porque passa a haver demanda por farm\u00e1cia, padaria, e o condom\u00ednio valoriza o metro quadrado. Ou seja, h\u00e1 apenas aspectos positivos para o empreendimento e para o entorno\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1946: Proibi\u00e7\u00e3o dos cassinos no Brasil<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Entre as d\u00e9cadas de 1930 e 1940, os cassinos viveram um per\u00edodo considerado de ouro no Brasil, com mais de 70 estabelecimentos em opera\u00e7\u00e3o. Em 30 de abril de 1946, apenas tr\u00eas meses ap\u00f3s assumir a Presid\u00eancia da Rep\u00fablica, <strong>Eurico Gaspar Dutra<\/strong> assinou o decreto que <a href=\"https:\/\/sbcnoticias.com\/br\/cassinos-brasil-entrevista-hugo-baungartner\/\">proibiu a pr\u00e1tica e a explora\u00e7\u00e3o de jogos de azar<\/a> em todo o territ\u00f3rio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9cadas depois, em 1991, foi apresentado o Projeto de Lei (PL) n\u00ba 442, que deu origem \u00e0 proposta atualmente em tramita\u00e7\u00e3o no Congresso Nacional para legalizar cassinos, bingos e outras modalidades de jogos. Apesar do avan\u00e7o das discuss\u00f5es legislativas, os cassinos seguem proibidos no Brasil.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"381\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/casinos-antigos.jpg\" alt=\"\" class=\"wp-image-46972\" style=\"width:411px;height:auto\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/casinos-antigos.jpg 500w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/casinos-antigos-300x229.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/06\/casinos-antigos-80x60.jpg 80w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Casal jogando roleta em um cassino antigo. Cr\u00e9dito: Shutterstock.<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Para <strong><a href=\"https:\/\/sbcnoticias.com\/br\/hugo-baungartner-esportes-gaming-brasil-2026\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/hugo-baungartner-esportes-gaming-brasil-2026\/\" rel=\"noreferrer noopener\">Hugo Baungartner<\/a><\/strong>, especialista do setor com mais de 30 anos de experi\u00eancia, n\u00e3o h\u00e1 motivos para manter a proibi\u00e7\u00e3o dos cassinos no Brasil: \u201cO argumento de que os cassinos podem ser usados para lavagem de dinheiro n\u00e3o \u00e9 exclusivo dessa ind\u00fastria &#8211; qualquer modelo de neg\u00f3cio pode ser vulner\u00e1vel a esse tipo de crime. A solu\u00e7\u00e3o est\u00e1 em criar um sistema de regulamenta\u00e7\u00e3o que minimize esses riscos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Baungartner, a decis\u00e3o de fechar os cassinos foi influenciada pelo movimento conservador da \u00e9poca, representado por <strong>Dona Santinha<\/strong>, esposa do ent\u00e3o presidente Eurico Gaspar Dutra, al\u00e9m da busca por projetar uma imagem mais moralizada do pa\u00eds no per\u00edodo p\u00f3s-guerra.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Situa\u00e7\u00e3o atual do PL dos Cassinos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/www25.senado.leg.br\/web\/atividade\/materias\/-\/materia\/154401\" target=\"_blank\" rel=\"noreferrer noopener\">PL n\u00ba 2.234\/2022<\/a>, tamb\u00e9m conhecido como PL dos Cassinos, est\u00e1 atualmente em tramita\u00e7\u00e3o no <strong>Senado Federal<\/strong>. A proposta tem origem no PL 442\/1991, de autoria do ex-deputado federal <strong>Renato Vianna<\/strong>, e busca regulamentar a explora\u00e7\u00e3o de cassinos, bingos, jogo do bicho e apostas em corridas de cavalos no Brasil. O texto tem como relator o senador <a href=\"https:\/\/sbcnoticias.com\/br\/sbc-summit-rio-entrevista-iraja-abreu-2025\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Iraj\u00e1 Abreu<\/strong><\/a> (PSD-TO).<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer conferir mais hist\u00f3rias como esta? Acesse o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro Jo\u00e3o Ot\u00e1vio de Noronha, do Superior Tribunal de Justi\u00e7a (STJ), defendeu a legaliza\u00e7\u00e3o dos cassinos no Brasil durante entrevista concedida ao portal Migalhas no 14\u00ba F\u00f3rum de Lisboa. [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":46975,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,8892],"tags":[3953,89,4828,5555,5865],"class_list":["post-46966","post","type-post","status-publish","format-standard","has-post-thumbnail","category-brasil","category-destacado","tag-apostas-online","tag-brasil","tag-cassinos-fisicos","tag-pl-dos-cassinos","tag-stf"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=46966"}],"version-history":[{"count":3,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46966\/revisions"}],"predecessor-version":[{"id":46980,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/46966\/revisions\/46980"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/46975"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=46966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=46966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=46966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}