{"id":48124,"date":"2026-07-14T16:24:08","date_gmt":"2026-07-14T19:24:08","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=48124"},"modified":"2026-07-14T16:24:16","modified_gmt":"2026-07-14T19:24:16","slug":"belo-horizonte-decreto-restricoes-apostas","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/belo-horizonte-decreto-restricoes-apostas\/","title":{"rendered":"Belo Horizonte restringe publicidade de apostas em espa\u00e7os municipais e perto de escolas"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/sbcnoticias.com\/br\/belo-horizonte-lei-prevencao-ludopatia\/\" target=\"_blank\" rel=\"noreferrer noopener\">Belo Horizonte<\/a><\/strong>, a capital do Estado de <strong>Minas Gerais<\/strong>, proibiu a veicula\u00e7\u00e3o de publicidade de operadoras de apostas de quota fixa em mobili\u00e1rios urbanos, im\u00f3veis municipais e eventos promovidos pelo poder p\u00fablico. A medida foi estabelecida pelo <a href=\"https:\/\/dom-web.pbh.gov.br\/visualizacao\/ato\/486671\" data-type=\"link\" data-id=\"https:\/\/dom-web.pbh.gov.br\/visualizacao\/ato\/486671\" target=\"_blank\" rel=\"noreferrer noopener\">Decreto n\u00ba 19.654<\/a>, publicado na segunda-feira, em 13 de julho de 2026.<\/p>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<p>O texto, assinado pelo prefeito <strong>\u00c1lvaro Dami\u00e3o<\/strong> (Uni\u00e3o Brasil), altera o Decreto n\u00ba 14.060 que regulamenta o C\u00f3digo de Posturas do munic\u00edpio. A nova regra abrange engenhos de publicidade est\u00e1ticos ou digitais, como pain\u00e9is, placas, outdoors, telas e outras estruturas destinadas \u00e0 exposi\u00e7\u00e3o de an\u00fancios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"370\" src=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/07\/Alvaro-Damiao-Prefeito-Belo-Horizonte-Limita-Publicidade-de-Apostas.jpg\" alt=\"\u00c1lvaro Dami\u00e3o, prefeito de Belo Horizonte.\" class=\"wp-image-48125\" style=\"aspect-ratio:2\/3;object-fit:cover\" srcset=\"https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/07\/Alvaro-Damiao-Prefeito-Belo-Horizonte-Limita-Publicidade-de-Apostas.jpg 490w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/07\/Alvaro-Damiao-Prefeito-Belo-Horizonte-Limita-Publicidade-de-Apostas-300x227.jpg 300w, https:\/\/resourcesbr.sbcnoticias.com\/sbcnoticiasbr\/sites\/3\/2026\/07\/Alvaro-Damiao-Prefeito-Belo-Horizonte-Limita-Publicidade-de-Apostas-80x60.jpg 80w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dito: Prefeitura de Belo Horizonte<\/figcaption><\/figure>\n<\/div>\n\n\n\n<p>A restri\u00e7\u00e3o vale para pe\u00e7as publicit\u00e1rias instaladas em mobili\u00e1rio urbano e pr\u00f3prios municipais. A utiliza\u00e7\u00e3o de publicidade de apostas tamb\u00e9m fica proibida no \u00e2mbito de concess\u00f5es, permiss\u00f5es e autoriza\u00e7\u00f5es concedidas pela administra\u00e7\u00e3o municipal, al\u00e9m de eventos promovidos pelo poder p\u00fablico de Belo Horizonte.<\/p>\n\n\n\n<p>Na pr\u00e1tica, empresas respons\u00e1veis por equipamentos ou servi\u00e7os municipais n\u00e3o poder\u00e3o utilizar esses espa\u00e7os para divulgar marcas ou campanhas de casas de apostas, conforme as condi\u00e7\u00f5es estabelecidas pelo novo decreto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Belo Horizonte estabelece que publicidades de apostas devem ficar 100 metros longe de escolas<\/h2>\n\n\n\n<p>O decreto tamb\u00e9m pro\u00edbe a instala\u00e7\u00e3o de engenhos de publicidade em um raio de 100 metros de escolas, museus e equipamentos ou servi\u00e7os p\u00fablicos destinados ao atendimento de crian\u00e7as, adolescentes e jovens.<\/p>\n\n\n\n<p>Os \u00f3rg\u00e3os e as entidades da Prefeitura de Belo Horizonte ter\u00e3o 15 dias \u00fateis para revisar atos administrativos e contratos atualmente em vigor. O objetivo \u00e9 interromper a veicula\u00e7\u00e3o de an\u00fancios que estejam em desacordo com as novas determina\u00e7\u00f5es.<\/p>\n\n\n\n<p>A norma municipal entrou em vigor na data de sua publica\u00e7\u00e3o. Com isso, eventuais contratos envolvendo publicidade de operadoras de apostas em espa\u00e7os alcan\u00e7ados pelo decreto dever\u00e3o ser adequados pela administra\u00e7\u00e3o municipal dentro do prazo estabelecido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Poss\u00edvel ofensiva contra o setor de apostas<\/h2>\n\n\n\n<p>A medida tomada pela Prefeitura de Belo Horizonte \u00e9 similar \u00e0 medida tomada pela <strong>Prefeitura do Rio de Janeiro<\/strong> na segunda-feira, 13 de julho. A capital carioca proibiu a publicidade de apostas em ambientes externos e em espa\u00e7os p\u00fablicos por meio do <a href=\"https:\/\/sbcnoticias.com\/br\/publicidade-apostas-decreto-rj-58274-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Decreto n\u00ba 58.274\/2026<\/a>.\u00a0<\/p>\n\n\n\n<p>Os decretos, publicados no mesmo dia, indicam que grandes prefeituras podem estar fazendo uma a\u00e7\u00e3o coordenada contra a publicidade de apostas. Na sexta-feira passada, 10, o <a href=\"https:\/\/sbcnoticias.com\/br\/governo-define-novas-regras-publicidade-apostas\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/governo-define-novas-regras-publicidade-apostas\/\" rel=\"noreferrer noopener\"><strong>Governo Federal<\/strong> enrijeceu as regras para a publicidade<\/a> ap\u00f3s pol\u00eamicas envolvendo propagandas durante a <strong>Copa do Mundo<\/strong>.<\/p>\n\n\n\n<p>Paralelamente, h\u00e1 alguns projetos de lei tramitando na <strong>C\u00e2mara dos Deputados<\/strong> e no <strong>Senado Federal<\/strong> que prop\u00f5em a proibi\u00e7\u00e3o da publicidade de apostas em todo o territ\u00f3rio nacional. <a href=\"https:\/\/sbcnoticias.com\/br\/anjl-questiona-decreto-rj-publicidade-apostas\/\" target=\"_blank\" data-type=\"link\" data-id=\"https:\/\/sbcnoticias.com\/br\/anjl-questiona-decreto-rj-publicidade-apostas\/\" rel=\"noreferrer noopener\">O setor regulado de apostas questiona tais medidas<\/a>, j\u00e1 que a atividade foi legalizada e regulamentada no pa\u00eds.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><em>Quer conferir mais hist\u00f3rias como esta? Acesse o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Belo Horizonte, a capital do Estado de Minas Gerais, proibiu a veicula\u00e7\u00e3o de publicidade de operadoras de apostas de quota fixa em mobili\u00e1rios urbanos, im\u00f3veis municipais e eventos promovidos pelo [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":48126,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3664,8892,3666],"tags":[10282,7039,10281,4302],"class_list":["post-48124","post","type-post","status-publish","format-standard","has-post-thumbnail","category-apostas-esportivas","category-destacado","category-regulamento","tag-alvaro-damiao","tag-belo-horizonte","tag-decreto-no-19-654","tag-publicidade-de-apostas"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/48124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=48124"}],"version-history":[{"count":1,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/48124\/revisions"}],"predecessor-version":[{"id":48127,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/48124\/revisions\/48127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/48126"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=48124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=48124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=48124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}