{"id":49616,"date":"2026-09-02T11:40:43","date_gmt":"2026-09-02T14:40:43","guid":{"rendered":"https:\/\/sbcnoticias.com\/br\/?p=49616"},"modified":"2026-09-02T11:40:47","modified_gmt":"2026-09-02T14:40:47","slug":"sbc-lanca-forum-mercados-de-previsao","status":"publish","type":"post","link":"https:\/\/sbcnoticias.com\/br\/sbc-lanca-forum-mercados-de-previsao\/","title":{"rendered":"SBC lan\u00e7a Global Prediction Markets Forum para discutir principais desafios do setor"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os mercados de previs\u00e3o deixaram de ser um segmento de nicho para serem uma das quest\u00f5es mais debatidas no mercado global de apostas. Afinal, s\u00e3o produtos financeiros, produtos de apostas ou uma modalidade para a qual os reguladores ainda n\u00e3o estabeleceram regras claras? O novo <a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Global Prediction Markets Forum<\/strong><\/a>, promovido pela <strong>SBC<\/strong>, reunir\u00e1 os principais nomes do setor para discutir essas quest\u00f5es em uma <a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP#agenda\" target=\"_blank\" rel=\"noreferrer noopener\">programa\u00e7\u00e3o de confer\u00eancia<\/a> de um dia em Lisboa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O evento ser\u00e1 realizado na <strong>quinta-feira, 1\u00ba de outubro<\/strong>, no Myriad Hotel, em Lisboa, paralelamente ao <a href=\"https:\/\/sbcevents.com\/sbc-summit\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>SBC Summit 2026<\/strong><\/a>, e funcionar\u00e1 como um ponto de encontro dedicado a profissionais interessados no futuro dos mercados de previs\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Operadores, especialistas em mercados de previs\u00e3o, profissionais das \u00e1reas jur\u00eddica e regulat\u00f3ria e l\u00edderes de tecnologia se encontrar\u00e3o para analisar os principais desafios do setor, que passa de segmento predominantemente concentrado nos Estados Unidos para oportunidade de expans\u00e3o no mercado global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As sess\u00f5es abordar\u00e3o a evolu\u00e7\u00e3o dos marcos regulat\u00f3rios e jur\u00eddicos, o potencial de adapta\u00e7\u00e3o dos mercados de previs\u00e3o ao p\u00fablico europeu, os aspectos t\u00e9cnicos relacionados ao lan\u00e7amento e \u00e0 integra\u00e7\u00e3o desses produtos e as perspectivas de longo prazo para o setor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOs mercados de previs\u00e3o rapidamente se tornaram um dos principais assuntos em discuss\u00e3o no setor, mas, como acontece com qualquer segmento que avan\u00e7a nesse ritmo, as oportunidades v\u00eam acompanhadas de muitas quest\u00f5es\u201d, afirmou <strong>Rasmus Sojmark<\/strong>, fundador e CEO da SBC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPara os operadores que consideram entrar nesse mercado, a quest\u00e3o \u00e9 como fazer isso de maneira eficiente, segura e em conformidade com as regras. Esse \u00e9 o objetivo do f\u00f3rum: reunir novos participantes e especialistas no mesmo espa\u00e7o, abordar essas quest\u00f5es e construir uma compreens\u00e3o mais clara sobre os rumos do setor\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com diferentes jurisdi\u00e7\u00f5es divididas entre bloquear, regulamentar ou licenciar os mercados de previs\u00e3o, a sess\u00e3o \u201c<a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP&amp;selectedSession=4h39xh2gj7ja4293eyr19609dc#agenda\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Regulating futures: bridging the gap between the US and Europe<\/em><\/a>\u201d analisar\u00e1 a evolu\u00e7\u00e3o do cen\u00e1rio regulat\u00f3rio nos dois lados do Atl\u00e2ntico. Os especialistas <strong>Andrew Lyman<\/strong> (comiss\u00e1rio de Jogos e diretor-executivo, Governo de Gibraltar), <strong>Charles Mizzi<\/strong> (CEO, Malta Gaming Authority), <strong>Terence Cassar<\/strong> (s\u00f3cio, GTG Legal) e <strong>Zach Doctor<\/strong> (cofundador e CEO, WagerWire), sob modera\u00e7\u00e3o de <strong>Ron Segev<\/strong> (s\u00f3cio-fundador, Segev LLP), avaliar\u00e3o as incertezas regulat\u00f3rias em importantes mercados globais e discutir\u00e3o como os operadores podem se preparar para futuras mudan\u00e7as nas regras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No centro desse debate regulat\u00f3rio est\u00e1 a quest\u00e3o de como os mercados de previs\u00e3o devem ser definidos juridicamente. A sess\u00e3o \u201c<a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP&amp;selectedSession=4k6rfzbzwsxxqtp5ht129xm9nt#agenda\" target=\"_blank\" rel=\"noreferrer noopener\"><em>The legal conundrum: are prediction markets gambling?<\/em><\/a>\u201d discutir\u00e1 diretamente o tema, reunindo <strong>Matt Kane<\/strong> (head de Legal, Betr), <strong>Arthur Stadler<\/strong> (s\u00f3cio-fundador, Stadler Partner Attorneys) e <strong>Steve Humenik<\/strong> (CLO, Crypto.com), com modera\u00e7\u00e3o de <strong>Quirino Mancini<\/strong> (s\u00f3cio, WH Partners Italy). O painel debater\u00e1 se os contratos de eventos devem ser classificados como apostas ou opera\u00e7\u00f5es financeiras, analisar\u00e1 os marcos jur\u00eddicos existentes e discutir\u00e1 como os reguladores poder\u00e3o se posicionar no futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A discuss\u00e3o avan\u00e7ar\u00e1 para os aspectos t\u00e9cnicos relacionados ao lan\u00e7amento de mercados de previs\u00e3o na sess\u00e3o \u201c<a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP&amp;selectedSession=42trk2j71938xwadcvmfws5946#agenda\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Time to market &#8211; the technological hurdles to launching a prediction market product<\/em><\/a>\u201d. Os palestrantes <strong>Andrew Gonzalez<\/strong> (CEO, ParlayX), <strong>Henrich Tauber<\/strong> (head de Business Development, Limitless) e <strong>Amit Mahensaria<\/strong> (CEO, Pred.app), al\u00e9m de <strong>Guy Dotan<\/strong> (cofundador, WireMarkets), sob modera\u00e7\u00e3o de <strong>Jeff Haas<\/strong> (Strategic Advisor, Binara.ai), avaliar\u00e3o as tecnologias necess\u00e1rias para garantir conformidade, as op\u00e7\u00f5es de integra\u00e7\u00e3o dispon\u00edveis e quais solu\u00e7\u00f5es podem oferecer um caminho mais r\u00e1pido e eficiente para o lan\u00e7amento desses produtos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O futuro dos mercados de previs\u00e3o ser\u00e1 o foco da sess\u00e3o \u201c<a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP&amp;selectedSession=40n36j042q6wwv4vtc443n3wmj#agenda\" target=\"_blank\" rel=\"noreferrer noopener\"><em>An industry on the cusp of boom or bust: what&#8217;s the future of futures?<\/em><\/a>\u201d. Os especialistas <strong>John Aristotle Phillips<\/strong> (CEO, PredictIt), <strong>Joey Levy<\/strong> (CEO, Betr) e <strong>Noah Traisman<\/strong> (CEO, Winible) discutir\u00e3o se os mercados de previs\u00e3o podem coexistir com as plataformas tradicionais de apostas esportivas, o que pode ser aprendido com outros formatos, como p\u00f4quer e fantasy sports, e se h\u00e1 espa\u00e7o para m\u00faltiplos grandes players no mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outras sess\u00f5es ao longo do dia abordar\u00e3o temas como o papel de parcerias estrat\u00e9gicas com empresas de m\u00eddia para levar os mercados de previs\u00e3o ao grande p\u00fablico, as diferen\u00e7as entre mercados de previs\u00e3o e plataformas de apostas esportivas, as vantagens dos modelos peer-to-peer e de odds fixas e os avan\u00e7os que transformaram os mercados de previs\u00e3o de um produto de nicho em um dos principais temas do mercado global de apostas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>O acesso ao Global Prediction Markets Forum exige a aquisi\u00e7\u00e3o de <\/em><a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP#tickets?promo=sbcmrktng-4il9fyzn&amp;utm_source=NEWSPAGEANDPARTNERSLISBON&amp;utm_medium=LISBONPR&amp;utm_campaign=SBCS-26&amp;utm_content=gpmf-ticket&amp;tr=true\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>ingresso separado<\/em><\/strong><\/a><em>, com pre\u00e7o de <\/em><strong><em>\u20ac 399<\/em><\/strong><em>. Cada participante tamb\u00e9m receber\u00e1 gratuitamente uma c\u00f3pia do relat\u00f3rio \u201cPrediction Market Report 2026\u201d, da SBC Insights.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Os ingressos est\u00e3o dispon\u00edveis <\/em><a href=\"https:\/\/sbcevents.com\/global-prediction-markets-forum\/?promo=WIGAPARTNERVIP#tickets\" target=\"_blank\" rel=\"noreferrer noopener\"><em>aqui<\/em><\/a><em>.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Quer conferir mais hist\u00f3rias como esta? Acesse o novo canal da&nbsp;<a href=\"https:\/\/www.youtube.com\/@SBCMediaChannel\" target=\"_blank\" rel=\"noreferrer noopener\">SBC Media no YouTube<\/a>, o novo espa\u00e7o dedicado a tudo relacionado \u00e0 multim\u00eddia na SBC, onde nossa equipe explora em detalhes as principais not\u00edcias dos setores de apostas esportivas, iGaming, afiliados e pagamentos.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Receba um resumo com as principais not\u00edcias sobre o mercado de jogos online e de apostas esportivas no Brasil atrav\u00e9s do&nbsp;<\/em><a href=\"https:\/\/sbcnoticias.com\/br\/newsletter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>link<\/em><\/a><em>. A newsletter \u00e9 enviada toda segunda, ter\u00e7a e quinta-feira, sempre \u00e0s 17 horas<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os mercados de previs\u00e3o deixaram de ser um segmento de nicho para serem uma das quest\u00f5es mais debatidas no mercado global de apostas. Afinal, s\u00e3o produtos financeiros, produtos de apostas [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":49620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[8892,3667],"tags":[3644,3742,10263,1170,788],"class_list":["post-49616","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacado","category-internacional-2","tag-apostas-esportivas","tag-cassinos-online","tag-mercados-de-previsao","tag-sbc-events","tag-sbc-summit"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/49616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/comments?post=49616"}],"version-history":[{"count":4,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/49616\/revisions"}],"predecessor-version":[{"id":49625,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/posts\/49616\/revisions\/49625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media\/49620"}],"wp:attachment":[{"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/media?parent=49616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/categories?post=49616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbcnoticias.com\/br\/wp-json\/wp\/v2\/tags?post=49616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}